{"id":439541,"date":"2026-04-12T06:34:14","date_gmt":"2026-04-12T06:34:14","guid":{"rendered":"https:\/\/www.europesays.com\/it\/439541\/"},"modified":"2026-04-12T06:34:14","modified_gmt":"2026-04-12T06:34:14","slug":"francesco-moser-sulla-nipotina-figlia-di-ignazio-e-di-cecilia-rodriguez-mi-dimentico-sempre-il-suo-nome-sara-perche-ne-ha-due-non-sono-un-nonno-tenero","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/439541\/","title":{"rendered":"Francesco Moser sulla nipotina, figlia di Ignazio e di Cecilia Rodriguez: \u00abMi dimentico sempre il suo nome, sar\u00e0 perch\u00e9 ne ha due. Non sono un nonno tenero\u00bb"},"content":{"rendered":"<p class=\"has-dropcap body dropcap\">Schietto e diretto, anche quando parla di famiglia e affetti. Francesco Moser, intervistato dal settimanale Oggi, racconta il suo rapporto con la nipotina Clara Isabel Moser, nata nell\u2019ottobre 2025 dall\u2019amore tra il figlio Ignazio e Cecilia Rodriguez. L\u2019ex campione di ciclismo, classe 1951 e 273 vittorie da professionista, spiega: \u00abIgnazio e Cecilia sono in Argentina per far vedere la bambina ai bisnonni. <strong>Sa che mi dimentico sempre il nome di mia nipote?<\/strong>\u00bb, dice. Il motivo? \u00ab<strong>Perch\u00e9 ha due nomi credo. Una volta mi ricordo uno, una volta mi ricordo l&#8217;altro<\/strong>\u00bb.<\/p>\n<p>Alla domanda su come la chiami, replica: \u00abMa <strong>non capisce niente adesso, cosa la chiamo?<\/strong>\u00bb. E anche quando gli si chiede che tipo nonno \u00e8, il campione &#8211; che si era guadagnato l\u2019appellativo di \u00absceriffo\u00bb &#8211; non addolcisce i toni: \u00ab<strong>Io nonno o compagno tenero? No, voglio che facciano quello che dico io<\/strong>\u00bb.<\/p>\n<p>Francesco Moser parla anche del figlio <a href=\"https:\/\/www.vanityfair.it\/people\/gossip\/2018\/01\/31\/ignazio-moser-cecilia-rodriguez-intervista-amore-foto-gossip\" rel=\"nofollow noopener\" target=\"_blank\">Ignazio<\/a>, oggi diviso tra social e passioni sportive, ma lontano dalla carriera agonistica. \u00abIo gli avevo detto: \u201cO lo fai convinto o \u00e8 meglio smettere\u201d. <strong>Aveva le caratteristiche ma non ci metteva anima e corpo<\/strong>\u00bb, dice. \u00abHa corso fino ai 23-24 anni. Era andato anche in una squadra svizzera importante, e poi dopo <strong>\u00e8 andato a fare il Grande Fratello<\/strong> (dove <a href=\"https:\/\/www.vanityfair.it\/people\/gossip\/2018\/01\/31\/ignazio-moser-cecilia-rodriguez-intervista-amore-foto-gossip\" target=\"_blank\" rel=\"nofollow noopener\">ha conosciuto Cecilia Rodriguez<\/a> e si \u00e8 fidanzato con lei, ndr) <strong>e l\u00ec \u00e8 cambiata la sua vita<\/strong>, insomma\u00bb.<\/p>\n<p>Lo aveva <a href=\"https:\/\/www.vanityfair.it\/sport\/altri-sport\/2018\/04\/19\/francesco-moser-ciclismo-sacrificio-figlio-ignazio-grande-fratello\" target=\"_blank\" rel=\"nofollow noopener\">spiegato anche a Vanity Fair<\/a>, all\u2019anteprima del film sulla sua vita, Moser, scacco al tempo: \u00abIgnazio non poteva diventare come me perch\u00e9 ha un fisico diverso, crescendo si \u00e8 appesantito di costituzione e in bici, soprattutto in salita, il peso conta. Per\u00f2 per certe gare sarebbe potuto senza dubbio essere competitivo\u00bb. E ancora: \u00ab<strong>Io mi ero accorto che non la faceva.<\/strong> Infatti gli ho detto di scegliere, non poteva portare avanti situazioni a met\u00e0 strada. <strong>La bicicletta \u00e8 uno sport a cui devi dedicarti al 100%, non al 50.<\/strong> Ma non \u00e8 il solo: tanti ciclisti fanno una stagione super e poi scompaiono\u00bb. Sulla partecipazione del figlio al reality, in quell\u2019occasione aveva detto: \u00abGli hanno chiesto di andare, io non c\u2019entro nulla. Anzi, l\u2019ho saputo solo all\u2019ultimo. Mi pare abbia fatto una buona figura. In questi casi c\u2019\u00e8 chi approva e chi non approva: io <strong>posso dire di essere contento per lui se \u00e8 riuscito a trovare questo successo, chiamiamolo cos\u00ec<\/strong>\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"Schietto e diretto, anche quando parla di famiglia e affetti. Francesco Moser, intervistato dal settimanale Oggi, racconta il&hellip;\n","protected":false},"author":3,"featured_media":439542,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1451],"tags":[6060,1621,1620,203,204,1537,90,89],"class_list":{"0":"post-439541","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-celebrita","8":"tag-cecilia-rodriguez","9":"tag-celebrita","10":"tag-celebrities","11":"tag-entertainment","12":"tag-intrattenimento","13":"tag-it","14":"tag-italia","15":"tag-italy"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116390348136634088","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/439541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=439541"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/439541\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/439542"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=439541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=439541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=439541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}