{"id":439753,"date":"2026-04-12T09:43:14","date_gmt":"2026-04-12T09:43:14","guid":{"rendered":"https:\/\/www.europesays.com\/it\/439753\/"},"modified":"2026-04-12T09:43:14","modified_gmt":"2026-04-12T09:43:14","slug":"elettra-lamborghini-ricoverata-in-ospedale-poi-arriva-a-canzonissima-a-meta-puntata-ma-cosa-e-successo","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/439753\/","title":{"rendered":"Elettra Lamborghini ricoverata in ospedale, poi arriva a Canzonissima a met\u00e0 puntata. Ma cosa \u00e8 successo?"},"content":{"rendered":"<p>Con una <a href=\"https:\/\/www.vanityfair.it\/topic\/foto\" isautogenerated=\"true\" rel=\"nofollow noopener\" target=\"_blank\">foto<\/a> \u00e8 apparsa sdraiata su un <strong>letto d&#8217;ospedale attaccata ad una flebo.<\/strong><\/p>\n<p><img decoding=\"async\" alt=\"Foto screenshotInstagram\" loading=\"lazy\" class=\"ResponsiveImageContainer-dkeESL cQPiWi responsive-image__image\"   src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/04\/IMG_1752.jpg\"\/><\/p>\n<p>Foto: screenshot@Instagram<\/p>\n<p>Questo ha messo in <strong>forte rischio la sua partecipazione allo show<\/strong> in diretta su Rai1 in prima serata. Ma, con grande sorpresa, Elettra Lamborghini invece \u00e8 riuscita ad esserci e a non mancare l&#8217;esibizione prevista per la puntata. <strong>L&#8217;artista \u00e8 arrivata in studio intorno alle 23.45<\/strong> per cantare un brano a cui ha detto di tenere molto, I bambini fanno oh, canzone di Povia del 2005, accompagnata da un coro di bambini alle sue spalle. \u00abTengo botta\u00bb, ha risposto sorridente a Milly Carlucci che l&#8217;ha ringraziata per esserci nonostante non si sentisse bene.<\/p>\n<p>La performance \u00e8 stata applaudita a molti. <a href=\"https:\/\/www.vanityfair.it\/topic\/caterina-balivo\" isautogenerated=\"true\" rel=\"nofollow noopener\" target=\"_blank\">Caterina Balivo<\/a> che <strong>si \u00e8 complimentata subito con lei:<\/strong> \u00abHai cantato dal vivo dopo una giornata terribile. Ti stai raccontando in maniera vera, non rinneghi quello che sei\u00bb. <strong>Anche Francesca Fialdini si \u00e8 espressa in modo positivo<\/strong> facendo i suoi complimenti a Elettra Lamborghini per cercare di proporsi anche in una chiave diversa dal solito in un programma del sabato sera.<\/p>\n","protected":false},"excerpt":{"rendered":"Con una foto \u00e8 apparsa sdraiata su un letto d&#8217;ospedale attaccata ad una flebo. Foto: screenshot@Instagram Questo ha&hellip;\n","protected":false},"author":3,"featured_media":439754,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1451],"tags":[1621,1620,203,204,1537,90,89,2377,5704],"class_list":{"0":"post-439753","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-celebrita","8":"tag-celebrita","9":"tag-celebrities","10":"tag-entertainment","11":"tag-intrattenimento","12":"tag-it","13":"tag-italia","14":"tag-italy","15":"tag-milly-carlucci","16":"tag-programmi-tv"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116391091513485812","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/439753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=439753"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/439753\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/439754"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=439753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=439753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=439753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}