{"id":441650,"date":"2026-04-13T15:36:15","date_gmt":"2026-04-13T15:36:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/441650\/"},"modified":"2026-04-13T15:36:15","modified_gmt":"2026-04-13T15:36:15","slug":"pupo-stava-con-me-mentre-era-sposato-ci-amavamo-ma-io-lho-usato-e-stato-il-mio-trampolino-per-fare-musica","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/441650\/","title":{"rendered":"\u00abPupo stava con me mentre era sposato. Ci amavamo ma io l&#8217;ho usato, \u00e8 stato il mio trampolino per fare musica\u00bb"},"content":{"rendered":"<p>&#13;<br \/>\n                               &#13;<br \/>\n                                                &#13;<br \/>\n                &#13;<\/p>\n<p><strong><a href=\"https:\/\/www.leggo.it\/t\/donatella-milani\" rel=\"nofollow noopener\" target=\"_blank\">Donatella Milani<\/a><\/strong> ospite a\u00a0<a href=\"https:\/\/www.leggo.it\/t\/la-volta-buona\" rel=\"nofollow noopener\" target=\"_blank\">La volta buona<\/a>, ha ripercorso alcuni dei momenti pi\u00f9 difficili della sua vita privata, dal rapporto con il padre biologico fino alla rottura con la madre dopo il suo <strong>outing<\/strong>. Un racconto intimo e doloroso, segnato da assenze, ferite mai rimarginate e legami spezzati.<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\nIl legame con il pap\u00e0&#13;<br \/>\n&#13;<\/p>\n<p>Parlando del padre, la cantante ex di Pupo ha detto:\u00a0\u00abAppena ha saputo che mamma era rimasta incinta, se n\u2019\u00e8 andato e ci ha lasciato da sole\u00bb. Quindi ha ricordato le difficolt\u00e0 vissute dalla madre in quei mesi:\u00a0\u00abLa famiglia di mamma non ci volevano in casa, non ci accettavano. Siamo state\u00a0tre mesi in un orfanotrofio\u00bb. Per molto tempo, ha spiegato, non ha sentito il bisogno di sapere chi fosse quell\u2019uomo:\u00a0\u00abNon mi interessava sapere chi fosse pap\u00e0\u00bb.<\/p>\n<p>&#13;<br \/>\n&#13;<\/p>\n<p>Poi, per\u00f2, tre anni fa ha deciso di cercarlo.\u00a0\u00abTre anni fa ad Empoli sono andata da mio padre nell\u2019officina dove lavora. Gli ho detto: \u201cSenta, ma lei \u00e8 andato a Montevarchi e ha conosciuto una Milani Mina?\u201d Lui ha iniziato ad indietreggiare e gli ho detto: \u201cSa perch\u00e9? Perch\u00e9 ha fatto una figlia\u201d. E me ne sono andata\u00bb, ha raccontato. Dopo quell\u2019incontro, ha contattato anche la famiglia dell\u2019uomo:\u00a0\u00abChiamai a casa sua e rispose la moglie e io le raccontai tutto. Lei disse: \u201cGuardi, pu\u00f2 succedere\u2026 noi abbiamo dei figli\u201d\u00bb, frase che Donatella ha interpretato come un modo per chiudere il discorso.<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\nIl coming out e la reazione di mamma\u00a0&#13;<br \/>\n&#13;<\/p>\n<p>Molto doloroso anche il capitolo dedicato alla madre di Donatella Milani:\u00a0\u00abIl rapporto con mia mamma si \u00e8 interrotto perch\u00e9 ho fatto <strong>outing<\/strong>\u00bb. Poi ha aggiunto:\u00a0\u00abAvevo la necessit\u00e0 di provare con le donne e ne ho parlato a lei\u00bb. <\/p>\n<p>La reazione della madre, secondo il suo racconto, sarebbe stata molto dura:\u00a0\u00abMi disse qualcosa di grosso, \u201cPreferisco che tu fossi stata\u2026\u201d. Mi disse che non l\u2019accettava, \u201cStai a casa tua e io sto a casa mia\u201d\u00bb.&#13;<br \/>\n&#13;<\/p>\n<p>Nonostante tutto, il legame non si sarebbe spezzato subito del tutto:\u00a0\u00abMi chiam\u00f2 il giorno dopo perch\u00e9 stava male, per\u00f2&#8230;\u00a0Lei non voleva sapere che io stavo con una donna, faceva finta che non esistesse quel mio lato\u00bb. Infine, Donatella Milani ha concluso con amarezza:\u00a0\u00abIo per lei ci sono sempre stata, soprattutto con tutte le malattie che ha avuto, ma ad un certo punto ti rendi conto che non ce la fai pi\u00f9\u00bb.<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n<br \/>&#13;<br \/>\nLa stoccata a Pupo<br \/>&#13;<br \/>\n\u00a0&#13;<br \/>\n&#13;<\/p>\n<p>Durante la chiacchierata, Caterina Balivo ha commentato anche la quarta puntata di Canzonissima dove i Jalisse hanno interpretato \u201cSu di noi\u201d, celebre brano di Pupo scritto con Donatella Milani. Quest\u2019ultima ha commentato la stesura del brano: \u00abCon Pupo siamo stati insieme qualche mese, il tempo di fare \u201cSu di noi\u201d. E anche altre cose\u2026\u00bb.\u00a0Balivo, allora la punge: \u00abAvete fatto anche l&#8217;amore, ma io non lo voglio sapere. A 17 anni hai scritto una bella canzone perch\u00e9 stavi bene con lui, no?\u00bb.<\/p>\n<p>Donatella Milani per\u00f2 controbatte: \u00abIo scrivo la musica, ho composto il brano, l&#8217;ho fatto sentire ad Enzo e gli \u00e8 piaciuto. Sono stata innamorata di lui, certo, ma Enzo poteva essere un trampolino, ho &#8220;usato&#8221; questo amore per fare musica, anche se questo termine non mi piace. Siamo stati insieme e quando fai questo tipo di lavoro, \u00e8 meglio avere una persona accanto nel mondo della musica. Era Enzo quello molto innamorato, ma era sposato. Su di noi qualche nuvola, ma adesso siamo felici, sono contenta per lui\u00bb.<\/p>\n<p>                                &#13;<br \/>\n                &#13;<br \/>\n&#13;<br \/>\n                Ultimo aggiornamento: luned\u00ec 13 aprile 2026, 15:39&#13;<br \/>\n                <br \/>&#13;<br \/>\n                &#13;<br \/>\n                  &#13;<br \/>\n                    &#13;<br \/>\n                        \u00a9 RIPRODUZIONE RISERVATA&#13;<\/p>\n<p>&#13;<\/p>\n<p>                    &#13;<\/p>\n","protected":false},"excerpt":{"rendered":"&#13; &#13; &#13; &#13; Donatella Milani ospite a\u00a0La volta buona, ha ripercorso alcuni dei momenti pi\u00f9 difficili della&hellip;\n","protected":false},"author":3,"featured_media":441651,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1443],"tags":[73071,203,204,1537,90,89,68601,1538,1539],"class_list":{"0":"post-441650","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-musica","8":"tag-donatella-milani","9":"tag-entertainment","10":"tag-intrattenimento","11":"tag-it","12":"tag-italia","13":"tag-italy","14":"tag-la-volta-buona","15":"tag-music","16":"tag-musica"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116398141427177444","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/441650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=441650"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/441650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/441651"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=441650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=441650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=441650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}