{"id":444149,"date":"2026-04-15T06:14:17","date_gmt":"2026-04-15T06:14:17","guid":{"rendered":"https:\/\/www.europesays.com\/it\/444149\/"},"modified":"2026-04-15T06:14:17","modified_gmt":"2026-04-15T06:14:17","slug":"non-si-puo-dire-che-la-mia-stagione-sia-stata-negativa","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/444149\/","title":{"rendered":"\u201cNon si pu\u00f2 dire che la mia stagione sia stata negativa\u201d"},"content":{"rendered":"<p>Nel corso del <strong>FISI Media Day<\/strong> a Milano ha parlato alla stampa <strong>Sofia Goggia<\/strong>, che ha fatto un bilancio della stagione appena conclusa, nella quale l\u2019azzurra ha portato a casa la <strong>medaglia di bronzo nella discesa libera delle Olimpiadi<\/strong> e la <strong>Coppa del Mondo di specialit\u00e0 nel superG<\/strong>.<\/p>\n<p>L\u2019azzurra \u00e8 <strong>soddisfatta della gestione mentale dei momenti complicati<\/strong>: \u201c\u00c8 stata una stagione piena di difficolt\u00e0. Sono riuscita a gestire delle situazioni difficili, anche la discesa delle Olimpiadi. In quella giornata avrei potuto non commettere degli errori, per\u00f2 fu estremamente positiva per come l\u2019ho gestita mentalmente\u201c.<\/p>\n<p>Goggia traccia un<strong> bilancio complessivo della stagione<\/strong>, che non pu\u00f2 che essere <strong>positivo<\/strong>, visto quanto fatto: \u201cChiudere la stagione con una medaglia olimpica e una Coppa del Mondo non si pu\u00f2 dire che sia negativa. Le aspettative erano alte in tre discipline, ma tante cose non sono andate per il verso giusto\u201c.<\/p>\n","protected":false},"excerpt":{"rendered":"Nel corso del FISI Media Day a Milano ha parlato alla stampa Sofia Goggia, che ha fatto un&hellip;\n","protected":false},"author":3,"featured_media":413756,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[176],"tags":[1537,90,89,80282,245,244],"class_list":["post-444149","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sport","tag-it","tag-italia","tag-italy","tag-sofia-goggia","tag-sport","tag-sports"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116407256068984463","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/444149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=444149"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/444149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/413756"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=444149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=444149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=444149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}