{"id":445179,"date":"2026-04-15T21:04:15","date_gmt":"2026-04-15T21:04:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/445179\/"},"modified":"2026-04-15T21:04:15","modified_gmt":"2026-04-15T21:04:15","slug":"van-der-poel-una-primavera-senza-monumento-e-i-dubbi-quali-obiettivi-per-la-seconda-parte-dellanno","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/445179\/","title":{"rendered":"Van der Poel, una primavera senza monumento e i dubbi: quali obiettivi per la seconda parte dell&#8217;anno?"},"content":{"rendered":"<p><a href=\"https:\/\/www.quibicisport.it\/wp-content\/uploads\/2026\/04\/VanderPoel-3-1.jpg\" data-caption=\"Mathieu Van der Poel nella Foresta di Arenberg, mentre aspetta di cambiare bici (credit: ASO\/Pressesports\/Etienne Garnier).\" rel=\"nofollow noopener\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" data-lazyloaded=\"1\" width=\"696\" height=\"484\" class=\"entry-thumb td-modal-image\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/04\/VanderPoel-3-1-696x484.jpg\"  data- alt=\"Van der Poel\" title=\"VanderPoel-3\"\/><\/a>Mathieu Van der Poel nella Foresta di Arenberg, mentre aspetta di cambiare bici (credit: ASO\/Pressesports\/Etienne Garnier).<\/p>\n<p><strong>Ottavo alla Milano-Sanremo, secondo al Giro delle Fiandre, quarto alla Parigi-Roubaix, vincitore alla Omloop, alla E3 e in due tappe della Tirreno-Adriatico: per il 99% dei corridori, con questi risultati, si parlerebbe di ottima primavera. Ma Mathieu Van der Poel non \u00e8 uno come gli altri: \u00e8 un corridore che negli ultimi tre anni aveva sempre vinto due tra Sanremo, Fiandre e Roubaix, e che dal 2020 a oggi solo un\u2019altra volta (nel 2021) aveva chiuso la primavera senza aver conquistato classiche monumento. Cosa \u00e8 mancato a Mathieu, rispetto alle scorse stagioni?&#8230;<\/strong><\/p>\n<p style=\"text-align: center\">&#8230;&#8230;&#8230;&#8230;&#8230;<\/p>\n<p style=\"text-align: center\">Ami il ciclismo? Vuoi leggere questo articolo e tutti i contenuti esclusivi di quibicisport.it? Aderisci alle offerte EXTRA di Bicisport <a href=\"https:\/\/www.quibicisport.it\/piani-di-abbonamento\/\" rel=\"nofollow noopener\" target=\"_blank\"><strong>cliccando qui<\/strong><\/a>. <\/p>\n<p style=\"text-align: center\">Se sei gi\u00e0 abbonato <a href=\"https:\/\/www.quibicisport.it\/login\/\" rel=\"nofollow noopener\" target=\"_blank\"><strong>clicca qui<\/strong><\/a> per accedere<\/p>\n","protected":false},"excerpt":{"rendered":"Mathieu Van der Poel nella Foresta di Arenberg, mentre aspetta di cambiare bici (credit: ASO\/Pressesports\/Etienne Garnier). Ottavo alla&hellip;\n","protected":false},"author":3,"featured_media":445180,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1456],"tags":[1824,1825,1537,90,89,245,244,44738],"class_list":{"0":"post-445179","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ciclismo","8":"tag-ciclismo","9":"tag-cycling","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-sport","14":"tag-sports","15":"tag-van-der-poel"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116410756209862968","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/445179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=445179"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/445179\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/445180"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=445179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=445179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=445179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}