{"id":448687,"date":"2026-04-18T02:42:24","date_gmt":"2026-04-18T02:42:24","guid":{"rendered":"https:\/\/www.europesays.com\/it\/448687\/"},"modified":"2026-04-18T02:42:24","modified_gmt":"2026-04-18T02:42:24","slug":"i-benchmark-spec-su-chip-m5-pro-e-m5-max-di-apple-sono-imbarazzanti-per-intel","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/448687\/","title":{"rendered":"I benchmark SPEC su chip M5 Pro e M5 Max di Apple sono imbarazzanti per Intel"},"content":{"rendered":"<p>Imitata ma finora mai eguagliata: l\u2019architettura Apple Silicon continua a fare passi da gigante rispetto alle architetture concorrenti. \u00a0Negli anni lo schema adottato di Cupertino rimane invariato nelle linee generali, e rimane estremamente difficile per la concorrenza riuscire a scalfire la superiorit\u00e0, come rivelano recenti test specifici eseguiti sui chip <strong>M5 Pro.<\/strong><\/p>\n<p>I chip M5 Pro dimostrano potenza pari agli ultimi Panther Lake di Intel ma con una differenza rivelante: gli stessi risultati si ottengono con una frazione dell\u2019energia richiesta ai chip rivali.<\/p>\n<p><strong>La maturit\u00e0 di M5 Pro e M5 Max<\/strong><\/p>\n<p>Con <a href=\"https:\/\/www.macitynet.it\/processori-m5-pro-ed-m5-max\/\" rel=\"nofollow noopener\" target=\"_blank\"><strong>M5 Pro e M5 Max<\/strong><\/a> siamo arrivati alla maturit\u00e0, con l\u2019adozione dell\u2019architettura \u201cFusion\u201d che combina due die in un unico System on Chip (SoC) che include una CPU, una GPU scalabile, un Media Engine, un controller di memoria unificata, un Neural Engine e la tecnologia Thunderbolt 5, merito del packaging avanzato 3D detto <strong>SoIC-MH<\/strong> (Molding Horizontal) e che \u2013 semplificando \u2013 permette di integrare singoli chip, es. CPU, GPU e Neural Engine, in un unico package, una garanzia di flessibilit\u00e0 senza precedenti per Apple che pu\u00f2 moltiplicare le configurazioni come desidera e ottimizzare ogni componente in modo indipendente mantenendo una latenza minima tra le interconnessioni.<\/p>\n<p>Gli\u00a0ultimi chip di Apple non si accontentano di riorganizzare i vari \u201cdie\u201d (parti del chip prodotte in modo separato, che poi vengono unite in un unico prodotto) ma prevedono una nuova nomenclatura e una nuova gerarchia dei core per CPU, ora chiamati <strong>super core<\/strong>, ai quali si aggiungono nuovi <strong>performance core<\/strong> (P-Core) ottimizzati per ridurre i consumi nei flussi di lavoro multi-thread che sostituiscono i tradizionali Efficient core (E-cores).<\/p>\n<p>Come fa <a href=\"https:\/\/www.macg.co\/materiel\/2026\/04\/m5-pro-linsolente-superiorite-dapple-silicon-face-au-futur-dintel-308089\" class=\"external\" rel=\"nofollow noopener\" target=\"_blank\">notare<\/a> il sito francese Macg spiegando che non si tratta di una semplice ridenominazione di marketing, <a href=\"https:\/\/www.macg.co\/materiel\/2026\/04\/m5-pro-linsolente-superiorite-dapple-silicon-face-au-futur-dintel-308089\" class=\"external\" rel=\"nofollow noopener\" target=\"_blank\">spiega<\/a>: i performance core beneficiano di una microarchitettura completamente rivista, che si distingue nettamente dai Super-core. L\u2019obiettivo \u00e8 offrire una solida potenza di calcolo per le attivit\u00e0 tradizionali senza bisogno di sollecitare l\u2019artiglieria pesante, pur vantando un consumo elettrico irrisorio.<\/p>\n<p><strong>Il test SPEC integer<\/strong><\/p>\n<p>La dimostrazione della superiorit\u00e0 delle scelte di Apple, c\u2019\u00e8 un giudice imparziale: il test per la misura delle prestazioni SPEC integer\u00a0 che misura la capacit\u00e0 di un processore di elaborare carichi di lavoro standard basati su numeri interi.<\/p>\n<p>I benchmark <a href=\"https:\/\/blog.hjc.im\/spec-cpu-2017\" class=\"external\" rel=\"nofollow noopener\" target=\"_blank\">pubblicati<\/a> dal ricercatore jht5132, evidenziano risultati sbalorditivi: Un semplice performance core del chip M5 Pro riesce a eguagliare i punteggi di un core Intel (Panther Lake), pur consumando meno di 2,5 Watt alla frequenza di 4,38 GHz. Il core di Apple \u00e8 fino a 4 volte pi\u00f9 efficiente rispetto a quello Intel, un risultato sorprendente tenendo conto che il piccolo core di Apple fornisce gi\u00e0 il 70% della potenza dei super-core del SoC della Mela.<\/p>\n<p><a href=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/04\/SPECint2017-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-1466694\" title=\"Il benchmark SPEC su chip M5 Pro e M5 Max di Apple sono imbarazzanti per Intel - macitynet.it\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/04\/SPECint2017-scaled.jpg\" alt=\"Il benchmark SPEC su chip M5 Pro e M5 Max di Apple sono imbarazzanti per Intel - macitynet.it\" width=\"1068\" height=\"2560\"  \/><\/a>Immagine dal Blog di David Huang<\/p>\n<p>Non finisce qui: Intel utilizza per i suoi chip Panther Lake un processo di fabbricazione a <strong>1,8 nm c<\/strong>he ha richiesto anni di sviluppo e investimenti record e dovrebbe essere pi\u00f9 avanzato rispetto ai <strong>3nm<\/strong> di TSMC che Apple sfrutta per i suoi M5 Pro e Max. Prova se necessario che il design dell\u2019architettura conta tanto, se non di pi\u00f9, rispetto al processo produttivo.<\/p>\n","protected":false},"excerpt":{"rendered":"Imitata ma finora mai eguagliata: l\u2019architettura Apple Silicon continua a fare passi da gigante rispetto alle architetture concorrenti.&hellip;\n","protected":false},"author":3,"featured_media":448688,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[173],"tags":[624,251936,11742,1537,90,89,195,198,199,197,200,201,194,196],"class_list":["post-448687","post","type-post","status-publish","format-standard","has-post-thumbnail","category-scienza-e-tecnologia","tag-apple","tag-apple-silicon","tag-intel","tag-it","tag-italia","tag-italy","tag-science","tag-science-and-technology","tag-scienceandtechnology","tag-scienza","tag-scienza-e-tecnologia","tag-scienzaetecnologia","tag-technology","tag-tecnologia"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116423409544932683","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/448687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=448687"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/448687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/448688"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=448687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=448687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=448687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}