{"id":461563,"date":"2026-04-26T09:07:34","date_gmt":"2026-04-26T09:07:34","guid":{"rendered":"https:\/\/www.europesays.com\/it\/461563\/"},"modified":"2026-04-26T09:07:34","modified_gmt":"2026-04-26T09:07:34","slug":"il-motivo-dietro-la-sparizione-dai-social","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/461563\/","title":{"rendered":"il motivo dietro la sparizione dai social"},"content":{"rendered":"<p>Cecilia Rodriguez \u00e8 la nuova ospite del podcast di Giulia Salemi \u201cNon solo x moda\u201d. La sorella della pi\u00f9 famosa Bel\u00e9n Rodriguez si \u00e8 racconta a 360\u00b0 lasciandosi andare ad alcune rivelazioni anche sul rapporto con il marito Ignazio Moser, sul nipotino Santiago De Martino (e altro).<\/p>\n<p>Le parole di Cecilia Rodriguez sul nipote Santiago<\/p>\n<p>\u201cQuando Bel\u00e9n viene, non si interessa pi\u00f9 di nessuno, prende in braccio Clarita (figlia di Cecilia e Ignazio, ndr). Mi ha anche chiesto di lasciargliela una notte, ma io al momento non voglio con nessuno. Non sono pronta, voglio dormire con la mia bambina\u201d, ha detto Cecilia.<\/p>\n<p>Poi ha parlato, invece, dei suoi nipotini Luna (figlia di Bel\u00e9n e Antonino Spinalbese) e Santiago (figlio di Bel\u00e9n e Stefano De Martino): \u201cA me piacerebbe passare pi\u00f9 tempo con loro. Quando loro erano piccoli stavo tanto con loro\u201d. Giulia Salemi ha ricordato le tante foto che Cecilia pubblicava con i nipotini, cosa che ora accade molto pi\u00f9 raramente.<\/p>\n<p>Dietro, in realt\u00e0, c&#8217;\u00e8 una precisa richiesta proprio di De Martino junior: \u201cSantiago ha chiesto di non essere pi\u00f9 pubblicato sui social, quindi adesso non lo faccio. Non vuole e lo rispettiamo. Ha 13 anni, \u00e8 cresciuto. Non c&#8217;\u00e8 vero, non vuole. Un giorno abbiamo fatto un video in famiglia, un trend e lui era girato di spalle. Magari non gli piace essere riconosciuto, succede in strada e a lui non piace&#8221;, ha spiegato <a href=\"https:\/\/www.today.it\/gossip\/vip\/francesco-monte-replica-giulia-salemi-cecilia-rodriguez.html\" target=\"_blank\" rel=\"nofollow noopener\">Cecilia Rodriguez<\/a>.<\/p>\n<p>&#8220;Io penso che a volte sia bello condividere ma i figli non lo hanno scelto, \u00e8 giusto. A me a volte scappa qualche foto con mia figlia, vederemo pi\u00f9 avanti\u201d, ha aggiunto. \u201cIo a volte vorrei far vedere Kian perch\u00e9 \u00e8 cos\u00ec buffo e simpatico, ma ho veramente paura perch\u00e9 in giro \u00e8 pieno di matti\u201d, il commento di Salemi parlando del proprio figlio. \u201cIgnazio invece non \u00e8 di questa teoria\u201d, le parole di Rodriguez.<\/p>\n<p><a href=\"https:\/\/www.today.it\/gossip\/vip\/scuole-figli-vip-costi-totti-ferragni.html\" target=\"_blank\" rel=\"nofollow noopener\">Quanto costano le scuole dei figli dei vip? Da Chanel e Isabel Totti a Santiago De Martino: le rette (da capogiro)<\/a>\u00a0<a href=\"https:\/\/www.today.it\/gossip\/vip\/francesco-monte-replica-giulia-salemi-cecilia-rodriguez.html\" target=\"_blank\" rel=\"nofollow noopener\">&#8220;Scusate se a letto non sono stato all&#8217;altezza. Adolescenti rancorose&#8221;. Lo sfogo di Monte dopo le rivelazioni hot di Salemi e Rodriguez<\/a>\u00a0La verit\u00e0 dietro alla presunta lite con Ignazio<\/p>\n<p>A proposito di Ignazio, Cecilia ha fatto chiarezza anche della presunta crisi che ebbe con il marito e di cui tanto si \u00e8 parlato. \u201cSono molto abituata alle polemiche, ormai sono 15 anni che sto in questo mondo. Non me la sono vissuta bene perch\u00e9 ero incinta, ero arrabbiata con il mondo perch\u00e9 dicono sempre che le donne incinta vanno protette\u2026\u201d.<\/p>\n<p>\u201cIo non ho litigato con Ignazio &#8211; le parole di Cecilia Rodriguez -, non eravamo in crisi. Non ci siamo mai lasciati. Non l&#8217;ho smentito pubblicamente perch\u00e9 non volevo alimentare qualcosa che non esisteva. Con mia sorella s\u00ec, avevo litigato, ma erano cose personali. Io non sono una che racconta sui social i fatti propri, io li uso per farci una bella risata\u201d.<\/p>\n<p>Infine Cecilia ha concluso: \u201cNon ci siamo parlati per un po&#8217;, io non volevo neanche dirlo (Bel\u00e9n ne ha parlato a Belve, ndr). Dentro di me volevo urlare a tutti la mia verit\u00e0, certo. Tante volte avrei voluto, ma non fa parte di me e quindi non l&#8217;ho fatto\u201d.<\/p>\n<p><a href=\"https:\/\/www.today.it\/gossip\/vip\/belen-stefano-antonino-santiago.html\" target=\"_blank\" rel=\"nofollow noopener\">Belen al compleanno del figlio Santiago con gli ex Stefano e Antonino: &#8220;Clima disteso nella famiglia allargata&#8221;<\/a>\u00a0 <\/p>\n<p>  &#13;<br \/>\n&#13;<br \/>\n  &lt;!?php if ( SF_DOMAIN == &#8216;citynews-bruxellestoday&#8217; || SF_DOMAIN == &#8216;citynews-cagliaritoday&#8217; || SF_DOMAIN == &#8216;citynews-sassaritoday&#8217; || SF_DOMAIN == &#8216;citynews-tarantotoday&#8217; || SF_DOMAIN == &#8216;citynews-viterbotoday&#8217; || SF_DOMAIN == &#8216;citynews-ferraratoday&#8217; ): ?&gt;&#13;<br \/>\n    &#13;<br \/>\n  &lt;!?php endif; ?&gt;&#13;<br \/>\n  &#13;<br \/>\n&#13;<br \/>\n        &#13;<br \/>\n        &#13;<\/p>\n","protected":false},"excerpt":{"rendered":"Cecilia Rodriguez \u00e8 la nuova ospite del podcast di Giulia Salemi \u201cNon solo x moda\u201d. La sorella della&hellip;\n","protected":false},"author":3,"featured_media":461564,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1451],"tags":[6060,1621,1620,203,204,1537,90,89,16046],"class_list":{"0":"post-461563","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-celebrita","8":"tag-cecilia-rodriguez","9":"tag-celebrita","10":"tag-celebrities","11":"tag-entertainment","12":"tag-intrattenimento","13":"tag-it","14":"tag-italia","15":"tag-italy","16":"tag-santiago-de-martino"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116470221916836227","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/461563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=461563"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/461563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/461564"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=461563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=461563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=461563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}