{"id":472752,"date":"2026-05-03T18:09:20","date_gmt":"2026-05-03T18:09:20","guid":{"rendered":"https:\/\/www.europesays.com\/it\/472752\/"},"modified":"2026-05-03T18:09:20","modified_gmt":"2026-05-03T18:09:20","slug":"nessuno-sa-dove-siano-e-mistero-sulle-sorti-di-11-tonnellate-di-uranio-arricchito-da-teheran","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/472752\/","title":{"rendered":"\u201cNessuno sa dove siano\u201d: \u00e8 mistero sulle sorti di 11 tonnellate di uranio arricchito da Teheran"},"content":{"rendered":"<p dir=\"ltr\" id=\"docs-internal-guid-3d949531-7fff-0f70-bf78-6c5b5c65cceb\">Le trattative tra Stati Uniti e <a href=\"https:\/\/www.ilgiornale.it\/news\/cronaca-internazionale\/donald-trump-ancora-allattacco-litalia-non-stata-nessun-2658641.html\" data-datalayer-click-event-target=\"internal\" rel=\"nofollow noopener\" target=\"_blank\">Iran<\/a> sembrano ormai arrivate al capolinea e si moltiplicano le indiscrezioni dei media su un possibile imminente riavvio di operazioni militari contro Teheran. Il blocco navale imposto dagli Usa a seguito, a sua volta, dello stop al passaggio delle navi nello Stretto di Hormuz da parte di Teheran non ha piegato il regime teocratico.  Non solo sulla riapertura del nodo strategico ma anche sullo spinoso e pluridecennale dossier nucleare della Repubblica Islamica, il quale, avrebbe detto Gadda, assomiglia sempre pi\u00f9 ad un \u201cpasticciaccio brutto\u201d di difficile soluzione.<\/p>\n<p dir=\"ltr\"><a data-autogenerated=\"yes\" data-datalayer-click-event-target=\"internal\" href=\"https:\/\/www.ilgiornale.it\/persone\/donald-trump-131539.html\" rel=\"nofollow noopener\" target=\"_blank\">Donald Trump<\/a> ha ripetuto pi\u00f9 volte nelle scorse settimane che i pasdaran non potranno avere un\u2019arma nucleare ma secondo gli esperti l\u2019impasse sul programma atomico dell\u2019Iran \u00e8 frutto di un decisione che affonda le sue origini nella decisione presa dallo stesso presidente americano al tempo del suo primo mandato. Nel 2018 infatti il tycoon decise di ritirare gli Stati Uniti dall\u2019accordo negoziato con Teheran dalla precedente amministrazione guidata da Barack Obama, il Joint Comprehensive Plan of Action (Jcpoa). \u201cOrribile\u201d, la definizione affibbiata dall\u2019attuale leader Usa all\u2019intesa siglata dal suo predecessore che, per quanto imperfetta, aveva per\u00f2 il merito di porre sotto controllo le attivit\u00e0 del regime degli ayatollah in campo nucleare.<\/p>\n<p dir=\"ltr\">Dopo il ritiro di Washington dall\u2019accordo, ricostruisce in una lunga analisi il <a href=\"https:\/\/www.nytimes.com\/2026\/04\/25\/us\/politics\/trump-iran-nuclear.html\" data-datalayer-click-event-target=\"external\" target=\"_blank\" rel=\"noopener nofollow\">New York Times<\/a>, gli iraniani hanno accelerato il processo di arricchimento dell\u2019uranio, avvicinandosi pi\u00f9 che mai alla bomba atomica. Negli ultimi tempi molto si \u00e8 parlato della circa mezza tonnellata di uranio arricchito probabilmente sepolto in un complesso di tunnel bombardati lo scorso giugno durante la campagna dei 12 giorni (e che il Pentagono starebbe pensando di recuperare con una pericolosa e complessa operazione di terra), ma, sottolinea il quotidiano americano, tale quantitativo di combustibile radioattivo rappresenta solo una piccola parte del problema.<\/p>\n<p dir=\"ltr\">Questo perch\u00e9, stando a quanto riportato dagli ispettori internazionali, oggi Teheran possiede un totale di circa 11 tonnellate di uranio, a vari livelli di arricchimento, e con un\u2019ulteriore processo di purificazione esse sarebbero sufficienti per costruire fino a 100 armi nucleari. Un numero, sottolinea il New York Times, superiore a quello stimato dell\u2019arsenale israeliano.<\/p>\n<p dir=\"ltr\">Le 11 tonnellate di combustibile in questione sarebbero state accumulate quasi per intero negli anni successivi all\u2019abbandono, deciso da Trump, dell\u2019intesa negoziata nel 2015 da Obama. All\u2019epoca, come previsto dall\u2019accordo, il regime dei pasdaran aveva infatti mantenuto la promessa di inviare alla Russia le oltre 12 tonnellate di uranio lavorato in suo possesso, pari a circa il 97% del totale.<\/p>\n<p dir=\"ltr\">Negli ultimi 20 anni Teheran ha pi\u00f9 volte usato la carta del nucleare per ricattare la comunit\u00e0 internazionale e mettere a rischio la stabilit\u00e0 in Medio Oriente. Nel 2006 l&#8217;Iran ha iniziato l\u2019arricchimento dell\u2019uranio su scala industriale, pur dichiarando che i suoi obiettivi fossero di natura pacifica e civile. Salvo poi, nel 2010, avviare l\u2019arricchimento dell\u2019uranio al 20%, un livello che demarca l\u2019uso del combustibile a fini civili e militari. Proprio tale iniziativa intrapresa da Teheran e l\u2019ulteriore innalzamento del livello di arricchimento dell\u2019uranio allarmarono il presidente Obama spingendo la Casa Bianca e i suoi principali alleati a negoziare, come gi\u00e0 menzionato, un accordo con il regime iraniano.<\/p>\n<p dir=\"ltr\">Nel 2021, pochi giorni prima della fine del primo mandato di Trump, i pasdaran, ormai liberi dalle limitazioni stabilite dalla precedente intesa con Washington, decisero di ripristinare l\u2019arricchimento dell\u2019uranio al 20%. Per rappresaglia dopo una misteriosa esplosione (probabile frutto di un sabotaggio israeliano) che caus\u00f2 un blackout a Natanz, il principale sito di arricchimento del combustibile radioattivo in Iran, Teheran decise di aumentare parte delle scorte fino al 60%. Una mossa poi ampliata nel corso dell\u2019amministrazione Biden.<\/p>\n<p dir=\"ltr\">L\u2019esatta ubicazione delle circa 11 tonnellate di uranio arricchito accumulate da Teheran rimane un mistero. Al quale si aggiunge inoltre l\u2019incertezza sull\u2019esatta collocazione di un nuovo complesso di arricchimento che la Repubblica Islamica stava per annunciare alla vigilia della guerra dei 12 giorni dello scorso anno. Gli analisti, riferisce ancora il New York Times, ritengono che l\u2019Iran possa aver costruito l\u2019impianto nel labirinto di gallerie montane nei pressi del sito industriale di Isfahan, lo stesso dove potrebbe trovarsi la maggiorparte del combustibile nucleare iraniano. In tale localit\u00e0, ben protetta dalle montagne e in profondit\u00e0, si potrebbe dunque celare un sito industriale in grado di condurre nuove fasi di arricchimento dell\u2019uranio a fini militari.\n<\/p>\n<p> Un obiettivo che il rafforzamento dell\u2019ala oltranzista del regime determinato dall\u2019operazione Furia Epica di Washington e Tel Aviv potrebbe, paradossalmente, aver reso ancora pi\u00f9 probabile. Con buona pace delle iniziative del tycoon che mira a raggiungere con i pasdaran un accordo migliore di quello negoziato da Obama sul nucleare.<\/p>\n","protected":false},"excerpt":{"rendered":"Le trattative tra Stati Uniti e Iran sembrano ormai arrivate al capolinea e si moltiplicano le indiscrezioni dei&hellip;\n","protected":false},"author":3,"featured_media":472753,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[14,164,165,166,7,15,11,167,12,168,161,162,163],"class_list":{"0":"post-472752","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-cronaca","9":"tag-dal-mondo","10":"tag-dalmondo","11":"tag-mondo","12":"tag-news","13":"tag-notizie","14":"tag-ultime-notizie","15":"tag-ultime-notizie-di-mondo","16":"tag-ultimenotizie","17":"tag-ultimenotiziedimondo","18":"tag-world","19":"tag-world-news","20":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116511989286460835","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/472752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=472752"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/472752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/472753"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=472752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=472752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=472752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}