{"id":474174,"date":"2026-05-04T16:35:24","date_gmt":"2026-05-04T16:35:24","guid":{"rendered":"https:\/\/www.europesays.com\/it\/474174\/"},"modified":"2026-05-04T16:35:24","modified_gmt":"2026-05-04T16:35:24","slug":"al-bano-romina-power-e-le-infinite-frecciatine-in-tv-che-dovrebbero-essere-private","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/474174\/","title":{"rendered":"Al Bano, Romina Power e le infinite frecciatine in tv che dovrebbero essere private"},"content":{"rendered":"<p>Se, dopo tutti questi anni, stiamo ancora parlando di Al Bano e Romina Power, 82 anni lui e 74 lei, \u00e8 perch\u00e9 Al Bano e Romina Power contengono dentro di loro tutti gli ingredienti vincenti per la storia perfetta. L&#8217;amore sbocciato in tenera et\u00e0 tra due mondi &#8211; lei figlia d&#8217;arte, del grande <strong>Tyrone Power, che nella sua carriera ha lavorato tra gli altri con Fritz Lang, Billy Wilder e John Ford, lui figlio di agricoltori con una voce da diversi decibel<\/strong> &#8211; che sulla carta non avrebbero mai potuto incontrarsi; il successo inaspettato all&#8217;insegna della leggerezza e dell&#8217;armonia; l&#8217;amore condiviso con i giornali e le televisioni; la rottura violenta e inaspettata; <a href=\"https:\/\/www.vanityfair.it\/article\/al-bano-domenica-risponde-romina-power-belve-lacrime-ylenia-carrisi-gossip\" target=\"_blank\" rel=\"nofollow noopener\">le frecciatine<\/a>; la reunion che quasi nessuno sperava avvenisse e, di nuovo, i battibecchi su quello che non sono evidentemente riusciti a dirsi in privato perch\u00e9 era evidente che ormai la loro grammatica era quella pubblica. <strong>Arrivati a questo punto sarebbe per\u00f2 forse opportuno che sia Al Bano che Romina Power capissero che forse \u00e8 meglio alzare il telefono<\/strong> e parlare da soli anzich\u00e9 guerrigliare con una telecamera a dividersi.<\/p>\n<p><img decoding=\"async\" alt=\"Al Bano Romina Power e le infinite frecciatine in tv che dovrebbero essere private\" loading=\"lazy\" class=\"ResponsiveImageContainer-dkeESL cQPiWi responsive-image__image\"   src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/al%20bano%202.jpg\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"Se, dopo tutti questi anni, stiamo ancora parlando di Al Bano e Romina Power, 82 anni lui e&hellip;\n","protected":false},"author":3,"featured_media":474175,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1443],"tags":[24824,203,204,1537,90,89,1538,1539,5704,53435],"class_list":{"0":"post-474174","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-musica","8":"tag-al-bano","9":"tag-entertainment","10":"tag-intrattenimento","11":"tag-it","12":"tag-italia","13":"tag-italy","14":"tag-music","15":"tag-musica","16":"tag-programmi-tv","17":"tag-romina-power"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116517283140201560","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/474174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=474174"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/474174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/474175"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=474174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=474174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=474174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}