{"id":478650,"date":"2026-05-07T10:07:12","date_gmt":"2026-05-07T10:07:12","guid":{"rendered":"https:\/\/www.europesays.com\/it\/478650\/"},"modified":"2026-05-07T10:07:12","modified_gmt":"2026-05-07T10:07:12","slug":"in-vaticano-lincontro-tra-papa-leone-xiv-e-il-segretario-di-stato-usa-rubio","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/478650\/","title":{"rendered":"In Vaticano l&#8217;incontro tra Papa Leone XIV e il Segretario di Stato Usa Rubio"},"content":{"rendered":"\n<p>Il segretario di Stato americano <strong>Marco Rubio<\/strong> \u00e8 arrivato in <strong>Vaticano <\/strong>per l&#8217;incontro con <strong>Papa Leone XIV<\/strong> e successivamente con il cardinale segretario di Stato <strong>Pietro Parolin<\/strong>. Secondo alcune indiscrezioni, il colloquio potrebbe durare circa mezz&#8217;ora (alle 12 il Papa ha gi\u00e0 un altro impegno in agenda) ma anche il tempo che durer\u00e0 effettivamente e i toni delle dichiarazioni potranno essere una chiave di lettura.<\/p>\n<p>Accompagnato dall&#8217;ambasciatore degli Stati Uniti presso la Santa Sede, Brian Burch, \u00e8 stato accolto nel Cortile di San Damaso dal prefetto della Casa Pontificia, monsignor Petar Rajic. Quindi \u00e8 stato accompagnato all&#8217;interno del Palazzo apostolico per l&#8217;incontro con il Papa. Mentre Rubio arrivava in via della Conciliazione, accompagnato da diverse vetture di scorta, usciva dal colonnato il premier polacco <strong>Donald Tusk<\/strong> che ha avuto un incontro con Leone XIV questa mattina. I due cortei non si sono incrociati per una manciata di secondi.<\/p>\n<p>L&#8217;aereo con a bordo Rubio \u00e8 atterrato all&#8217;aeroporto di Ciampino questa mattina, prima delle 9, tra rigide misure di sicurezza. Il capo del Dipartimento di Stato, responsabile della politica estera statunitense, dopo l&#8217;appuntamento di oggi in Vaticano, \u00e8 atteso <strong>domani a Palazzo Chigi<\/strong> e in programma ci sono incontri anche con i ministri degli Esteri e della Difesa, <strong>Antonio Tajani<\/strong> e <strong>Guido Crosetto<\/strong>. \u00a0\u00a0<\/p>\n<p>La Chiesa \u00e8 dalla parte delle vittime della guerra, ha ribadito ieri Leone XIV alla vigilia del<strong> <\/strong>faccia a faccia di oggi.<\/p>\n<p>Il Pontefice, nel corso dell&#8217;udienza generale del mercoled\u00ec, \u00e8 tornato sul t<strong>ema dei conflitti nel mondo<\/strong>. <strong>La Chiesa, ha detto Prevost, \u201c\u00e8 anche investita della missione di pronunciare parole chiare<\/strong> per rifiutare tutto ci\u00f2 che mortifica la vita e ne impedisce lo sviluppo e <strong>prendere posizione a favore dei poveri, degli sfruttati, delle vittime della violenza e della guerra <\/strong>e di tutti coloro che soffrono, nel corpo e nello spirito\u201d.<\/p>\n<p>E la <strong>guerra in Medio Oriente, gli attacchi in Libano<\/strong>, come pure <strong>il conflitto in Ucraina,<\/strong> sono tra i temi su cui il Santo Padre pi\u00f9 volte ha richiamato l&#8217;attenzione,<strong> invocando la pace<\/strong>. Il viaggio di Rubio si inserisce in una fase di <strong>forte pressione geopolitica<\/strong>, che riguarda i <strong>rapporti tra Stati Uniti ed Europa, <\/strong>resi pi\u00f9 difficili dalle sparate di Trump. Alcuni commentatori non hanno mancato di sottolineare che questa \u201cmissione\u201d in Italia serva non solo a rimettere pace tra le due sponde dell&#8217;Atlantico ma anche allo stesso Rubio per costruire la sua <strong>candidatura alle presidenziali del 2028<\/strong>.<\/p>\n<p>    <strong>La visita e i temi dell&#8217;incontro, Parolin: \u201cIl Santo Padre \u00e8 aperto a tutto, se ci fosse la richiesta di un incontro con Trump non si tirerebbe indietro\u201d<\/strong><\/p>\n<p>La visita a Roma del segretario di Stato Usa viene letta come un tentativo di <strong>consolidare il fronte occidentale su pi\u00f9 dossier<\/strong>, dal Medio Oriente alla sicurezza energetica, fino alle crisi umanitarie. In questo quadro, <strong>l&#8217;Italia \u00e8 considerata un interlocutore chiave<\/strong>, sia per il suo ruolo nel Mediterraneo sia per la presenza in Libano.<\/p>\n<p>Ad anticipare i <strong>temi dell&#8217;incontro <\/strong>\u00e8 stato il segretario di Stato vaticano, cardinale Pietro Parolin, che a margine di un evento ieri <strong>ha affermato: \u201cAscolteremo, l&#8217;iniziativa \u00e8 partita da loro<\/strong>. Immagino che si parler\u00e0 di tutto quello \u00e8 successo in questi giorni, ma <strong>si parler\u00e0 anche di conflitti, di America Latina e immagino anche di Cuba\u201d <\/strong>(Rubio \u00e8 di origine cubana).<\/p>\n<p>Attualit\u00e0 dunque centrale, con &#8211; magari &#8211; una prospettiva sul futuro delle relazioni tra Usa e Santa Sede, perch\u00e9 se \u00e8 vero che \u201c\u00e8 prematuro\u201d ipotizzare un possibile colloquio tra Trump e Leone XIV, \u00e8 altrettanto vero, ha rimarcato Parolin, che \u201cil Santo Padre \u00e8 aperto a tutte le cose, non si \u00e8 mai tirato indietro di fronte a nessuno. Quindi, se ci fosse l&#8217;offerta anche o la richiesta di un dialogo diretto con il presidente Trump, immagino che non avrebbe nessuna difficolt\u00e0 per accettarlo\u201d, anche perch\u00e9 \u201cnon si pu\u00f2 prescindere dagli Stati Uniti\u201d e \u201cnonostante qualche difficolt\u00e0 che c&#8217;\u00e8, loro rimangono, certamente, un interlocutore per la Santa Sede\u201d.<\/p>\n<p>Il porporato ha poi detto la sua proprio sugli attacchi di Trump a Leone: \u201c<strong>Il Papa fa quello che deve fare il Papa <\/strong>e quindi, attaccarlo in questa maniera o rimproverare quello che fa mi pare un po&#8217; strano\u201d.<\/p>\n<p>    <strong>Le parole del Pontefice dopo gli attacchi di Trump<\/strong><\/p>\n<p><strong>Papa Leone si \u00e8 detto fiducioso<\/strong> rispetto a questo appuntamento, auspicando <strong>\u201capertura\u201d<\/strong> e <strong>\u201ccomprensione\u201d <\/strong>reciproca. Ma la linea resta sempre quella: <strong>la Chiesa \u201clegge e interpreta a partire dal Vangelo i dinamismi della storia, denunciando il male in tutte le sue forme<\/strong> e annunciando\u201d la pace, ha detto ieri mattina all&#8217;udienza generale parlando dei documenti del Concilio Vaticano II ma <strong>il tono della catechesi \u00e8 in linea pienamente con quanto sta accadendo<\/strong> a livello internazionale.<\/p>\n<p>Il Vaticano sembra volere<strong> rimettere al centro anche l&#8217;Europa,<\/strong> restituendole quel ruolo sullo scenario internazionale che nelle ultime vicende sembrava affievolito. I<strong> vescovi francesi hanno annunciato un possibile viaggio di Papa Leone nel loro Paese<\/strong> <strong>a fine settembre<\/strong>. Si tratterebbe del terzo viaggio in Europa nel giro di pochi mesi, dopo quello nel Principato di Monaco e quello di giugno in Spagna. Nel recente incontro con gli europarlamentari del Ppe, <strong>Leone ha citato i fondatori dell&#8217;Europa, tra i quali Alcide De Gasperi, invitando i politici a rifuggire da \u201celitismi\u201d e \u201cpopulismi\u201d<\/strong>. E sulla scia di tali dichiarazioni, Parolin ha sottolineato: \u201cOggi in Europa si sente brandire una parola, remigrazione, che di cristiano ha ben poco\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"Il segretario di Stato americano Marco Rubio \u00e8 arrivato in Vaticano per l&#8217;incontro con Papa Leone XIV e&hellip;\n","protected":false},"author":3,"featured_media":478651,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[14,164,165,166,7,15,11,167,12,168,161,162,163],"class_list":{"0":"post-478650","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-cronaca","9":"tag-dal-mondo","10":"tag-dalmondo","11":"tag-mondo","12":"tag-news","13":"tag-notizie","14":"tag-ultime-notizie","15":"tag-ultime-notizie-di-mondo","16":"tag-ultimenotizie","17":"tag-ultimenotiziedimondo","18":"tag-world","19":"tag-world-news","20":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116532743268032238","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/478650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=478650"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/478650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/478651"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=478650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=478650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=478650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}