{"id":480480,"date":"2026-05-08T12:56:11","date_gmt":"2026-05-08T12:56:11","guid":{"rendered":"https:\/\/www.europesays.com\/it\/480480\/"},"modified":"2026-05-08T12:56:11","modified_gmt":"2026-05-08T12:56:11","slug":"inizia-la-stagione-spiccano-rychlicki-e-bovolenta","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/480480\/","title":{"rendered":"inizia la stagione, spiccano Rychlicki e Bovolenta"},"content":{"rendered":"<p><strong>Ferdinando De Giorgi ha diramato le prime convocazioni della stagione:<\/strong> il CT della Nazionale Italiana di volley maschile ha selezionato <strong>quindici giocatrici per il primo collegiale<\/strong> di questa annata agonistica, che <strong>si svolger\u00e0 da luned\u00ec 11 a domenica 17 maggio<\/strong> presso il Centro Giulio Onesti dell\u2019Acqua Acetosa a Roma. Inizier\u00e0 a tutti gli effetti la lunga estate (anche se siamo in primavera, \u00e8 un mero modo di dire) dei<strong> Campioni del Mondo,<\/strong> che saranno poi chiamati ad affrontare la Nations League e gli Europei, dove verr\u00e0 messo in palio il primo pass per le Olimpiadi di Los Angeles 2028.<\/p>\n<p><strong>All\u2019appello mancano tutti i big di Perugia<\/strong> (che nel fine settimana del 16-17 maggio disputer\u00e0 la Final Four della Champions League), a cominciare dal capitano e palleggiatore <strong>Simone Giannelli<\/strong> e dal centrale <strong>Roberto Russo<\/strong>. Assenti anche gli uomini di Civitanova (reduce dalla finale scudetto persa contro i Block Devils), tra cui lo schiacciatore <strong>Mattia Bottolo e il libero Fabio Balaso<\/strong>. Assente anche l\u2019opposto <strong>Yuri Roman\u00f2<\/strong> dopo la stagione in Russia, mancano all\u2019appello i riferimenti di Trento (su tutti i martelli <strong>Alessandro Michieletto e Daniele Lavia<\/strong>, oltre al palleggiatore <strong>Riccardo Sbertoli<\/strong>).<\/p>\n<p>Per l\u2019occasione spiccano l\u2019opposto <strong>Alessandro Bovolenta<\/strong> (eccellente a Piacenza) e il bomber<strong> Kamil Rychlicki<\/strong>, il miglior marcatore del massimo campionato polacco con la maglia dello ZAKSA. Rispondono presente, tra gli altri, il martello <strong>Francesco Sani<\/strong> e il palleggiatore <strong>Paolo Porro<\/strong>. Di seguito il quadro dettagliato dei primi convocati di Ferdinando De Giorgi per la stagione 2026.<\/p>\n<p>CONVOCATE ITALIA COLLEGIALE VOLLEY MASCHILE<\/p>\n<p>Alessandro Bovolenta, Francesco Comparoni, Domenico Pace, Paolo Porro (You Energy Volley); Alessandro Fanizza, Tommaso Guzzo (Cisterna Volley); Tommaso Ichino (Powervolley Milano); Giulio Magalini, Marco Pellacani (M.&amp; G. Scuola Pallavolo); Leandro Aussibio Mosca (Volley Milano); Mattia Orioli, Andrea Truocchio (Pallavolo Padova); Kamil Rychlicki (Trentino Volley); Francesco Romano Sani, Matteo Staforini (Verona Volley).<\/p>\n","protected":false},"excerpt":{"rendered":"Ferdinando De Giorgi ha diramato le prime convocazioni della stagione: il CT della Nazionale Italiana di volley maschile&hellip;\n","protected":false},"author":3,"featured_media":283007,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1474],"tags":[113495,56665,1537,90,89,24475,245,244,1869],"class_list":{"0":"post-480480","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-volley","8":"tag-alessandro-bovolenta","9":"tag-ferdinando-de-giorgi","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-kamil-rychlicki","14":"tag-sport","15":"tag-sports","16":"tag-volley"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116539069936093819","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/480480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=480480"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/480480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/283007"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=480480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=480480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=480480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}