{"id":481066,"date":"2026-05-08T20:54:16","date_gmt":"2026-05-08T20:54:16","guid":{"rendered":"https:\/\/www.europesays.com\/it\/481066\/"},"modified":"2026-05-08T20:54:16","modified_gmt":"2026-05-08T20:54:16","slug":"biennale-di-venezia-corteo-pro-palestina-contro-israele-decine-di-padiglioni-chiusi","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/481066\/","title":{"rendered":"Biennale di Venezia, corteo pro Palestina contro Israele: decine di padiglioni chiusi"},"content":{"rendered":"<p>                Segui FQ su<\/p>\n<p>            <a href=\"https:\/\/whatsapp.com\/channel\/0029Vb6YLWiGzzKYN6spre2E\" class=\"ifq-post__engagement-banner-channels__action ifq-post__engagement-banner-channels__action--whatsapp\" target=\"_blank\" rel=\"nofollow noopener\" title=\"Segui FQ su WhatsApp\"><\/p>\n<p>                    WhatsApp<\/p>\n<p>                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/st.ilfattoquotidiano.it\/wp-content\/themes\/ifq-2025\/assets\/img\/fq-www\/icon-social-whatsapp-color.svg\" alt=\"WhatsApp\" height=\"16\" width=\"16\"\/><\/p>\n<p>            <\/a><\/p>\n<p>            <a href=\"https:\/\/profile.google.com\/cp\/CgovbS8wODBmNmMw\" class=\"ifq-post__engagement-banner-channels__action ifq-post__engagement-banner-channels__action--discover\" rel=\"nofollow noopener\" title=\"Segui FQ su Discover\" target=\"_blank\"><\/p>\n<p>                    Discover<\/p>\n<p>                    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/st.ilfattoquotidiano.it\/wp-content\/themes\/ifq-2025\/assets\/img\/fq-www\/icon-social-discover-color.svg\" alt=\"Discover\" height=\"16\" width=\"16\"\/><\/p>\n<p>            <\/a><\/p>\n<p>            <img decoding=\"async\" src=\"https:\/\/st.ilfattoquotidiano.it\/wp-content\/themes\/ifq-2025\/assets\/img\/fq-www\/logo-strillone-full-length.svg\" alt=\"Il Fatto Quotidiano\" class=\"ifq-post__engagement-banner-channels__media-image\" loading=\"lazy\" width=\"25\" height=\"32\"\/><\/p>\n<p class=\"ifq-post__label-soft-registration-title\">\n            Questo articolo \u00e8 gratis.        <\/p>\n<p class=\"ifq-post__label-soft-registration-text\">\n                Per leggerne altri, ricevere le newsletter e avere libero accesso ai contenuti scelti dalla redazione            <\/p>\n<p>            <a href=\"https:\/\/shop.ilfattoquotidiano.it\/registrati\/?ifq-reg-origin=regwall-soft-article-cronaca\" class=\"ifq-post__label-soft-registration-button\" onclick=\"window.dataLayer = window.dataLayer || []; window.dataLayer.push({&#010;                    event: &#039;click_paywall&#039;,&#010;                    category: &#039;regwall&#039;,&#010;                    action: &#039;Articolo gratis - registrazione&#039;,&#010;                    label: &#039;Registrati - &#039; + (window.fscUser?.test?.regwall ?? &#039;unknown&#039;)&#010;                });\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n                Registrati            <\/a><\/p>\n<p>Circa 2mila <strong>attivisti pro Pal<\/strong> in corteo contro la presenza di <strong>Israele<\/strong> alla <strong>Biennale<\/strong>. I manifestanti hanno sfilato verso l\u2019Arsenale e negli interventi al megafono hanno chiesto che \u201cvenga chiuso il padiglione di Israele\u201d e che non ci sia \u201cnessuno spazio per il sionismo e per giustificare il genocidio ancora in corso\u201d. Momenti di <strong>tensione<\/strong> con la polizia, quando gli attivisti hanno cercato di sfondare il cordone della polizia, che li ha bloccati con l\u2019uso di manganelli. Dopo pochi minuti, i manifestanti si sono allontanati ed \u00e8 tornata la calma.<\/p>\n<p>Protesta anche all\u2019interno della Biennale: decine di padiglioni ed esposizioni sono chiusi per lo sciopero di lavoratrici e lavoratori della cultura sempre contro la presenza del padiglione israeliano e il genocidio ancora in corso in Palestina e in solidariet\u00e0 <a href=\"https:\/\/www.ilfattoquotidiano.it\/2026\/05\/08\/flotilla-gaza-avila-lettera-carcere-israeliano-notizie\/8379626\/\" target=\"_blank\" rel=\"noopener nofollow\">con gli attivisti della Global Sumud Flotilla <strong>Thiago<\/strong> e <strong>Saif<\/strong><\/a>. Come annuncia Global Project la lista dei padiglioni chiusi, in aggiornamento, \u00e8 la seguente: Austria, Belgio, Egitto, Lituania, Catalogna, Lussemburgo, Polonia, Slovenia, Spagna, Svizzera, Turchia, Finlandia, Olanda, Irlanda, Qatar, Malta, Cipro, Ecuador, UK.<\/p>\n","protected":false},"excerpt":{"rendered":"Segui FQ su WhatsApp Discover Questo articolo \u00e8 gratis. Per leggerne altri, ricevere le newsletter e avere libero&hellip;\n","protected":false},"author":3,"featured_media":481067,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[14,164,165,166,7,15,11,167,12,168,161,162,163],"class_list":{"0":"post-481066","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-cronaca","9":"tag-dal-mondo","10":"tag-dalmondo","11":"tag-mondo","12":"tag-news","13":"tag-notizie","14":"tag-ultime-notizie","15":"tag-ultime-notizie-di-mondo","16":"tag-ultimenotizie","17":"tag-ultimenotiziedimondo","18":"tag-world","19":"tag-world-news","20":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116540950446759848","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/481066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=481066"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/481066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/481067"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=481066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=481066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=481066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}