{"id":481097,"date":"2026-05-08T21:22:15","date_gmt":"2026-05-08T21:22:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/481097\/"},"modified":"2026-05-08T21:22:15","modified_gmt":"2026-05-08T21:22:15","slug":"starmer-tira-dritto-farage-gongola","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/481097\/","title":{"rendered":"Starmer tira dritto, Farage gongola"},"content":{"rendered":"<p>Per il premier \u00e8 un colpo pesante.\u00a0Gi\u00e0 alle prese con il caso Mandelson, ha comunque allontanato le ipotesi di dimissioni.\u00a0\u00abSono stato eletto per un mandato di 5 anni. Intendo portarlo a termine\u00bb. Il brexiteer invece festeggia:\u00a0\u00abCambiamento storico\u00bb. Bene anche i Liberaldemocratici e i Verdi<\/p>\n<p>\u00abNo, non ho intenzione di tirarmi indietro e gettare il paese nel caos\u00bb. Parole di <a href=\"http:\/\/editorialedomani.it\/tag\/keir starmer\" rel=\"nofollow noopener\" target=\"_blank\">Keir Starmer<\/a>, mano a mano che i risultati delle elezioni locali nel <a href=\"http:\/\/editorialedomani.it\/tag\/regno unito\" rel=\"nofollow noopener\" target=\"_blank\">Regno Unito<\/a> svolte il 7 maggio confermavano la disfatta del suo Labour. I britannici sono andati al voto per rinnovare\u00a0centinaia di seggi nei consigli comunali, ma anche per scegliere la composizione dei parlamentini di Galles e Scozia. E complessivamente l\u2019esito \u00e8 stato disastroso per i laburisti e pessimo per i Conservatori.\u00a0<\/p>\n<p> I risultati delle elezioni<\/p>\n<p>Chi pu\u00f2 rivendicare la vittoria,\u00a0\u00e8 Reform di Nigel Farage, il partito populista di estrema destra. Nonostante i\u00a0diversi voti ancora da scrutinare, specie quelli dei parlamenti scozzesi e gallesi, Reform ha gi\u00e0 conquistato il maggior numero di seggi in palio: ne possedeva solo due in partenza, ora sono 406. All\u2019opposto, i laburisti ne hanno vinti per adesso 253 e il saldo \u00e8 pi\u00f9 che negativo con 261\u00a0\u201cpoltrone\u201d andate perdute. Anche i Tories sono crollati, perdendo per adesso 179\u00a0seggi e attestandosi a 262.\u00a0<\/p>\n<p>Il segno positivo, per\u00f2, lo registrano anche altre due forze politiche: i Liberaldemocratici e i Verdi. I primi hanno guadagnato 37 seggi, salendo quindi a 260, mentre i secondi sono arrivati a 53, con un +28.\u00a0<\/p>\n<p> Labour in crisi<\/p>\n<p>Per Starmer \u00e8 un colpo pesante, pur previsto. <a href=\"https:\/\/www.editorialedomani.it\/politica\/mondo\/starmer-mandelson-epstein-files-rischio-dimissioni-downing-street-regno-unito-yatu2cep\" rel=\"nofollow noopener\" target=\"_blank\">Gi\u00e0 alle prese con il caso Mandelson<\/a>,\u00a0e <a href=\"https:\/\/www.editorialedomani.it\/politica\/europa\/starmer-attacchi-ebrei-antisemitismo-premier-indebolito-verdi-regno-unito-phaje61w\" rel=\"nofollow noopener\" target=\"_blank\">fortemente indebolito<\/a>, il leader laburista ha comunque allontanato le ipotesi di dimissioni.\u00a0\u00abSono stato eletto per un mandato di 5 anni. Intendo portarlo a termine\u00bb ha dichiarato ai giornalisti questa mattina. Non si \u00e8 comunque nascosto, ha definito\u00a0\u00abduri\u00bb i risultati, assumendosene la responsabilit\u00e0.\u00a0\u00abNon c\u2019\u00e8 modo di indorare la pillola\u00bb,\u00a0ma ha rilanciato:\u00a0\u00abGiorni come questo non indeboliscono la mia determinazione a realizzare il cambiamento che ho promesso, rafforzano la mia determinazione a farlo\u00bb.\u00a0<\/p>\n<p>Per i laburisti \u00e8 periodo di grande subbuglio, con correnti che chiedono la testa politica di Starmer e con un candidato che sta sempre pi\u00f9 emergendo per prendere il suo posto, il sindaco di\u00a0Greater Manchester, Andy Burnham. Ma anche se ci dovesse essere un cambio di leadership, per il Labour si prospettano tempi difficili.<\/p>\n<p> Chi vince<\/p>\n<p>A vincere, dunque, \u00e8 Nigel Farage.\u00a0\u00abPenso che, nel complesso,\u00a0ci\u00f2 che \u00e8 accaduto rappresenti un cambiamento davvero storico nella politica britannica\u00bb, ha affermato il brexiteer, rimarcando la crisi dei laburisti\u00a0\u00abspazzati via\u00bb in diverse aree tradizionalmente favorevoli al centrosinistra. Farage non smette di\u00a0gongolare:\u00a0\u00abIl meglio deve ancora arrivare\u00bb ha detto, evidenziando anche i seggi <a href=\"https:\/\/www.editorialedomani.it\/politica\/mondo\/badenoch-leader-conservatori-sunak-y4zwn0y7\" rel=\"nofollow noopener\" target=\"_blank\">ai conservatori di Kemi Badenoch<\/a>.<\/p>\n<p>A esultare sono anche i centristi Liberaldemocratici, in crescita costante da anni. Il loro leader, Ed Davey, vuole ergersi a ultimo bastione contro l\u2019avanzata degli uomini di Farage, ma non solo.\u00a0\u00abI Liberaldemocratici sono ormai l\u2019unico partito abbastanza forte da opporsi agli estremismi populisti e proteggere il nostro paese dal caos. Saremo il punto di riferimento per tutti coloro che credono nella costruzione, non nella distruzione\u00bb, ha dichiarato.<\/p>\n<p><a href=\"https:\/\/www.editorialedomani.it\/politica\/europa\/regno-unito-elezioni-suppletive-starmer-green-party-hannah-spencer-ts3deaax\" rel=\"nofollow noopener\" target=\"_blank\">Il risultato \u00e8 pi\u00f9 che positivo anche per i Verdi di Zack Polanski<\/a>, che hanno sottratto diversi seggi ai laburisti e che in molti altri hanno decretato la sconfitta del Labour, erodendo il loro consenso da sinistra anche se cos\u00ec facendo hanno portato alla vittoria i partiti di destra. Ad ogni modo, per Polanski si tratta di un trampolino di lancio per competere a livello nazionale.<\/p>\n<p>\u00a9 Riproduzione riservata<\/p>\n","protected":false},"excerpt":{"rendered":"Per il premier \u00e8 un colpo pesante.\u00a0Gi\u00e0 alle prese con il caso Mandelson, ha comunque allontanato le ipotesi&hellip;\n","protected":false},"author":3,"featured_media":481098,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[14,164,165,166,7,15,11,167,12,168,161,162,163],"class_list":{"0":"post-481097","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-cronaca","9":"tag-dal-mondo","10":"tag-dalmondo","11":"tag-mondo","12":"tag-news","13":"tag-notizie","14":"tag-ultime-notizie","15":"tag-ultime-notizie-di-mondo","16":"tag-ultimenotizie","17":"tag-ultimenotiziedimondo","18":"tag-world","19":"tag-world-news","20":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116541059728184022","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/481097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=481097"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/481097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/481098"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=481097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=481097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=481097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}