{"id":481240,"date":"2026-05-08T23:26:15","date_gmt":"2026-05-08T23:26:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/481240\/"},"modified":"2026-05-08T23:26:15","modified_gmt":"2026-05-08T23:26:15","slug":"torino-sassuolo-2-1-gol-di-thorstvedt-simeone-e-pedersen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/481240\/","title":{"rendered":"Torino-Sassuolo 2-1, gol di Thorstvedt, Simeone e Pedersen"},"content":{"rendered":"<p>                                        Decisivi i cambi di D&#8217;Aversa con Pedersen e Zapata che hanno confezionato la rete del 2-1. Alla squadra di Grosso non basta il gol di\u00a0Thorstvedt<\/p>\n<p class=\"paragraph\" spellcheck=\"true\">Il Toro la vince con il cuore e con la forza dei suoi calciatori pi\u00f9 rappresentativi: Vlasic \u00e8 l\u2019uomo che non si arrende mai, Simeone apre la rimonta con il gol dell\u20191-1, poi Zapata scocca l\u2019assist per il 2-1 di Pedersen che festeggia il suo primo gol con il Toro. Il Sassuolo si \u00e8 fatto prendere e poi scavalcare dopo il vantaggio di Thorstvedt in avvio di ripresa e dopo aver salutato un brutto primo tempo. Granata anche sfortunati, fermati due volte sulla traversa: prima con Njie, poi con Simeone. Il Toro sale a 44 punti, scavalca per una sera il Parma in classifica e raggiunge gli stessi punti fatti la stagione scorsa a due giornate dalla fine del campionato.<\/p>\n<p>    NJIE SULLA TRAVERSA\u2014 \u00a0<\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">Ci dovessimo fermare sul primo quarto d\u2019ora, verrebbe anche da dire che le premesse per un Toro-Sassuolo all\u2019insegna del divertimento c\u2019erano tutte. Passino gli errori difensivi (grossi, da una parte e dall\u2019altra) evidenziati gi\u00e0 dai primissimi minuti, ma almeno nascono tre occasioni che aiutano a tenere vivo lo spirito del poco pubblico presente al Grande Torino. Nel primo tempo il problema \u00e8 tutto quello che \u00e8 venuto dopo il primo quarto d\u2019ora: ritmi bassi, tipicamente da partita di fine stagione con due squadre in campo senza pi\u00f9 grandi obiettivi. Soprattutto una sfilza di errori tecnici sparsi in tutte le zone del campo. Ritorniamo ai primi quindici minuti e alle tre occasioni. Al 3\u2019 la prima \u00e8 del Sassuolo e nasce da un buco di Coco, nel quale si infila Pinamonti ma la conclusione muore comodamente tra le braccia di Paleari. Nel Toro gioca dall\u2019inizio Njie in coppia con Simeone e il ventenne cresciuto nel vivaio granata si mette subito in evidenza. Minuto 12, angolo di Gineitis, proprio Njie di testa si stampa sulla traversa. Un minuto dopo da un cross di Lazaro, ancora Njie si divora un gol a porta vuota sparando in curva. Il primo tempo finisce di fatto qua, anche se al 45\u2019 c\u2019\u00e8 una bella rovesciata di Simeone a chiamare i riflessi di Muric ma il gioco viene fermato per un fallo, poco prima, di Lazaro su Doig.<\/p>\n<p><a class=\"is-partner-link\" href=\"https:\/\/abbonamenti.gazzetta.it\/scudetto-inter-poster-de\/?pwcmp=cta&amp;forceBrowser=true\" rel=\"nofollow noopener\" target=\"_blank\">Inter Campione d\u2019Italia: abbonati alla Digital Edition + Poster Prima Pagina a 4,99\u20ac\/mese<\/a><\/p>\n<p>    toro di rimonta\u2014 \u00a0<\/p>\n<p class=\"paragraph is-inline\" spellcheck=\"true\">In avvio di secondo tempo, una dormita collettiva dei difensori del Toro regala il vantaggio al Sassuolo. Minuto 6\u2019, Lipani si infila sulla destra e mette una palla in mezzo che passa accanto al piede di Marianucci. Il difensore \u201cbuca\u201d, dietro di lui Lazaro non interviene, a Thorstvedt non pare vero e mette dentro a due passi. Dentro Zapata e Pedersen, al 17\u2019 \u00e8 Simeone a suonare la carica: prende la traversa di testa. E\u2019 solo il preavviso, quattro minuti pi\u00f9 tardi il Cholito incorna in maniera vincente sul cross di Ebosse: \u00e8 il suo undicesimo gol in campionato. Il Toro ormai si \u00e8 svegliato, ha cambiato marcia e al 25\u2019 trova il colpo della rimonta: cross di Zapata, testa di Pedersen. Il gol nasce tutto dalla panchina.<\/p>\n<p>la partita\u2014 \u00a0<\/p>\n<p>Il Torino non ha trovato nemmeno un gol nelle ultime duegiornate di Serie A, ma pu\u00f2 contare su un Simeone in grande spolvero. L&#8217;argentino ha trovato la rete in ciascuna delle ultime quattro presenze casalinghe in Serie A e solo un giocatore \u00e8 arrivato a cinque gare interne di fila a segno con la maglia del Torino in un singolo massimo campionato nell&#8217;era dei tre punti a vittoria: Marco Ferrante nel 2000.\u00a0Il Sassuolo, invece, ha mantenuto la porta inviolata nelle ultime due gare (vs Fiorentina e Milan) e potrebbe arrivare a tre clean sheet di fila per la prima volta da novembre 2020 in Serie A, sotto la guida di Roberto De Zerbi.<\/p>\n<p class=\"is-copyright\">\u00a9 RIPRODUZIONE RISERVATA<\/p>\n","protected":false},"excerpt":{"rendered":"Decisivi i cambi di D&#8217;Aversa con Pedersen e Zapata che hanno confezionato la rete del 2-1. Alla squadra&hellip;\n","protected":false},"author":3,"featured_media":481241,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1452],"tags":[4158,3732,721,1856,921,3173,246,2147,108253,5362,1740,1976,5197,4795,1537,90,89,59573,1981,3479,3483,60806,2672,29199,21438,21066,1292,3673,16310,6299,7189,270,1739,245,244,577,1928,63196,1641,5517,267924,7553,29202],"class_list":{"0":"post-481240","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-calcio","8":"tag-app","9":"tag-avvio","10":"tag-calcio","11":"tag-campionato","12":"tag-campo","13":"tag-cross","14":"tag-dazn","15":"tag-dispositivi","16":"tag-dispositivi-mobili","17":"tag-errori","18":"tag-football","19":"tag-gol","20":"tag-granata","21":"tag-infila","22":"tag-it","23":"tag-italia","24":"tag-italy","25":"tag-lazaro","26":"tag-mette","27":"tag-minuti","28":"tag-minuto","29":"tag-mobili","30":"tag-nasce","31":"tag-njie","32":"tag-occasioni","33":"tag-pedersen","34":"tag-punti","35":"tag-quarto","36":"tag-rimonta","37":"tag-sassuolo","38":"tag-simeone","39":"tag-sky","40":"tag-soccer","41":"tag-sport","42":"tag-sports","43":"tag-stagione","44":"tag-testa","45":"tag-thorstvedt","46":"tag-torino","47":"tag-toro","48":"tag-toro-sassuolo","49":"tag-traversa","50":"tag-zapata"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116541547317580437","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/481240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=481240"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/481240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/481241"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=481240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=481240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=481240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}