{"id":481298,"date":"2026-05-09T00:07:14","date_gmt":"2026-05-09T00:07:14","guid":{"rendered":"https:\/\/www.europesays.com\/it\/481298\/"},"modified":"2026-05-09T00:07:14","modified_gmt":"2026-05-09T00:07:14","slug":"sedico-bimbo-di-sei-anni-muore-sotto-un-muletto","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/481298\/","title":{"rendered":"Sedico, bimbo di sei anni muore sotto un muletto"},"content":{"rendered":"<p>Muore un bambino di sei anni, in un piazzale della zona industriale di Sedico. Per cause ancora in corso di accertamento da parte dello Spisal e della Polizia, il piccolo sarebbe rimasto schiacciato da un muletto, davanti alle aziende De March, Jet System e Serma.<\/p>\n<p>L\u2019incidente mortale risale alle 18.30, quando una telefonata \u00e8 arrivata al 113 e ha messo in moto la macchina dei soccorsi. <strong>Sul posto, anche l\u2019elicottero del Suem 118, che \u00e8 atterrato nella zona del Boscon,<\/strong> ma quando i soccorritori sono arrivati per il bimbo non c\u2019era pi\u00f9 nulla da fare e il medico legale ha potuto solo constatare il decesso e avvertire il magistrato di turno.<\/p>\n<p>Bimbo di sei anni muore sotto un muletto a Sedico: la videoricostruzione<\/p>\n<p><strong>Da chiarire con precisione i motivi dell\u2019incidente mortale<\/strong>, dopo che la squadra dei vigili del fuoco del Comando di Belluno ha rimosso il pesante macchinario, che sar\u00e0 senz\u2019altro messo sotto sequestro. Fino alle 20, la salma non era ancora stata rimossa e sono ancora in corso tutti gli accertamenti necessari alle indagini, anche per individuare eventuali responsabilit\u00e0.<\/p>\n<p>Da stabilire soprattutto cosa ci facesse <strong>un bimbo accanto a un muletto, naturalmente sprovvisto di tutti i dispositivi di sicurezza previsti dalle normative in vigore<\/strong>. Quelli che di solito indossano i lavoratori per proteggersi dagli infortuni, che possono capitare.<\/p>\n","protected":false},"excerpt":{"rendered":"Muore un bambino di sei anni, in un piazzale della zona industriale di Sedico. Per cause ancora in&hellip;\n","protected":false},"author":3,"featured_media":481299,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[14,8,1537,90,89,7,15,82,9,83,10,13,11,80,84,12,81,85],"class_list":{"0":"post-481298","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ultime-notizie","8":"tag-cronaca","9":"tag-headlines","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-news","14":"tag-notizie","15":"tag-notizie-di-cronaca","16":"tag-notizie-principali","17":"tag-notiziedicronaca","18":"tag-notizieprincipali","19":"tag-titoli","20":"tag-ultime-notizie","21":"tag-ultime-notizie-di-cronaca","22":"tag-ultime-notizie-e-news-di-oggi","23":"tag-ultimenotizie","24":"tag-ultimenotiziedicronaca","25":"tag-ultimenotizieenewsdioggi"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116541708455376229","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/481298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=481298"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/481298\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/481299"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=481298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=481298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=481298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}