{"id":481897,"date":"2026-05-09T10:27:15","date_gmt":"2026-05-09T10:27:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/481897\/"},"modified":"2026-05-09T10:27:15","modified_gmt":"2026-05-09T10:27:15","slug":"taranto-uomo-ferito-in-piazza-fontana","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/481897\/","title":{"rendered":"Taranto, uomo ferito in Piazza Fontana"},"content":{"rendered":"<p>TARANTO \u2013 Omicidio nella citt\u00e0 vecchia di Taranto alle prime ore del mattino. Il grave episodio \u00e8 avvenuto in Piazza Fontana, a ridosso dell\u2019area del porto mercantile.<\/p>\n<p>Intorno alle 05.30 ,\u00a0 un uomo di nazionalit\u00e0 straniera, un 35enne del Mali , sarebbe stato ucciso al culmine di una lite le cui cause sono in corso di accertamento. L\u2019uomo presenta diverse ferite sull\u2019addome, l\u2019arma utilizzata potrebbe essere un cacciavite.<\/p>\n<p>La discussione, tra la vittima ed altri uomini, sarebbe partita all\u2019interno di un bar presente nella stessa piazza, per poi degenerare all\u2019esterno dell\u2019attivit\u00e0, e dopo che il titolare del bar avrebbe invitato tutti ad uscire dal locale.<\/p>\n<p>Sul posto \u00e8 intervenuta immediatamente un\u2019ambulanza del 118 che ha prestato le prime cure alla vittima, apparsa in condizioni serie e successivamente trasportata d\u2019urgenza all\u2019ospedale Santissima Annunziata, dove poi \u00e8 deceduto<\/p>\n<p>La zona \u00e8 stata blindata dagli agenti della Polizia di Stato (Squadra Volante e Squadra Mobile) che hanno avviato i rilievi per ricostruire la dinamica dell\u2019aggressione e individuare il responsabile.<\/p>\n<p>L\u2019episodio riaccende il dibattito sulla sicurezza urbana in una zona della citt\u00e0 gi\u00e0 teatro, in passato, di simili episodi di violenza. Gli investigatori starebbero acquisendo i filmati\u00a0 delle numerose telecamere di videosorveglianza preswnti nella zona per ottenere elementi utili alle indagini<\/p>\n<p>IMMAGINI DI FRANCESCO MANFUSO<\/p>\n<p>\u00a0<\/p>\n<p>++ NOTIZIA IN AGGIORNAMENTO\u00a0 ++<\/p>\n<p>        About Author<\/p>\n<p>\t\tContinue Reading<\/p>\n","protected":false},"excerpt":{"rendered":"TARANTO \u2013 Omicidio nella citt\u00e0 vecchia di Taranto alle prime ore del mattino. Il grave episodio \u00e8 avvenuto&hellip;\n","protected":false},"author":3,"featured_media":481898,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[9763,14,93,94,1537,90,89,7,15,151116,10960,11,84,91,12,85,92],"class_list":{"0":"post-481897","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-italia","8":"tag-accoltellamento","9":"tag-cronaca","10":"tag-cronaca-italiana","11":"tag-cronacaitaliana","12":"tag-it","13":"tag-italia","14":"tag-italy","15":"tag-news","16":"tag-notizie","17":"tag-piazza-fontana","18":"tag-taranto","19":"tag-ultime-notizie","20":"tag-ultime-notizie-e-news-di-oggi","21":"tag-ultime-notizie-italia","22":"tag-ultimenotizie","23":"tag-ultimenotizieenewsdioggi","24":"tag-ultimenotizieitalia"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/481897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=481897"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/481897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/481898"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=481897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=481897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=481897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}