{"id":483444,"date":"2026-05-10T09:55:16","date_gmt":"2026-05-10T09:55:16","guid":{"rendered":"https:\/\/www.europesays.com\/it\/483444\/"},"modified":"2026-05-10T09:55:16","modified_gmt":"2026-05-10T09:55:16","slug":"gli-ultimi-due-attivisti-della-global-sumud-flotilla-sono-stati-liberati-ed-espulsi-da-israele","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/483444\/","title":{"rendered":"Gli ultimi due attivisti della Global Sumud Flotilla sono stati liberati ed espulsi da Israele"},"content":{"rendered":"<p>Israele ha liberato ed espulso dal paese Thiago \u00c1vila e Saif Abu Keshek, gli <a href=\"https:\/\/www.ilpost.it\/2026\/04\/26\/partita-nuova-flotilla-gaza\/\" rel=\"nofollow noopener\" target=\"_blank\">attivisti<\/a> della Global Sumud Flotilla <a href=\"https:\/\/www.ilpost.it\/2026\/04\/29\/global-sumud-flotilla-intercettata-imbarcazioni-militari-israeliane-in-acque-internazionali\/\" rel=\"nofollow noopener\" target=\"_blank\">arrestati<\/a> il 29 aprile e trasferiti in un carcere israeliano per essere interrogati. Entrambi si trovavano a bordo di barche italiane ed erano in acque internazionali, al largo dell\u2019isola di Creta, quando erano stati bloccati dalla marina israeliana: fanno parte del comitato direttivo della Flotilla.<\/p>\n<p>Il ministero degli Esteri israeliano, che li ha <a href=\"https:\/\/x.com\/IsraelMFA\/status\/2053317156310237651\" rel=\"nofollow\">definiti<\/a> due \u00abprovocatori professionisti\u00bb, ha fatto sapere di averli espulsi dal paese \u00abdopo aver completato le indagini su di loro\u00bb. La loro detenzione era stata confermata dal tribunale di Ashkelon, in Israele, soltanto <a href=\"https:\/\/www.ilpost.it\/2026\/05\/05\/tribunale-israeliano-estende-sei-giorni-a-domenica-la-detenzione-due-attivisti-global-sumud-flotilla\/\" rel=\"nofollow noopener\" target=\"_blank\">fino a domenica<\/a>.<\/p>\n<p>Abu Keshek, che \u00e8 spagnolo, \u00e8 accusato di far parte di un gruppo terroristico, mentre \u00c1vila, che \u00e8 brasiliano, \u00e8 accusato di attivit\u00e0 illegali: entrambi negano tutte le accuse.<\/p>\n<p>Durante la detenzione entrambi hanno detto di avere sub\u00ecto maltrattamenti e abusi psicologici. Due avvocate che li avevano incontrati luned\u00ec avevano fatto sapere che entrambi si trovavano detenuti in isolamento e in celle con illuminazione ad alta intensit\u00e0 per 24 ore su 24, una pratica impiegata nel sistema carcerario israeliano per privare i detenuti del sonno e disorientarli.<\/p>\n","protected":false},"excerpt":{"rendered":"Israele ha liberato ed espulso dal paese Thiago \u00c1vila e Saif Abu Keshek, gli attivisti della Global Sumud&hellip;\n","protected":false},"author":3,"featured_media":483445,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[14,8,1537,90,89,7,15,82,9,83,10,13,11,80,84,12,81,85],"class_list":{"0":"post-483444","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ultime-notizie","8":"tag-cronaca","9":"tag-headlines","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-news","14":"tag-notizie","15":"tag-notizie-di-cronaca","16":"tag-notizie-principali","17":"tag-notiziedicronaca","18":"tag-notizieprincipali","19":"tag-titoli","20":"tag-ultime-notizie","21":"tag-ultime-notizie-di-cronaca","22":"tag-ultime-notizie-e-news-di-oggi","23":"tag-ultimenotizie","24":"tag-ultimenotiziedicronaca","25":"tag-ultimenotizieenewsdioggi"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116549682909871635","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/483444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=483444"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/483444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/483445"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=483444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=483444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=483444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}