{"id":483617,"date":"2026-05-10T12:36:11","date_gmt":"2026-05-10T12:36:11","guid":{"rendered":"https:\/\/www.europesays.com\/it\/483617\/"},"modified":"2026-05-10T12:36:11","modified_gmt":"2026-05-10T12:36:11","slug":"guerra-ucraina-russia-le-ultime-news-di-oggi-10-maggio-diretta","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/483617\/","title":{"rendered":"Guerra Ucraina Russia, le ultime news di oggi 10 maggio. DIRETTA"},"content":{"rendered":"<p>L&#8217;operazione militare speciale in Ucraina si concluder\u00e0 con una vittoria. Lo ha detto il portavoce del Cremlino, Dmitry Peskov, in un&#8217;intervista citata dalla Tass. \\&#8221;Questa \u00e8 la nostra guerra. E la vinceremo\\&#8221;, ha sottolineato il portavoce.\\n<\/p>\n<p>La guerra in Ucraina \u201csi avvia alla conclusione\u201d, aveva detto ieri Vladimir Putin al termine della lunga giornata cominciata la parata sulla Piazza Rossa nell&#8217;anniversario della vittoria sul nazifascismo. \u201cCombattiamo contro una forza aggressiva che \u00e8 sostenuta e armata dall&#8217;intero blocco della Nato\u201d, aveva detto lo zar nel suo breve discorso, mentre il Cremlino gelava gli auspici di Trump di estendere la tregua di tre giorni dichiarata ieri. \u201cNon abbiamo mai rifiutato di tenere negoziati con l&#8217;Ue. Come candidato al ruolo di negoziatore, preferirei l&#8217;ex cancelliere tedesco Schroeder\u201d, le parole del presidente russo.<\/p>\n<p>\\n<\/p>\n<p><strong>Per approfondire:<\/strong><\/p>\n<p>\\n\\n<\/p>\n<p><strong>Per ricevere le notizie di Sky TG24:<\/strong><\/p>\n<p>\\n<\/p>\n<ul>\\n  <\/p>\n<li>Il canale Whatsapp di Sky TG24 (<a href=\"\\&quot;https:\/\/whatsapp.com\/channel\/0029VaDyGIp90x2wDXgUnV2j\\&quot;\" data-intcmp-qp=\"\\&quot;skytg24_liveblog_interlink_text\\&quot;\">clicca qui<\/a>)<\/li>\n<p>\\n  <\/p>\n<li>Le notizie audio con i titoli del tg (<a href=\"\\&quot;https:\/\/tg24.sky.it\/cronaca\/approfondimenti\/audio-news-sky-tg24.html\\&quot;\" data-intcmp=\"\\&quot;skytg24_liveblog_interlink_text\\&quot;\">clicca qui<\/a>)<\/li>\n<p>\\n<\/ul>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;0ff6e7c0-54c7-4226-afdf-5df06b48cffb&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}}],&#8221;posts&#8221;:[{&#8220;timestamp&#8221;:&#8221;2026-05-10T11:23:21.250Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-10T13:23:21+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Cremlino: \\&#8221;Questa \u00e8 la nostra guerra, vinceremo\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>\\&#8221;Questa \u00e8 la nostra guerra. E \u00a0la vinceremo\\&#8221;. Lo ha detto il portavoce del Cremlino, Dmitry Peskov, in dichiarazioni rilanciate dall&#8217;agenzia russa Tass, passati pi\u00f9 di quattro anni dall&#8217;avvio dell&#8217;invasione russa su vasta scala dell&#8217;Ucraina. Le parole di Peskov arrivano dopo che ieri il leader russo, Vladimir Putin, ha detto di ritenere \\&#8221;il conflitto stia volgendo al termine\\&#8221;.<\/p>\n<p>\\n&#8221;,&#8221;postId&#8221;:&#8221;44656c5c-8b7a-4997-8112-6d2390fdedf4&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-10T11:20:45.571Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-10T13:20:45+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Cremlino: \\&#8221;Witkoff e Kushner attesi presto a Mosca\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Gli inviati del presidente americano Steve Witkoff e Jared Kushner sono attesi \\&#8221;presto\\&#8221; a Mosca per \\&#8221;continuare il dialogo\\&#8221;. Lo ha annunciato il consigliere presidenziale russo Yuri Ushakov a Rossiya-1, citato dalla Tass. \\&#8221;Prima o poi, e credo abbastanza presto, i nostri omologhi Witkoff e Kushner verranno a Mosca\\&#8221;, ha affermato il diplomatico. \\&#8221;Continueremo il nostro dialogo con loro\\&#8221;, ha aggiunto.\u00a0<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;8c607ffe-9598-4fd7-a11c-8bf8e68f1303&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-10T11:04:33.386Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-10T13:04:33+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Cremlino: \\&#8221;La guerra in Ucraina finir\u00e0 con una vittoria\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>L&#8217;operazione militare speciale in Ucraina si concluder\u00e0 con una vittoria. Lo ha detto il portavoce del Cremlino, Dmitry Peskov, in un&#8217;intervista citata dalla Tass. \\&#8221;Questa \u00e8 la nostra guerra. E la vinceremo\\&#8221;, ha sottolineato il portavoce. Ieri il presidente Vladimir Putin aveva dichiarato che \\&#8221;il conflitto ucraino sta volgendo al termine\\&#8221;.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;5a546343-68d9-4f43-af2e-979e89090e76&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-10T10:03:14.113Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-10T12:03:14+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Mosca: attacchi ucraini contro postazioni militari e siti civili nonostante la tregua&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>\\&#8221;Nonostante il cessate il fuoco, l&#8217;esercito ucraino ha continuato a effettuare attacchi con droni e artiglieria contro posizioni russe e siti civili nelle zone di confine\\&#8221;. Lo afferma il ministero della Difesa russo citato dalla Tass.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;f46642db-2f45-456a-a633-128b4491a92d&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-10T08:21:41.281Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-10T10:21:41+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Autorit\u00e0 ucraine: almeno 17 feriti in attacchi russi durante la tregua&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Almeno 17 persone sono risultate ferite in attacchi attribuiti alle forze russe in Ucraina avvenuti tra la mattinata di ieri e le prime ore di oggi, dunque nel corso del periodo di cessate il fuoco di tre giorni annunciato tra le parti e iniziato ieri: \u00e8 quanto riferiscono stamane le autorit\u00e0 locali, citate da Ukrinform.\u00a0\u00a0\u00a0\u00a0Una delle persone ferite, una bimba di tre anni, \u00e8 stata segnalata nel Dnipropetrovsk, altre sette, tra cui un bimbo, nel Kherson, altre otto, tra cui due minori, nel Kharkiv e uno nella regione di Sumy.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;c136cc29-628d-480b-b684-adf6941d6f73&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-10T07:33:39.938Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-10T09:33:39+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Putin: da Kiev ancora nessuna proposta sullo scambio di prigionieri&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Il presidente russo Vladimir Putin ha dichiarato che la Russia non ha ricevuto alcuna proposta dall&#8217;Ucraina in merito a un ampio scambio di prigionieri annunciato dal presidente degli Stati Uniti Donald Trump. \\&#8221;Contiamo sulla risposta della parte ucraina alla proposta avanzata dal presidente degli Stati Uniti. Purtroppo, finora non abbiamo ancora ricevuto alcuna proposta\\&#8221;, ha detto Putin ai giornalisti.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;f169eea5-e850-439b-a834-6839173406fd&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-10T04:19:37.049Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-10T06:19:37+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Cremlino, \\&#8221;Fico non ha portato a Putin alcun messaggio di Zelensky\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Il primo ministro slovacco Robert Fico non ha trasmesso alcun \\&#8221;messaggio\\&#8221; da parte di Volodymyr Zelensky durante il suo incontro con il presidente russo Vladimir Putin a Mosca. Lo ha detto ai giornalisti il consigliere di Putin, Yuri Ushakov. \u00a0Fico \u00e8 stato l&#8217;unico leader dell&#8217;Unione Europea a visitare Mosca per le celebrazioni del Giorno della Vittoria in Russia, pur non partecipando alla parata. In precedenza, un funzionario slovacco aveva affermato che Fico avrebbe potuto trasmettere messaggi di Zelensky a Putin durante il suo incontro con il leader russo. Ushakov ha affermato che ci\u00f2 non \u00e8 accaduto, pur ammettendo che Fico ha parlato dei suoi recenti incontri con Zelensky durante il suo colloquio con Putin. \\&#8221;Il primo ministro ha informato il nostro presidente e la nostra delegazione di aver effettivamente incontrato Zelensky qualche giorno fa\\&#8221;, ha dichiarato Ushakov, secondo quanto riportato dall&#8217;agenzia di stampa russa Interfax. \\&#8221;Zelensky ha condiviso la sua valutazione della situazione attuale nel contesto russo-ucraino. Ma Zelensky non inviato alcun messaggio tramite lui. Fico si \u00e8 limitato a fornire un resoconto piuttosto dettagliato di ci\u00f2 che aveva discusso con Zelensky\\&#8221;.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;8b74c6f7-61a2-4246-834d-46f586b9ba95&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-10T04:19:02.785Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-10T06:19:02+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Putin: \\&#8221;Nessuna proposta da Kiev per scambio prigionieri\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Il presidente Vladimir Putin ha dichiarato che la Russia non ha ricevuto alcuna proposta dall&#8217;Ucraina in merito a un ampio scambio di prigionieri annunciato dal presidente statunitense Donald Trump. \\&#8221;Contiamo sulla parte ucraina affinch\u00e9 risponda alla proposta avanzata dal Presidente degli Stati Uniti. Purtroppo, finora non abbiamo ancora ricevuto alcuna proposta\\&#8221;, ha dichiarato Putin ai giornalisti.<\/p>\n<p>\\n&#8221;,&#8221;postId&#8221;:&#8221;32830138-5e45-4901-aea2-b9de3cb4e3bb&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-10T04:18:37.922Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-10T06:18:37+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Putin: \\&#8221;Pronto a parlare con Ue, come negoziatore preferirei Schroeder\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Il presidente russo Vladimir Putin ha dichiarato di essere pronto ad accettare come negoziatore dell&#8217;Unione Europea con Mosca qualsiasi leader che non abbia espresso giudizi negativi sulla Russia. Ma personalmente, ha detto parlando con i giornalisti, il negoziatore ideale per il dialogo tra Russia ed Europa \u00e8 l&#8217;ex cancelliere tedesco Schroeder. Il 7 maggio, il presidente del Consiglio europeo Ant\u00f3nio Costa ha dichiarato che l&#8217;Ue si sta preparando a possibili negoziati con la Russia e il presidente Vladimir Putin sul conflitto in Ucraina. Ha affermato che la Ue ha le potenzialit\u00e0 per dialogare con la Russia e che attualmente si sta cercando di definire la modalit\u00e0 migliore per organizzare i preparativi per potenziali negoziati.<\/p>\n<p>\\n&#8221;,&#8221;postId&#8221;:&#8221;504ebe12-f34c-4aa7-86c8-bea7cd814387&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}}]}&#8221; query='{&#8220;configurationName&#8221;:&#8221;LIVEBLOG_CONTAINER_WIDGET&#8221;,&#8221;liveblogId&#8221;:&#8221;4c02616b-4f2a-43a8-9940-d8677c19da2d&#8221;,&#8221;tenant&#8221;:&#8221;tg24&#8243;,&#8221;limit&#8221;:800}&#8217; config='{&#8220;live&#8221;:true,&#8221;isWebView&#8221;:false,&#8221;postsPerPageMobile&#8221;:10,&#8221;postsPerPageDesktop&#8221;:10}&#8217;&gt;<\/p>\n<p>L&#8217;operazione militare speciale in Ucraina si concluder\u00e0 con una vittoria. Lo ha detto il portavoce del Cremlino, Dmitry Peskov, in un&#8217;intervista citata dalla Tass. &#8220;Questa \u00e8 la nostra guerra. E la vinceremo&#8221;, ha sottolineato il portavoce.<\/p>\n<p>La guerra in Ucraina \u201csi avvia alla conclusione\u201d, aveva detto ieri Vladimir Putin al termine della lunga giornata cominciata la parata sulla Piazza Rossa nell&#8217;anniversario della vittoria sul nazifascismo. \u201cCombattiamo contro una forza aggressiva che \u00e8 sostenuta e armata dall&#8217;intero blocco della Nato\u201d, aveva detto lo zar nel suo breve discorso, mentre il Cremlino gelava gli auspici di Trump di estendere la tregua di tre giorni dichiarata ieri. \u201cNon abbiamo mai rifiutato di tenere negoziati con l&#8217;Ue. Come candidato al ruolo di negoziatore, preferirei l&#8217;ex cancelliere tedesco Schroeder\u201d, le parole del presidente russo.<\/p>\n<p><strong>Per approfondire:<\/strong><\/p>\n<p><strong>Per ricevere le notizie di Sky TG24:<\/strong><\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>46 minuti fa<\/p>\n<p>Cremlino: &#8220;Questa \u00e8 la nostra guerra, vinceremo&#8221;<\/p>\n<p>&#8220;Questa \u00e8 la nostra guerra. E \u00a0la vinceremo&#8221;. Lo ha detto il portavoce del Cremlino, Dmitry Peskov, in dichiarazioni rilanciate dall&#8217;agenzia russa Tass, passati pi\u00f9 di quattro anni dall&#8217;avvio dell&#8217;invasione russa su vasta scala dell&#8217;Ucraina. Le parole di Peskov arrivano dopo che ieri il leader russo, Vladimir Putin, ha detto di ritenere &#8220;il conflitto stia volgendo al termine&#8221;.<\/p>\n<p>48 minuti fa<\/p>\n<p>Cremlino: &#8220;Witkoff e Kushner attesi presto a Mosca&#8221;<\/p>\n<p>Gli inviati del presidente americano Steve Witkoff e Jared Kushner sono attesi &#8220;presto&#8221; a Mosca per &#8220;continuare il dialogo&#8221;. Lo ha annunciato il consigliere presidenziale russo Yuri Ushakov a Rossiya-1, citato dalla Tass. &#8220;Prima o poi, e credo abbastanza presto, i nostri omologhi Witkoff e Kushner verranno a Mosca&#8221;, ha affermato il diplomatico. &#8220;Continueremo il nostro dialogo con loro&#8221;, ha aggiunto.\u00a0<\/p>\n<p>13:04<\/p>\n<p>Cremlino: &#8220;La guerra in Ucraina finir\u00e0 con una vittoria&#8221;<\/p>\n<p>L&#8217;operazione militare speciale in Ucraina si concluder\u00e0 con una vittoria. Lo ha detto il portavoce del Cremlino, Dmitry Peskov, in un&#8217;intervista citata dalla Tass. &#8220;Questa \u00e8 la nostra guerra. E la vinceremo&#8221;, ha sottolineato il portavoce. Ieri il presidente Vladimir Putin aveva dichiarato che &#8220;il conflitto ucraino sta volgendo al termine&#8221;.<\/p>\n<p>12:03<\/p>\n<p>Mosca: attacchi ucraini contro postazioni militari e siti civili nonostante la tregua<\/p>\n<p>&#8220;Nonostante il cessate il fuoco, l&#8217;esercito ucraino ha continuato a effettuare attacchi con droni e artiglieria contro posizioni russe e siti civili nelle zone di confine&#8221;. Lo afferma il ministero della Difesa russo citato dalla Tass.<\/p>\n<p>10:21<\/p>\n<p>Autorit\u00e0 ucraine: almeno 17 feriti in attacchi russi durante la tregua<\/p>\n<p>Almeno 17 persone sono risultate ferite in attacchi attribuiti alle forze russe in Ucraina avvenuti tra la mattinata di ieri e le prime ore di oggi, dunque nel corso del periodo di cessate il fuoco di tre giorni annunciato tra le parti e iniziato ieri: \u00e8 quanto riferiscono stamane le autorit\u00e0 locali, citate da Ukrinform.\u00a0\u00a0\u00a0\u00a0Una delle persone ferite, una bimba di tre anni, \u00e8 stata segnalata nel Dnipropetrovsk, altre sette, tra cui un bimbo, nel Kherson, altre otto, tra cui due minori, nel Kharkiv e uno nella regione di Sumy.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>09:33<\/p>\n<p>Putin: da Kiev ancora nessuna proposta sullo scambio di prigionieri<\/p>\n<p>Il presidente russo Vladimir Putin ha dichiarato che la Russia non ha ricevuto alcuna proposta dall&#8217;Ucraina in merito a un ampio scambio di prigionieri annunciato dal presidente degli Stati Uniti Donald Trump. &#8220;Contiamo sulla risposta della parte ucraina alla proposta avanzata dal presidente degli Stati Uniti. Purtroppo, finora non abbiamo ancora ricevuto alcuna proposta&#8221;, ha detto Putin ai giornalisti.<\/p>\n<p>06:19<\/p>\n<p>Cremlino, &#8220;Fico non ha portato a Putin alcun messaggio di Zelensky&#8221;<\/p>\n<p>Il primo ministro slovacco Robert Fico non ha trasmesso alcun &#8220;messaggio&#8221; da parte di Volodymyr Zelensky durante il suo incontro con il presidente russo Vladimir Putin a Mosca. Lo ha detto ai giornalisti il consigliere di Putin, Yuri Ushakov. \u00a0Fico \u00e8 stato l&#8217;unico leader dell&#8217;Unione Europea a visitare Mosca per le celebrazioni del Giorno della Vittoria in Russia, pur non partecipando alla parata. In precedenza, un funzionario slovacco aveva affermato che Fico avrebbe potuto trasmettere messaggi di Zelensky a Putin durante il suo incontro con il leader russo. Ushakov ha affermato che ci\u00f2 non \u00e8 accaduto, pur ammettendo che Fico ha parlato dei suoi recenti incontri con Zelensky durante il suo colloquio con Putin. &#8220;Il primo ministro ha informato il nostro presidente e la nostra delegazione di aver effettivamente incontrato Zelensky qualche giorno fa&#8221;, ha dichiarato Ushakov, secondo quanto riportato dall&#8217;agenzia di stampa russa Interfax. &#8220;Zelensky ha condiviso la sua valutazione della situazione attuale nel contesto russo-ucraino. Ma Zelensky non inviato alcun messaggio tramite lui. Fico si \u00e8 limitato a fornire un resoconto piuttosto dettagliato di ci\u00f2 che aveva discusso con Zelensky&#8221;.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>06:19<\/p>\n<p>Putin: &#8220;Nessuna proposta da Kiev per scambio prigionieri&#8221;<\/p>\n<p>Il presidente Vladimir Putin ha dichiarato che la Russia non ha ricevuto alcuna proposta dall&#8217;Ucraina in merito a un ampio scambio di prigionieri annunciato dal presidente statunitense Donald Trump. &#8220;Contiamo sulla parte ucraina affinch\u00e9 risponda alla proposta avanzata dal Presidente degli Stati Uniti. Purtroppo, finora non abbiamo ancora ricevuto alcuna proposta&#8221;, ha dichiarato Putin ai giornalisti.<\/p>\n<p>06:18<\/p>\n<p>Putin: &#8220;Pronto a parlare con Ue, come negoziatore preferirei Schroeder&#8221;<\/p>\n<p>Il presidente russo Vladimir Putin ha dichiarato di essere pronto ad accettare come negoziatore dell&#8217;Unione Europea con Mosca qualsiasi leader che non abbia espresso giudizi negativi sulla Russia. Ma personalmente, ha detto parlando con i giornalisti, il negoziatore ideale per il dialogo tra Russia ed Europa \u00e8 l&#8217;ex cancelliere tedesco Schroeder. Il 7 maggio, il presidente del Consiglio europeo Ant\u00f3nio Costa ha dichiarato che l&#8217;Ue si sta preparando a possibili negoziati con la Russia e il presidente Vladimir Putin sul conflitto in Ucraina. Ha affermato che la Ue ha le potenzialit\u00e0 per dialogare con la Russia e che attualmente si sta cercando di definire la modalit\u00e0 migliore per organizzare i preparativi per potenziali negoziati.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n","protected":false},"excerpt":{"rendered":"L&#8217;operazione militare speciale in Ucraina si concluder\u00e0 con una vittoria. Lo ha detto il portavoce del Cremlino, Dmitry&hellip;\n","protected":false},"author":3,"featured_media":419582,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[14,164,165,77,56742,166,7,15,171,170,11,167,12,168,4526,4528,161,162,163],"class_list":{"0":"post-483617","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-cronaca","9":"tag-dal-mondo","10":"tag-dalmondo","11":"tag-guerra","12":"tag-liveblog","13":"tag-mondo","14":"tag-news","15":"tag-notizie","16":"tag-russia","17":"tag-ucraina","18":"tag-ultime-notizie","19":"tag-ultime-notizie-di-mondo","20":"tag-ultimenotizie","21":"tag-ultimenotiziedimondo","22":"tag-vladimir-putin","23":"tag-volodymyr-zelensky","24":"tag-world","25":"tag-world-news","26":"tag-worldnews"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/483617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=483617"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/483617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/419582"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=483617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=483617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=483617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}