{"id":484208,"date":"2026-05-10T22:00:21","date_gmt":"2026-05-10T22:00:21","guid":{"rendered":"https:\/\/www.europesays.com\/it\/484208\/"},"modified":"2026-05-10T22:00:21","modified_gmt":"2026-05-10T22:00:21","slug":"borse-antidoto-allo-stress-emma-crea-ansianotansia","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/484208\/","title":{"rendered":"Borse antidoto allo stress, Emma crea \u00abAnsianotansia\u00bb"},"content":{"rendered":"\n<p>La creativit\u00e0, una cura per l\u2019anima di Emma Reina. <strong class=\"nero\">Classe 2000<\/strong>, nata a Milano ma cresciuta a Bergamo dove si \u00e8 trasferita con la famiglia all\u2019et\u00e0 di cinque anni, ha ideato \u00abAnsianotansia\u00bb, brand di borse, interamente realizzate da lei, come terapia contro alcuni problemi di ansia sorti attorno all\u2019et\u00e0 di 24 anni.<\/p>\n<p> Ora il suo sogno \u00e8 di farne la sua professione. \u00abSto terminando gli studi universitari \u2013 racconta -, sono all\u2019ultimo anno della Magistrale in Architettura, a Milano, ma questo progetto delle borse, nato un po\u2019 per caso, <strong class=\"nero\">mi piacerebbe che si concretizzasse ancor di pi\u00f9<\/strong>. La creativit\u00e0 \u00e8 sempre stata nelle mie corde e si \u00e8 dimostrata un\u2019ancora al quale aggrapparmi e che mi ha salvata in un momento particolare e difficile della mia vita\u00bb. <\/p>\n<blockquote class=\"quote-article-cont\">\n<p>\u00abVorrei proporre dei laboratori e workshop per creare una rete con questa mia \u201cterapia\u201d, con l\u2019auspicio che la creativit\u00e0 possa essere per tanti un alleato ed un\u2019arma contro il disagio\u00bb<\/p>\n<\/blockquote>\n<p><a data-title=\"Alcuno modelli di \u00abAnsianotansia\u00bb\" href=\"https:\/\/storage.ecodibergamo.it\/media\/photologue\/2026\/5\/10\/photos\/borse-antidoto-allo-stress-emma-crea-ansianotansia_cad010a0-4c79-11f1-8ff3-b29b100ed173_1080_1440.jpeg\" title=\"Alcuno modelli di \u00abAnsianotansia\u00bb\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n<img decoding=\"async\" alt=\"Borse antidoto allo stress, Emma crea \u00abAnsianotansia\u00bb\" class=\"lozad\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/borse-antidoto-allo-stress-emma-crea-ansianotansia_cad010a0-4c79-11f1-8ff3-b29b100ed173_1080_1440_v3.jpeg\" title=\"Alcuno modelli di \u00abAnsianotansia\u00bb\" width=\"100%\"\/><br \/>\n<\/a><\/p>\n<p>        Alcuno modelli di \u00abAnsianotansia\u00bb<\/p>\n<p><a data-title=\"Emma Reina con una sua borsa mini\" href=\"https:\/\/storage.ecodibergamo.it\/media\/photologue\/2026\/5\/10\/photos\/borse-antidoto-allo-stress-emma-crea-ansianotansia_cb34653c-4c79-11f1-8ff3-b29b100ed173_1080_1440.jpeg\" title=\"Emma Reina con una sua borsa mini\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n<img decoding=\"async\" alt=\"Borse antidoto allo stress, Emma crea \u00abAnsianotansia\u00bb\" class=\"lozad\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/borse-antidoto-allo-stress-emma-crea-ansianotansia_cb34653c-4c79-11f1-8ff3-b29b100ed173_1080_1440_v3.jpeg\" title=\"Emma Reina con una sua borsa mini\" width=\"100%\"\/><br \/>\n<\/a><\/p>\n<p>        Emma Reina con una sua borsa mini<\/p>\n<p><a data-title=\"Emma Reina al lavoro\" href=\"https:\/\/storage.ecodibergamo.it\/media\/photologue\/2026\/5\/10\/photos\/borse-antidoto-allo-stress-emma-crea-ansianotansia_cb970b1a-4c79-11f1-8ff3-b29b100ed173_1080_1440.jpeg\" title=\"Emma Reina al lavoro\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n<img decoding=\"async\" alt=\"Borse antidoto allo stress, Emma crea \u00abAnsianotansia\u00bb\" class=\"lozad\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/borse-antidoto-allo-stress-emma-crea-ansianotansia_cb970b1a-4c79-11f1-8ff3-b29b100ed173_1080_1440_v3.jpeg\" title=\"Emma Reina al lavoro\" width=\"100%\"\/><br \/>\n<\/a><\/p>\n<p>        Emma Reina al lavoro<\/p>\n<p><a data-title=\"Gli schizzi delle borse\" href=\"https:\/\/storage.ecodibergamo.it\/media\/photologue\/2026\/5\/10\/photos\/borse-antidoto-allo-stress-emma-crea-ansianotansia_cc1c135a-4c79-11f1-8ff3-b29b100ed173_1920_2580.jpeg\" title=\"Gli schizzi delle borse\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n<img decoding=\"async\" alt=\"Borse antidoto allo stress, Emma crea \u00abAnsianotansia\u00bb\" class=\"lozad\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/borse-antidoto-allo-stress-emma-crea-ansianotansia_cc1c135a-4c79-11f1-8ff3-b29b100ed173_1920_2580_v3.jpeg\" title=\"Gli schizzi delle borse\" width=\"100%\"\/><br \/>\n<\/a><\/p>\n<p>        Gli schizzi delle borse<\/p>\n<p>E racconta: \u00abHo iniziato a vivere una situazione di malessere e, oltre all\u2019aiuto di professionisti, <strong class=\"nero\">ho trovato giovamento progettando le mie borse\u00bb. <\/strong> <br \/>Prima i bozzetti disegnati tra le pagine di un taccuino, poi la realizzazione con diversi materiali: cotone, raso, stoffe varie, e corde intrecciate con la tecnica del macram\u00e8. Ogni creazione \u00e8 unica e studiata ad hoc: non esistono standard o linee da seguire, ma pezzi unici dando ampio spazio allo stimolo del momento. \u00abUn accessorio che non punta solo alla bellezza ed all\u2019estetica, ma vuole raccontare qualcosa ed essere portatore di valori e storie\u00bb.<\/p>\n<p><a data-title=\"Al lavoro su una borsa\" href=\"https:\/\/storage.ecodibergamo.it\/media\/photologue\/2026\/5\/10\/photos\/borse-antidoto-allo-stress-emma-crea-ansianotansia_cca42e34-4c79-11f1-8ff3-b29b100ed173_1920_1440.jpeg\" title=\"Al lavoro su una borsa\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n<img decoding=\"async\" alt=\"Borse antidoto allo stress, Emma crea \u00abAnsianotansia\u00bb\" class=\"lozad\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/borse-antidoto-allo-stress-emma-crea-ansianotansia_cca42e34-4c79-11f1-8ff3-b29b100ed173_1920_1440_v3.jpeg\" title=\"Al lavoro su una borsa\" width=\"100%\"\/><br \/>\n<\/a><\/p>\n<p>        Al lavoro su una borsa<\/p>\n<p>\u00abHo sempre adorato le borse \u2013 confessa -. Inizialmente non avevo pensato di \u201ccondividerle\u201d, ma poi sono arrivate le prime richieste anche da alcuni pop-up di Milano\u00bb.<br \/><strong class=\"nero\">Borse che possono fare tendenza ma con una finalit\u00e0 pi\u00f9 alta<\/strong>: \u00abCondividere la mia esperienza, perch\u00e9 possa essere d\u2019aiuto a coetanei e persone che stanno vivendo le mie stesse difficolt\u00e0. Vorrei proporre dei laboratori e workshop per creare una rete con questa mia \u201cterapia\u201d, con l\u2019auspicio che la creativit\u00e0 possa essere per tanti un alleato ed un\u2019arma contro il disagio. \u201cAnsiaisnotansia\u201d vorrei che fosse una comunit\u00e0 che abbraccia l\u2019imperfezione, celebra la resilienza ed invita a trasformare le sfide in opportunit\u00e0 per crescere e connettersi\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"La creativit\u00e0, una cura per l\u2019anima di Emma Reina. Classe 2000, nata a Milano ma cresciuta a Bergamo&hellip;\n","protected":false},"author":3,"featured_media":484209,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[1615,1644,1612,98312,269495,203,1909,204,1537,90,89,105757,3112,2259,2258],"class_list":{"0":"post-484208","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-intrattenimento","8":"tag-arte","9":"tag-cultura","10":"tag-design","11":"tag-ecodibergamo-it","12":"tag-emma-reina","13":"tag-entertainment","14":"tag-famiglia","15":"tag-intrattenimento","16":"tag-it","17":"tag-italia","18":"tag-italy","19":"tag-michela-gaiti","20":"tag-moda","21":"tag-questioni-sociali-generico","22":"tag-sociale"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116552534290027398","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/484208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=484208"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/484208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/484209"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=484208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=484208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=484208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}