{"id":484644,"date":"2026-05-11T06:09:13","date_gmt":"2026-05-11T06:09:13","guid":{"rendered":"https:\/\/www.europesays.com\/it\/484644\/"},"modified":"2026-05-11T06:09:13","modified_gmt":"2026-05-11T06:09:13","slug":"guerra-iran-usa-le-news-di-oggi-su-trump-lo-stretto-di-hormuz-e-crisi-in-medio-oriente-diretta","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/484644\/","title":{"rendered":"Guerra Iran USA, le news di oggi su Trump, lo stretto di Hormuz e crisi in Medio Oriente. DIRETTA"},"content":{"rendered":"<p>L&#8217;Iran respinge il piano Usa. \\&#8221;Non mi piace la loro risposta, \u00e8 inappropriata\\&#8221;, commenta Trump. Gli Usa monitorano le scorte residue di uranio arricchito di Teheran e \\&#8221;a un certo punto\\&#8221; se ne impadroniranno, aggiunge il tycoon. Il petrolio guadagna oltre il 3% col mancato accordo. Le autorit\u00e0 iraniane hanno intanto rilasciato su cauzione Mohammadi: la premio Nobel per la pace \u00e8 stata trasferita a Teheran per cure mediche. Oggi a Bruxelles riunione dei ministri degli Affari esteri Ue. Parigi e Londra presiederanno domani una riunione di quelli della Difesa su Hormuz.\\n\\n<\/p>\n<p><strong>Gli approfondimenti:<\/strong><\/p>\n<p>\\n\\n<\/p>\n<p><strong>Per ricevere le notizie di Sky TG24:<\/strong><\/p>\n<p>\\n<\/p>\n<ul>\\n  <\/p>\n<li>Il canale Whatsapp di Sky TG24 (<a href=\"\\&quot;https:\/\/whatsapp.com\/channel\/0029VaDyGIp90x2wDXgUnV2j\\&quot;\" data-intcmp-qp=\"\\&quot;skytg24_liveblog_interlink_text\\&quot;\">clicca qui<\/a>)<\/li>\n<p>\\n  <\/p>\n<li>Le notizie audio con i titoli del tg (<a href=\"\\&quot;https:\/\/tg24.sky.it\/cronaca\/approfondimenti\/audio-news-sky-tg24.html\\&quot;\" data-intcmp=\"\\&quot;skytg24_liveblog_interlink_text\\&quot;\">clicca qui<\/a>)<\/li>\n<p>\\n<\/ul>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;20bb917c-eb18-4023-b3c9-630aa17fe644&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}}],&#8221;posts&#8221;:[{&#8220;timestamp&#8221;:&#8221;2026-05-11T06:06:06.694Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T08:06:06+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Prezzo petrolio in rialzo, Wti scambiato a 99,77 dollari&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Prezzo del petrolio in rialzo questa mattina sui mercati delle materie \u00a0prime: il Wti con consegna a giugno passa di mano a 99,77 dollari al \u00a0barile con una crescita del 4,56% mentre il Brent con consegna a luglio \u00e8 \u00a0scambiato a 105,31 dollari al barile con un avanzamento del 3,97%.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;deb6de7c-cef1-4c2c-8422-eb71802298ee&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:59:19.807Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:59:19+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Iran, media: \\&#8221;Uomo giustiziato per spionaggio a favore Cia e Mossad\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>L&#8217;Iran ha giustiziato un uomo condannato per spionaggio a favore del \u00a0Mossad e dei servizi segreti statunitensi. Lo riferisce l&#8217;agenzia di \u00a0stampa Mizan, organo ufficiale della magistratura iraniana, precisando \u00a0che Erfan Shakourzadeh aveva lavorato presso un&#8217;organizzazione \u00a0scientifica coinvolta in attivit\u00e0 satellitari e che aveva condiviso \u00a0informazioni scientifiche classificate con servizi di intelligence \u00a0stranieri. L&#8217;organizzazione per i diritti umani Iran Human Rights \u00a0Society ha aggiunto che Shakourzadeh, laureato in ingegneria \u00a0aerospaziale di 29 anni, era stato arrestato l&#8217;anno scorso e costretto a \u00a0confessare.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;70f27441-b2dd-4314-a209-bd589b504218&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:53:34.545Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:53:34+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Kallas: \\&#8221;Sosteniamo soluzione diplomatica tra Iran e Usa\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>In Medio oriente la prima cosa \\&#8221;e&#8217; fermare la\\nguerra, aprire lo Stretto di Hormuz e li&#8217;, ovviamente, gli americani e\\nl&#8217;Iran stanno negoziando tra loro, e li&#8217; possiamo solo sostenerli, ma non\\npossiamo davvero raggiungere un accordo per loro conto\\&#8221;. Lo ha detto\\nl&#8217;Alto rappresentante per la Politica Estera, Kaja Kallas, arrivando al\\nConsiglio esteri. \\&#8221;Come ho detto, sosteniamo la soluzione diplomatica e\\nsiamo in contatto anche con i Paesi che mediano tra le due parti. &#8211; ha\\nproseguito Kallas &#8211; Siamo inoltre in contatto con i Paesi del Golfo,\\nperche&#8217; condividiamo le stesse preoccupazioni\\&#8221;.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;bb064b3a-ae4b-4db6-b6d2-2aed4e8002aa&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:49:23.756Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:49:23+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Kallas: \\&#8221;Mi aspetto intesa su sanzioni coloni violenti\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>\\&#8221;Mi aspetto un accordo politico sulle\\nsanzioni contro i coloni violenti; spero che riusciremo ad arrivarci\\&#8221;. Lo\\nha dichiarato l&#8217;Alta rappresentante dell&#8217;Ue per la Politica estera, Kaja\\nKallas, all&#8217;arrivo al Consiglio Esteri Ue. Le sanzioni nei confronti dei\\ncoloni violenti israeliani sono state a lungo bloccate al veto\\ndell&#8217;Ungheria di Viktor Orban. \\&#8221;Ci sono delle proposte avanzate dagli\\nStati membri, ma richiedono, come sapete, l&#8217;unanimita&#8217; o una maggioranza\\nqualificata in casi in cui in realta&#8217; non la abbiamo\\&#8221;, ha poi aggiunto.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;1dcff812-acaf-4b21-bc5e-7622160cde8a&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:49:01.506Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:49:01+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Netanyahu: \\&#8221;Israele protegge i cristiani, abbiamo radici comuni\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Il Primo ministro israeliano Benjamin Netanyahu ha minimizzato una serie di recenti episodi anticristiani, definendoli \\&#8221;aberrazioni\\&#8221; isolate i cui responsabili sono stati puniti o in cui l&#8217;errore \u00e8 stato corretto, esaltando i valori e la storia condivisi da Israele con i cristiani e il cristianesimo. L&#8217;ha fatto durante un&#8217;intervista a \\&#8221;60 Minutes\\&#8221; della Cbs. Lo riporta il Times of Israel specificando che le dichiarazioni compaiono in una parte dell&#8217;intervista non registrata, che non \u00e8 stata trasmessa ed \u00e8 riportata solo nella trascrizione integrale della Cbs.\u00a0\u00a0\u00a0\u00a0Nell&#8217;intervista \u00e8 stato chiesto al premier di commentare una serie di recenti incidenti che hanno danneggiato le relazioni di Israele con i cristiani, tra cui il divieto di accesso alla Chiesa del Santo Sepolcro per il Patriarca latino di Gerusalemme a Pasqua, la distruzione di una statua di Ges\u00f9 da parte di un soldato delle Forze di Difesa Israeliane in Libano e l&#8217;attacco a una suora nella Citt\u00e0 Vecchia di Gerusalemme.\u00a0\u00a0\u00a0\u00a0\u00a0Davanti all&#8217;ipotesi che gli episodi celino un trend di ostilit\u00e0 verso i cristiani, Netanyahu ha risposto definendolo una \\&#8221;incredibile invenzione\\&#8221;. Il premier ha affermato che Israele \u00e8 l&#8217;unico luogo nella regione in cui i cristiani hanno \\&#8221;prosperato\\&#8221;, mentre nei Paesi arabi confinanti \\&#8221;sono stati schiacciati, repressi, a volte massacrati\\&#8221;.\u00a0\u00a0\\&#8221;Israele \u00e8 l&#8217;unico Paese in Medio Oriente che protegge i cristiani, che li valorizza, che abbraccia il cristianesimo. Abbiamo radici comuni. Le apprezziamo. C&#8217;\u00e8 un tentativo non solo di falsificare la nostra storia comune, ma anche di falsificare gli eventi attuali, di aggrapparsi a queste, sapete, queste aberrazioni, e fingere che questa sia la politica israeliana. \u00c8 ridicolo\\&#8221;, ha concluso.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;978d0998-bd17-4002-a6d7-e52b63028b0c&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:41:12.201Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:41:12+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Iran, la premio Nobel Narges Mohammadi trasferita in ospedale&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Concessa la sospensione della pena su cauzione a seguito del \u00a0parere dell&#8217;Organizzazione di Medicina legale, composta da \u00a0professionisti nominati dal governo di Teheran. Ma per la Fondazione \u00a0dell&#8217;avvocata iraniana bisogna \\&#8221;garantire che non torni mai pi\u00f9 in \u00a0carcere per scontare i 18 anni rimanenti della sua pena\\&#8221;.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;da70de60-926a-4957-812d-73334d634f9c&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;Iran, la premio Nobel Narges Mohammadi trasferita in ospedale&#8221;,&#8221;url&#8221;:&#8221;https:\/\/tg24.sky.it\/mondo\/2026\/05\/10\/iran-narges-mohammadi-ricovero-ospedale&#8221;,&#8221;imageSrc&#8221;:&#8221;https:\/\/tg24.sky.it\/assets\/images\/f8b1c28635eed736d919308ec055e5842cc64661\/skytg24\/it\/mondo\/2026\/05\/10\/iran-narges-mohammadi-ricovero-ospedale\/narges-mohammadi-ansa.jpg?im=Resize,width=1218&#8243;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:37:35.045Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:37:35+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Netanyahu: \\&#8221;Su errori 7\/10 mia responsabilit\u00e0, ma anche di tutti gli altri vertici\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Il Primo Ministro israeliano Benjamin Netanyahu ha riconosciuto di \u00a0avere una certa responsabilit\u00e0 per gli errori che hanno permesso \u00a0\u00a0l&#8217;attacco di Hamas del 7 ottobre 2023, ma afferma che \\&#8221;tutti\\&#8221;, dal \u00a0vertice alla base, ne sono responsabili e che il \\&#8221;vero problema\\&#8221; \u00e8 ci\u00f2 \u00a0che \u00e8 accaduto dopo quell&#8217;attacco e non ci\u00f2 che lo ha preceduto. In \u00a0un&#8217;intervista con \\&#8221;60 Minutes\\&#8221; della CBS su come mai tutti coloro che \u00a0erano responsabili della sicurezza durante l&#8217;attentato si siano dimessi o \u00a0siano stati licenziati tranne lui, Netanyahu afferma che alcuni se ne \u00a0sono andati perch\u00e9 il loro mandato era scaduto e che solo uno o due \u00a0\\&#8221;hanno affermato di assumersi la responsabilit\u00e0, ma non \u00e8 chiaro qual \u00e8 \u00a0la loro responsabilit\u00e0\\&#8221;.\\nLe \u00a0osservazioni di Neatanyahu sono state espresse &#8216;off the record&#8217; e \u00a0appaiono solo nella trascrizione integrale della CBS. \\&#8221;Analizziamo la \u00a0gerarchia politica, quella militare, quella della sicurezza. Analizziamo \u00a0tutti, perch\u00e9 ognuno ha una qualche responsabilit\u00e0. S\u00ec, dall&#8217;alto, dal \u00a0primo ministro in gi\u00f9\\&#8221;, afferma, ribadendo poi la sua proposta di \u00a0istituire una commissione d&#8217;inchiesta di nomina politica anzich\u00e9 una \u00a0commissione d&#8217;inchiesta statale, la pi\u00f9 alta forma di inchiesta del \u00a0paese, che si \u00e8 rifiutato di creare.\\nI \u00a0sondaggi hanno costantemente indicato che una netta maggioranza di \u00a0israeliani sostiene una commissione statale, e lo stesso Netanyahu si \u00a0era espresso a favore di un&#8217;inchiesta sulla condotta del precedente \u00a0governo nel 2022. Tuttavia, il governo si \u00e8 ostinatamente rifiutato di \u00a0prenderla in considerazione e non ha ancora approvato alcuna inchiesta, a \u00a0oltre due anni e mezzo dal giorno pi\u00f9 tragico per gli ebrei \u00a0dall&#8217;Olocausto. \\&#8221;Ma credo &#8211; ha aggiunto Netanyahu &#8211; che il vero punto \u00a0sia che questo vale fino al 7 ottobre. E dopo? Era chiaramente mia \u00a0responsabilit\u00e0 liberare Israele da questo orribile cappio di morte che \u00a0gli iraniani ci avevano teso. E lo abbiamo fatto, sistematicamente e con \u00a0grande risolutezza, intervenendo su ognuno di questi sette fronti, uno \u00a0dopo l&#8217;altro, e respingendo l&#8217;ondata di terrore\\&#8221;.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;7072ad12-18bd-4305-8b18-4adc282012b3&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:37:00.620Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:37:00+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Wall Sreet: future in lieve calo, Dow Jones -0,21% &#8220;,&#8221;content&#8221;:&#8221;<\/p>\n<p>A Wall Street i future cedono leggermente dopo\\nche Donald Trump ha definito \\&#8221;inaccettabile\\&#8221; la risposta dell&#8217;Iran\\nall&#8217;ultima proposta di pace statunitense. Le due parti mantengono il\\nfragile cessate il fuoco ma cresce il timore che il conflitto si\\nprotragga, lasciando paralizzato il traffico a Hormuz. Oggi c&#8217;e&#8217; attesa\\nper l&#8217;ufficializzazione della nomina di Kevin Warsh a governatore Fed, un\\nvoto il cui esito appare scontato dopo l&#8217;ok della commissione bancaria.\\nPoi giovedi&#8217; ci sara&#8217; il passaggio di consegne tra Powell e Warsh. Il Dow\\nJones cede lo 0,21%, S&amp;P -0,12%, il Nasdaq sulla parita&#8217;.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;6b5db5fb-f266-4556-b967-9f23b36fe302&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:31:00.388Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:31:00+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Libano: raid israeliani su Kfar Tebnit e Choukine &#8220;,&#8221;content&#8221;:&#8221;<\/p>\n<p>L&#8217;aviazione israeliana sta bombardando le citta&#8217;\\nlibanesi di Kfar Tebnit e Choukine. Lo riporta Al Jazeera.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;2758471c-c40a-4990-b098-4e4cb095661a&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:29:21.730Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:29:21+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Oro: in calo per rinnovati timori d&#8217;inflazione&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>I prezzi dell&#8217;oro sono scesi luned\u00ec, poich\u00e9 la mancanza di progressi nei \u00a0negoziati di pace tra Stati Uniti e Iran ha spinto al rialzo i prezzi \u00a0del petrolio, alimentando i timori che un&#8217;inflazione elevata possa \u00a0mantenere i tassi di interesse alti pi\u00f9 a lungo.\u00a0\\nL&#8217;oro \u00a0spot \u00e8 sceso dello 0,6% a 4.684,32 dollari l&#8217;oncia, alle 02:23 Gmt. I \u00a0future sull&#8217;oro statunitensi con consegna a giugno hanno perso lo 0,8% a \u00a04.692,70 dollari.\\nL&#8217;argento \u00a0spot \u00e8 salito dello 0,7% a 80,88 dollari l&#8217;oncia, il platino \u00e8 sceso \u00a0dello 0,6% a 2.042,71 dollari e il palladio ha perso lo 0,4% a 1.484,99 \u00a0dollari.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;acb348a2-0945-4863-bf77-934bc7d542d5&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:28:47.958Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:28:47+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Borse asiatiche: listini contrastati, corre Seul +5% &#8220;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Stamane in Asia i listini sono contrastati in un\\ncontesto di rinnovata escalation delle tensioni tra Stati Uniti e Iran,\\nmentre cresce l&#8217;attesa per l&#8217;incontro tra Trump e Xi. Avanza Seul del 5%\\nsulla scia dei guadagni dell&#8217;intelligenza artificiale e dei chip. Il\\nNikkei arretra a -0,3%, mentre i mercati scommettono che un cambio di\\nrotta piu&#8217; restrittivo da parte della Boj e l&#8217;appoggio del Segretario del\\nTesoro statunitense Scott Bessent possano dare maggiore efficacia agli\\ninterventi di acquisto di yen e contribuire a rallentare il deprezzamento\\ndella valuta in difficolta&#8217;. In Cina Shanghai sale quasi dell&#8217;1% e Hong\\nKong perde lo 0,3% dopo che i prezzi alla produzione del Dragone sono\\nsaliti oltre le attese, al top degli ultimi 45 mesi ad aprile, mentre\\nanche l&#8217;inflazione al consumo ha accelerato, spinta dai costi energetici\\nglobali elevati.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;8294da7c-dbf9-4d61-a9fb-6d588542337b&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:28:11.328Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:28:11+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Pena morte per attentatori 7 ottobre, oggi voto a Knesset &#8220;,&#8221;content&#8221;:&#8221;<\/p>\n<p>La Knesset, il Parlamento israeliano, oggi votera&#8217;\\nil disegno di legge presentato dal ministro della Giustizia israeliano,\\nYariv Levin, per imporre la pena di morte e celebrare processi pubblici\\nper i palestinesi coinvolti negli attentati del 7 ottobre 2023. Lo\\nriportano i media israeliani. Il testo e&#8217; sostenuto sia dal partito di\\ngoverno che dall&#8217;opposizione. \\&#8221;Poiche&#8217; esiste la piena autorita&#8217; per\\nimporre la pena di morte, qualsiasi condanna, se inflitta, verra&#8217; anche\\neseguita\\&#8221;, ha dichiarato Levin. \\&#8221;Stiamo parlando di centinaia di imputati.\\nSono fiducioso che l&#8217;esercito abbia assunto la guida nell&#8217;attuazione delle\\nprocedure e sapra&#8217; come fare tutto il necessario affinche&#8217; i processi\\npossano iniziare presto\\&#8221;, ha aggiunto il ministro. Il presidente della\\nCommissione costituzionale della Knesset, Simcha Rothman, ha affermato che\\nla legge invia \\&#8221;un messaggio chiaro ai nemici di Israele: lo Stato di\\nIsraele non restera&#8217; a guardare, non dimentichera&#8217; ne&#8217; perdonera&#8217; e\\npunira&#8217; con le pene piu&#8217; severe previste dalla legge, inclusa la pena di\\nmorte\\&#8221;.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;46392276-bf8c-44a8-b434-d065a4559865&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:27:33.905Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:27:33+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Idf: riservista ucciso in un attacco di Hezbollah nel sud del Libano&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Un riservista delle Forze di Difesa Israeliane (Idf) \u00e8 \u00a0rimasto ucciso ieri in un attacco di droni di Hezbollah nel nord di \u00a0Israele, secondo quanto annunciato oggi dall&#8217;esercito.Il soldato \u00a0deceduto \u00e8 stato identificato come il sergente maggiore riservista \u00a0Alexander Glovanyov, 47 anni, autista del 6924mo Battaglione del Centro \u00a0Trasporti, originario di Petah Tikva.Secondo l&#8217;indagine dell&#8217;esercito \u00a0alcuni droni esplosivi lanciati da Hezbollah hanno colpito il territorio \u00a0israeliano, vicino al confine con il Libano, e uno dei droni ha ucciso \u00a0il riservista.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;4b3afcda-fea2-4770-9206-736199bd0bf8&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:18:37.368Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:18:37+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Petrolio: forte rialzo dopo mancato accordo pace, Brent 105&#8243;,&#8221;content&#8221;:&#8221;<\/p>\n<p>I prezzi del petrolio oggi salgono del 4%, con\\nil Brent sopra 105 dollari e il Wti che riavvicina a quota 100 dollari al\\nbarile, dopo che Donald Trump ha definito \\&#8221;inaccettabile\\&#8221; la risposta\\ndell&#8217;Iran all&#8217;ultima proposta di pace statunitense. Cresce il timore che\\nil conflitto si protragga, lasciando paralizzato il traffico a Hormuz.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;9a8be803-b73f-4a7c-9b89-e9145698702e&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:16:49.154Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:16:49+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Iran, la risposta alla proposta Usa sul Wsj: dal nucleare a Hormuz&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>L\u2019Iran ha inviato una risposta di diverse pagine all&#8217;ultima proposta \u00a0degli Stati Uniti per porre fine alla guerra. Secondo quanto riporta il \u00a0Wsj, nella risposta l\u2019Iran ha esposto nel dettaglio le sue richieste con \u00a0diversi punti aperti di divergenza. \u201cTotalmente inaccettabile\u201d, \u00e8 stato \u00a0il commento del presidente Usa Donald Trump. Ecco cosa sappiamo.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;e3e80e3f-6ada-4bf0-bbed-597c161c8957&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;Iran, la risposta alla proposta Usa sul Wsj: dal nucleare a Hormuz&#8221;,&#8221;url&#8221;:&#8221;https:\/\/tg24.sky.it\/mondo\/2026\/05\/10\/guerra-iran-risposta-proposta-usa&#8221;,&#8221;imageSrc&#8221;:&#8221;https:\/\/tg24.sky.it\/assets\/images\/622aa42ea87bc4f0d565149d3a188f7009fdfab8\/skytg24\/it\/mondo\/2026\/04\/26\/guerra-usa-iran-negoziati\/usa_iran_bandiere_ipa.jpg?im=Resize,width=1218&#8243;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:11:49.752Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:11:49+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Vacanze e crisi in Medio Oriente: guida a rimborsi e cancellazioni&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p><strong>La crisi in Medio Oriente sta creando forte incertezza anche nel <\/strong><a href=\"\\&quot;https:\/\/tg24.sky.it\/economia\/2026\/05\/07\/carenza-cherosene-aerei-situazione\\&quot;\" target=\"\\&quot;_self\\&quot;\" rel=\"\\&quot;follow\\&quot;\" data-intcmp=\"\\&quot;skytg24_liveblog_interlink_text\\&quot;\"><strong>settore dei viaggi<\/strong><\/a><strong> e sta modificando le abitudini degli italiani <\/strong>che \u00a0ogni anno, in questo periodo, organizzano le vacanze estive, \u00a0acquistando voli o pacchetti e prenotando alberghi e strutture \u00a0ricettive. A sottolinearlo \u00e8 il Codacons, che per aiutare i cittadini a \u00a0orientarsi tra cancellazioni, rincari e tutele previste dalla legge<strong> ha diffuso una guida con informazioni su diritti, rimborsi, \u00a0risarcimenti e assicurazioni, anche alla luce delle nuove linee guida \u00a0dell\u2019Unione europea sul trasporto aereo.<\/strong><\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;075aef91-832a-4ac2-af3c-ca9fec0acf62&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;Vacanze e crisi in Medio Oriente: guida a rimborsi e cancellazioni&#8221;,&#8221;url&#8221;:&#8221;https:\/\/tg24.sky.it\/economia\/2026\/05\/11\/vacanze-rimborsi-cancellazioni-crisi-medio-oriente&#8221;,&#8221;imageSrc&#8221;:&#8221;https:\/\/tg24.sky.it\/assets\/images\/15f98e3d879281061388621cd484a6c080a5734a\/skytg24\/it\/economia\/2026\/03\/16\/prezzo-voli-pasqua-2026\/01_ipa_prezzo_biglietti_aerei.jpg?im=Resize,width=1218&#8243;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:05:58.140Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:05:58+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Attacchi aerei Israele nel sud del Libano&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>I media israeliani hanno riferito che l&#8217;Idf sta\\nlanciando attacchi aerei e bombardando posizioni nel Libano meridionale,\\naggiungendo che si sono udite esplosioni in Galilea. Nel frattempo,\\nHezbollah ha annunciato di aver preso di mira un contingente israeliano\\nall&#8217;interno di un&#8217;abitazione nella citta&#8217; di Al-Taybeh, nel Libano\\nmeridionale.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;63876466-d77e-4a3b-8a12-598232d8ee6e&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:05:33.537Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:05:33+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Oggi ministri Esteri Ue discutono di sanzioni a coloni &#8220;,&#8221;content&#8221;:&#8221;<\/p>\n<p>I ministri degli Esteri dell&#8217;Unione Europea si\\nriuniranno oggi a Bruxelles per discutere di possibili sanzioni a causa\\ndell&#8217;attivita&#8217; di insediamento israeliana nella Cisgiordania occupata. Si\\nprevede che i colloqui si concentreranno sul raggiungimento di un accordo\\ndi principio sulle misure punitive contro i coloni israeliani. Diversi\\npaesi dell&#8217;UE stanno inoltre esercitando pressioni sulla Commissione\\neuropea affinche&#8217; proponga dazi doganali sulle importazioni di merci\\nprodotte negli insediamenti israeliani nei territori palestinesi.\\nTuttavia, permangono divisioni all&#8217;interno dell&#8217;Unione, con alcuni\\ngoverni, tra cui la Germania, che si oppongono a tali restrizioni\\ncommerciali. La discussione si svolgera&#8217; in concomitanza con una piu&#8217;\\nampia riunione dei ministri degli Esteri, che dovrebbe concentrarsi su\\nnuove sanzioni per le deportazioni e le adozioni forzate di bambini\\nucraini da parte della Russia.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;872fb2dd-dfef-405b-9806-bbcc99c0a4fe&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:05:12.701Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:05:12+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Droni Hezbollah uccidono soldato israeliano &#8220;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Un riservista delle Forze di Difesa Israeliane\\n(IDF) e&#8217; rimasto ucciso ieri in un attacco di droni di Hezbollah nel nord\\ndi Israele. Lo ha annunciato l&#8217;IDF. Il soldato ucciso e&#8217; stato\\nidentificato come il sergente maggiore Alexander Glovanyov, 47 anni,\\nautista del 6924* battaglione del Centro trasporti, originario di Petah\\nTikva. Durante l&#8217;attacco, diversi droni esplosivi lanciati da Hezbollah\\nhanno colpito il territorio israeliano, vicino al confine con il Libano.\\nSecondo un&#8217;indagine delle Forze di Difesa Israeliane (IDF), uno dei droni\\nha ucciso Glovanyov.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;935d4611-6ae9-4eaf-abf5-c429bf0ab616&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:04:34.081Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:04:34+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Iran: nipote Kennedy: \\&#8221;Usa hanno gi\u00e0 perso la guerra\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Jack Schlossberg, nipote del Presidente John F.\\nKennedy e principale candidato alla successione del seggio del deputato\\nnewyorkese uscente Jerry Nadler, ha dichiarato di sostenere un embargo\\nsulle armi contro Israele e ha affermato che gli Stati Uniti \\&#8221;hanno gia&#8217;\\nperso la guerra contro l&#8217;Iran\\&#8221;. Durante un dibattito elettorale pubblico\\ntenutosi presso la Stephen Wise Free Synagogue di Manhattan, Schlossberg,\\nche e&#8217; ebreo da parte di padre, ha affermato che avrebbe votato a favore\\ndella proposta del senatore Bernie Sanders di bloccare il trasferimento a\\nIsraele di bombe e attrezzature militari per un valore di 440 milioni di\\ndollari. Schlossberg ha aggiunto che opporsi alla guerra con l&#8217;Iran\\nsignifica opporsi a qualsiasi finanziamento per essa, ma ha sottolineato\\ndi sostenere comunque il finanziamento del sistema Iron Dome e la\\ndefinizione di Israele come Stato ebraico.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;66bdcf9c-9d73-4247-ac6a-2565b3fc9d8f&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-11T05:04:03.411Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-11T07:04:03+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Iran: richieste di Trump sono \\&#8221;eccessive\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>La rete televisiva statale iraniana PressTV ha\\nannunciato che l&#8217;iniziativa statunitense per porre fine alla guerra e&#8217;\\nstata respinta, in quanto \\&#8221;significherebbe la resa di Teheran alle\\nrichieste eccessive di Trump\\&#8221;.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;f63fa623-6f29-4474-9190-bc35270d1d34&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}}]}&#8221; query='{&#8220;configurationName&#8221;:&#8221;LIVEBLOG_CONTAINER_WIDGET&#8221;,&#8221;liveblogId&#8221;:&#8221;447852e8-c904-4fd4-837d-cce899e90b46&#8243;,&#8221;tenant&#8221;:&#8221;tg24&#8243;,&#8221;limit&#8221;:800}&#8217; config='{&#8220;live&#8221;:true,&#8221;isWebView&#8221;:false,&#8221;postsPerPageMobile&#8221;:10,&#8221;postsPerPageDesktop&#8221;:10}&#8217;&gt;<\/p>\n<p>L&#8217;Iran respinge il piano Usa. &#8220;Non mi piace la loro risposta, \u00e8 inappropriata&#8221;, commenta Trump. Gli Usa monitorano le scorte residue di uranio arricchito di Teheran e &#8220;a un certo punto&#8221; se ne impadroniranno, aggiunge il tycoon. Il petrolio guadagna oltre il 3% col mancato accordo. Le autorit\u00e0 iraniane hanno intanto rilasciato su cauzione Mohammadi: la premio Nobel per la pace \u00e8 stata trasferita a Teheran per cure mediche. Oggi a Bruxelles riunione dei ministri degli Affari esteri Ue. Parigi e Londra presiederanno domani una riunione di quelli della Difesa su Hormuz.<\/p>\n<p><strong>Gli approfondimenti:<\/strong><\/p>\n<p><strong>Per ricevere le notizie di Sky TG24:<\/strong><\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>meno di un minuto fa<\/p>\n<p>Prezzo petrolio in rialzo, Wti scambiato a 99,77 dollari<\/p>\n<p>Prezzo del petrolio in rialzo questa mattina sui mercati delle materie \u00a0prime: il Wti con consegna a giugno passa di mano a 99,77 dollari al \u00a0barile con una crescita del 4,56% mentre il Brent con consegna a luglio \u00e8 \u00a0scambiato a 105,31 dollari al barile con un avanzamento del 3,97%.<\/p>\n<p>6 minuti fa<\/p>\n<p>Iran, media: &#8220;Uomo giustiziato per spionaggio a favore Cia e Mossad&#8221;<\/p>\n<p>L&#8217;Iran ha giustiziato un uomo condannato per spionaggio a favore del \u00a0Mossad e dei servizi segreti statunitensi. Lo riferisce l&#8217;agenzia di \u00a0stampa Mizan, organo ufficiale della magistratura iraniana, precisando \u00a0che Erfan Shakourzadeh aveva lavorato presso un&#8217;organizzazione \u00a0scientifica coinvolta in attivit\u00e0 satellitari e che aveva condiviso \u00a0informazioni scientifiche classificate con servizi di intelligence \u00a0stranieri. L&#8217;organizzazione per i diritti umani Iran Human Rights \u00a0Society ha aggiunto che Shakourzadeh, laureato in ingegneria \u00a0aerospaziale di 29 anni, era stato arrestato l&#8217;anno scorso e costretto a \u00a0confessare.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>12 minuti fa<\/p>\n<p>Kallas: &#8220;Sosteniamo soluzione diplomatica tra Iran e Usa&#8221;<\/p>\n<p>In Medio oriente la prima cosa &#8220;e&#8217; fermare la<br \/>\nguerra, aprire lo Stretto di Hormuz e li&#8217;, ovviamente, gli americani e<br \/>\nl&#8217;Iran stanno negoziando tra loro, e li&#8217; possiamo solo sostenerli, ma non<br \/>\npossiamo davvero raggiungere un accordo per loro conto&#8221;. Lo ha detto<br \/>\nl&#8217;Alto rappresentante per la Politica Estera, Kaja Kallas, arrivando al<br \/>\nConsiglio esteri. &#8220;Come ho detto, sosteniamo la soluzione diplomatica e<br \/>\nsiamo in contatto anche con i Paesi che mediano tra le due parti. &#8211; ha<br \/>\nproseguito Kallas &#8211; Siamo inoltre in contatto con i Paesi del Golfo,<br \/>\nperche&#8217; condividiamo le stesse preoccupazioni&#8221;.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>16 minuti fa<\/p>\n<p>Kallas: &#8220;Mi aspetto intesa su sanzioni coloni violenti&#8221;<\/p>\n<p>&#8220;Mi aspetto un accordo politico sulle<br \/>\nsanzioni contro i coloni violenti; spero che riusciremo ad arrivarci&#8221;. Lo<br \/>\nha dichiarato l&#8217;Alta rappresentante dell&#8217;Ue per la Politica estera, Kaja<br \/>\nKallas, all&#8217;arrivo al Consiglio Esteri Ue. Le sanzioni nei confronti dei<br \/>\ncoloni violenti israeliani sono state a lungo bloccate al veto<br \/>\ndell&#8217;Ungheria di Viktor Orban. &#8220;Ci sono delle proposte avanzate dagli<br \/>\nStati membri, ma richiedono, come sapete, l&#8217;unanimita&#8217; o una maggioranza<br \/>\nqualificata in casi in cui in realta&#8217; non la abbiamo&#8221;, ha poi aggiunto.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>17 minuti fa<\/p>\n<p>Netanyahu: &#8220;Israele protegge i cristiani, abbiamo radici comuni&#8221;<\/p>\n<p>Il Primo ministro israeliano Benjamin Netanyahu ha minimizzato una serie di recenti episodi anticristiani, definendoli &#8220;aberrazioni&#8221; isolate i cui responsabili sono stati puniti o in cui l&#8217;errore \u00e8 stato corretto, esaltando i valori e la storia condivisi da Israele con i cristiani e il cristianesimo. L&#8217;ha fatto durante un&#8217;intervista a &#8220;60 Minutes&#8221; della Cbs. Lo riporta il Times of Israel specificando che le dichiarazioni compaiono in una parte dell&#8217;intervista non registrata, che non \u00e8 stata trasmessa ed \u00e8 riportata solo nella trascrizione integrale della Cbs.\u00a0\u00a0\u00a0\u00a0Nell&#8217;intervista \u00e8 stato chiesto al premier di commentare una serie di recenti incidenti che hanno danneggiato le relazioni di Israele con i cristiani, tra cui il divieto di accesso alla Chiesa del Santo Sepolcro per il Patriarca latino di Gerusalemme a Pasqua, la distruzione di una statua di Ges\u00f9 da parte di un soldato delle Forze di Difesa Israeliane in Libano e l&#8217;attacco a una suora nella Citt\u00e0 Vecchia di Gerusalemme.\u00a0\u00a0\u00a0\u00a0\u00a0Davanti all&#8217;ipotesi che gli episodi celino un trend di ostilit\u00e0 verso i cristiani, Netanyahu ha risposto definendolo una &#8220;incredibile invenzione&#8221;. Il premier ha affermato che Israele \u00e8 l&#8217;unico luogo nella regione in cui i cristiani hanno &#8220;prosperato&#8221;, mentre nei Paesi arabi confinanti &#8220;sono stati schiacciati, repressi, a volte massacrati&#8221;.\u00a0\u00a0&#8220;Israele \u00e8 l&#8217;unico Paese in Medio Oriente che protegge i cristiani, che li valorizza, che abbraccia il cristianesimo. Abbiamo radici comuni. Le apprezziamo. C&#8217;\u00e8 un tentativo non solo di falsificare la nostra storia comune, ma anche di falsificare gli eventi attuali, di aggrapparsi a queste, sapete, queste aberrazioni, e fingere che questa sia la politica israeliana. \u00c8 ridicolo&#8221;, ha concluso.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>24 minuti fa<\/p>\n<p>Iran, la premio Nobel Narges Mohammadi trasferita in ospedale<\/p>\n<p>Concessa la sospensione della pena su cauzione a seguito del \u00a0parere dell&#8217;Organizzazione di Medicina legale, composta da \u00a0professionisti nominati dal governo di Teheran. Ma per la Fondazione \u00a0dell&#8217;avvocata iraniana bisogna &#8220;garantire che non torni mai pi\u00f9 in \u00a0carcere per scontare i 18 anni rimanenti della sua pena&#8221;.<\/p>\n<p><a href=\"https:\/\/tg24.sky.it\/mondo\/2026\/05\/10\/iran-narges-mohammadi-ricovero-ospedale\" title=\"Iran, la premio Nobel Narges Mohammadi trasferita in ospedale\" class=\"lvbg-post-link\" data-intcmp=\"skytg24_liveblog_liveblog-preview_null\" data-analytics-element=\"liveblog-preview\" rel=\"nofollow noopener\" target=\"_blank\"><img alt=\"Iran, la premio Nobel Narges Mohammadi trasferita in ospedale\" style=\"opacity:0;transition:opacity 0.3s\" class=\"lvbg-post-link__image\"\/>Iran, la premio Nobel Narges Mohammadi trasferita in ospedaleVai al contenuto <\/a><\/p>\n<p>28 minuti fa<\/p>\n<p>Netanyahu: &#8220;Su errori 7\/10 mia responsabilit\u00e0, ma anche di tutti gli altri vertici&#8221;<\/p>\n<p>Il Primo Ministro israeliano Benjamin Netanyahu ha riconosciuto di \u00a0avere una certa responsabilit\u00e0 per gli errori che hanno permesso \u00a0\u00a0l&#8217;attacco di Hamas del 7 ottobre 2023, ma afferma che &#8220;tutti&#8221;, dal \u00a0vertice alla base, ne sono responsabili e che il &#8220;vero problema&#8221; \u00e8 ci\u00f2 \u00a0che \u00e8 accaduto dopo quell&#8217;attacco e non ci\u00f2 che lo ha preceduto. In \u00a0un&#8217;intervista con &#8220;60 Minutes&#8221; della CBS su come mai tutti coloro che \u00a0erano responsabili della sicurezza durante l&#8217;attentato si siano dimessi o \u00a0siano stati licenziati tranne lui, Netanyahu afferma che alcuni se ne \u00a0sono andati perch\u00e9 il loro mandato era scaduto e che solo uno o due \u00a0&#8220;hanno affermato di assumersi la responsabilit\u00e0, ma non \u00e8 chiaro qual \u00e8 \u00a0la loro responsabilit\u00e0&#8221;.<br \/>\nLe \u00a0osservazioni di Neatanyahu sono state espresse &#8216;off the record&#8217; e \u00a0appaiono solo nella trascrizione integrale della CBS. &#8220;Analizziamo la \u00a0gerarchia politica, quella militare, quella della sicurezza. Analizziamo \u00a0tutti, perch\u00e9 ognuno ha una qualche responsabilit\u00e0. S\u00ec, dall&#8217;alto, dal \u00a0primo ministro in gi\u00f9&#8221;, afferma, ribadendo poi la sua proposta di \u00a0istituire una commissione d&#8217;inchiesta di nomina politica anzich\u00e9 una \u00a0commissione d&#8217;inchiesta statale, la pi\u00f9 alta forma di inchiesta del \u00a0paese, che si \u00e8 rifiutato di creare.<br \/>\nI \u00a0sondaggi hanno costantemente indicato che una netta maggioranza di \u00a0israeliani sostiene una commissione statale, e lo stesso Netanyahu si \u00a0era espresso a favore di un&#8217;inchiesta sulla condotta del precedente \u00a0governo nel 2022. Tuttavia, il governo si \u00e8 ostinatamente rifiutato di \u00a0prenderla in considerazione e non ha ancora approvato alcuna inchiesta, a \u00a0oltre due anni e mezzo dal giorno pi\u00f9 tragico per gli ebrei \u00a0dall&#8217;Olocausto. &#8220;Ma credo &#8211; ha aggiunto Netanyahu &#8211; che il vero punto \u00a0sia che questo vale fino al 7 ottobre. E dopo? Era chiaramente mia \u00a0responsabilit\u00e0 liberare Israele da questo orribile cappio di morte che \u00a0gli iraniani ci avevano teso. E lo abbiamo fatto, sistematicamente e con \u00a0grande risolutezza, intervenendo su ognuno di questi sette fronti, uno \u00a0dopo l&#8217;altro, e respingendo l&#8217;ondata di terrore&#8221;.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>29 minuti fa<\/p>\n<p>Wall Sreet: future in lieve calo, Dow Jones -0,21% <\/p>\n<p>A Wall Street i future cedono leggermente dopo<br \/>\nche Donald Trump ha definito &#8220;inaccettabile&#8221; la risposta dell&#8217;Iran<br \/>\nall&#8217;ultima proposta di pace statunitense. Le due parti mantengono il<br \/>\nfragile cessate il fuoco ma cresce il timore che il conflitto si<br \/>\nprotragga, lasciando paralizzato il traffico a Hormuz. Oggi c&#8217;e&#8217; attesa<br \/>\nper l&#8217;ufficializzazione della nomina di Kevin Warsh a governatore Fed, un<br \/>\nvoto il cui esito appare scontato dopo l&#8217;ok della commissione bancaria.<br \/>\nPoi giovedi&#8217; ci sara&#8217; il passaggio di consegne tra Powell e Warsh. Il Dow<br \/>\nJones cede lo 0,21%, S&amp;P -0,12%, il Nasdaq sulla parita&#8217;.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>35 minuti fa<\/p>\n<p>Libano: raid israeliani su Kfar Tebnit e Choukine <\/p>\n<p>L&#8217;aviazione israeliana sta bombardando le citta&#8217;<br \/>\nlibanesi di Kfar Tebnit e Choukine. Lo riporta Al Jazeera.<\/p>\n<p>36 minuti fa<\/p>\n<p>Oro: in calo per rinnovati timori d&#8217;inflazione<\/p>\n<p>I prezzi dell&#8217;oro sono scesi luned\u00ec, poich\u00e9 la mancanza di progressi nei \u00a0negoziati di pace tra Stati Uniti e Iran ha spinto al rialzo i prezzi \u00a0del petrolio, alimentando i timori che un&#8217;inflazione elevata possa \u00a0mantenere i tassi di interesse alti pi\u00f9 a lungo.\u00a0<br \/>\nL&#8217;oro \u00a0spot \u00e8 sceso dello 0,6% a 4.684,32 dollari l&#8217;oncia, alle 02:23 Gmt. I \u00a0future sull&#8217;oro statunitensi con consegna a giugno hanno perso lo 0,8% a \u00a04.692,70 dollari.<br \/>\nL&#8217;argento \u00a0spot \u00e8 salito dello 0,7% a 80,88 dollari l&#8217;oncia, il platino \u00e8 sceso \u00a0dello 0,6% a 2.042,71 dollari e il palladio ha perso lo 0,4% a 1.484,99 \u00a0dollari.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>37 minuti fa<\/p>\n<p>Borse asiatiche: listini contrastati, corre Seul +5% <\/p>\n<p>Stamane in Asia i listini sono contrastati in un<br \/>\ncontesto di rinnovata escalation delle tensioni tra Stati Uniti e Iran,<br \/>\nmentre cresce l&#8217;attesa per l&#8217;incontro tra Trump e Xi. Avanza Seul del 5%<br \/>\nsulla scia dei guadagni dell&#8217;intelligenza artificiale e dei chip. Il<br \/>\nNikkei arretra a -0,3%, mentre i mercati scommettono che un cambio di<br \/>\nrotta piu&#8217; restrittivo da parte della Boj e l&#8217;appoggio del Segretario del<br \/>\nTesoro statunitense Scott Bessent possano dare maggiore efficacia agli<br \/>\ninterventi di acquisto di yen e contribuire a rallentare il deprezzamento<br \/>\ndella valuta in difficolta&#8217;. In Cina Shanghai sale quasi dell&#8217;1% e Hong<br \/>\nKong perde lo 0,3% dopo che i prezzi alla produzione del Dragone sono<br \/>\nsaliti oltre le attese, al top degli ultimi 45 mesi ad aprile, mentre<br \/>\nanche l&#8217;inflazione al consumo ha accelerato, spinta dai costi energetici<br \/>\nglobali elevati.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>37 minuti fa<\/p>\n<p>Pena morte per attentatori 7 ottobre, oggi voto a Knesset <\/p>\n<p>La Knesset, il Parlamento israeliano, oggi votera&#8217;<br \/>\nil disegno di legge presentato dal ministro della Giustizia israeliano,<br \/>\nYariv Levin, per imporre la pena di morte e celebrare processi pubblici<br \/>\nper i palestinesi coinvolti negli attentati del 7 ottobre 2023. Lo<br \/>\nriportano i media israeliani. Il testo e&#8217; sostenuto sia dal partito di<br \/>\ngoverno che dall&#8217;opposizione. &#8220;Poiche&#8217; esiste la piena autorita&#8217; per<br \/>\nimporre la pena di morte, qualsiasi condanna, se inflitta, verra&#8217; anche<br \/>\neseguita&#8221;, ha dichiarato Levin. &#8220;Stiamo parlando di centinaia di imputati.<br \/>\nSono fiducioso che l&#8217;esercito abbia assunto la guida nell&#8217;attuazione delle<br \/>\nprocedure e sapra&#8217; come fare tutto il necessario affinche&#8217; i processi<br \/>\npossano iniziare presto&#8221;, ha aggiunto il ministro. Il presidente della<br \/>\nCommissione costituzionale della Knesset, Simcha Rothman, ha affermato che<br \/>\nla legge invia &#8220;un messaggio chiaro ai nemici di Israele: lo Stato di<br \/>\nIsraele non restera&#8217; a guardare, non dimentichera&#8217; ne&#8217; perdonera&#8217; e<br \/>\npunira&#8217; con le pene piu&#8217; severe previste dalla legge, inclusa la pena di<br \/>\nmorte&#8221;.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>38 minuti fa<\/p>\n<p>Idf: riservista ucciso in un attacco di Hezbollah nel sud del Libano<\/p>\n<p>Un riservista delle Forze di Difesa Israeliane (Idf) \u00e8 \u00a0rimasto ucciso ieri in un attacco di droni di Hezbollah nel nord di \u00a0Israele, secondo quanto annunciato oggi dall&#8217;esercito.Il soldato \u00a0deceduto \u00e8 stato identificato come il sergente maggiore riservista \u00a0Alexander Glovanyov, 47 anni, autista del 6924mo Battaglione del Centro \u00a0Trasporti, originario di Petah Tikva.Secondo l&#8217;indagine dell&#8217;esercito \u00a0alcuni droni esplosivi lanciati da Hezbollah hanno colpito il territorio \u00a0israeliano, vicino al confine con il Libano, e uno dei droni ha ucciso \u00a0il riservista.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>47 minuti fa<\/p>\n<p>Petrolio: forte rialzo dopo mancato accordo pace, Brent 105<\/p>\n<p>I prezzi del petrolio oggi salgono del 4%, con<br \/>\nil Brent sopra 105 dollari e il Wti che riavvicina a quota 100 dollari al<br \/>\nbarile, dopo che Donald Trump ha definito &#8220;inaccettabile&#8221; la risposta<br \/>\ndell&#8217;Iran all&#8217;ultima proposta di pace statunitense. Cresce il timore che<br \/>\nil conflitto si protragga, lasciando paralizzato il traffico a Hormuz.<\/p>\n<p>49 minuti fa<\/p>\n<p>Iran, la risposta alla proposta Usa sul Wsj: dal nucleare a Hormuz<\/p>\n<p>L\u2019Iran ha inviato una risposta di diverse pagine all&#8217;ultima proposta \u00a0degli Stati Uniti per porre fine alla guerra. Secondo quanto riporta il \u00a0Wsj, nella risposta l\u2019Iran ha esposto nel dettaglio le sue richieste con \u00a0diversi punti aperti di divergenza. \u201cTotalmente inaccettabile\u201d, \u00e8 stato \u00a0il commento del presidente Usa Donald Trump. Ecco cosa sappiamo.<\/p>\n<p><a href=\"https:\/\/tg24.sky.it\/mondo\/2026\/05\/10\/guerra-iran-risposta-proposta-usa\" title=\"Iran, la risposta alla proposta Usa sul Wsj: dal nucleare a Hormuz\" class=\"lvbg-post-link\" data-intcmp=\"skytg24_liveblog_liveblog-preview_null\" data-analytics-element=\"liveblog-preview\" rel=\"nofollow noopener\" target=\"_blank\"><img alt=\"Iran, la risposta alla proposta Usa sul Wsj: dal nucleare a Hormuz\" style=\"opacity:0;transition:opacity 0.3s\" class=\"lvbg-post-link__image\"\/>Iran, la risposta alla proposta Usa sul Wsj: dal nucleare a HormuzVai al contenuto <\/a><\/p>\n<p>54 minuti fa<\/p>\n<p>Vacanze e crisi in Medio Oriente: guida a rimborsi e cancellazioni<\/p>\n<p><strong>La crisi in Medio Oriente sta creando forte incertezza anche nel <\/strong><a href=\"https:\/\/tg24.sky.it\/economia\/2026\/05\/07\/carenza-cherosene-aerei-situazione\" target=\"_self\" rel=\"follow nofollow noopener\" data-intcmp=\"skytg24_liveblog_interlink_text\"><strong>settore dei viaggi<\/strong><\/a><strong> e sta modificando le abitudini degli italiani <\/strong>che \u00a0ogni anno, in questo periodo, organizzano le vacanze estive, \u00a0acquistando voli o pacchetti e prenotando alberghi e strutture \u00a0ricettive. A sottolinearlo \u00e8 il Codacons, che per aiutare i cittadini a \u00a0orientarsi tra cancellazioni, rincari e tutele previste dalla legge<strong> ha diffuso una guida con informazioni su diritti, rimborsi, \u00a0risarcimenti e assicurazioni, anche alla luce delle nuove linee guida \u00a0dell\u2019Unione europea sul trasporto aereo.<\/strong><\/p>\n<p><a href=\"https:\/\/tg24.sky.it\/economia\/2026\/05\/11\/vacanze-rimborsi-cancellazioni-crisi-medio-oriente\" title=\"Vacanze e crisi in Medio Oriente: guida a rimborsi e cancellazioni\" class=\"lvbg-post-link\" data-intcmp=\"skytg24_liveblog_liveblog-preview_null\" data-analytics-element=\"liveblog-preview\" rel=\"nofollow noopener\" target=\"_blank\"><img alt=\"Vacanze e crisi in Medio Oriente: guida a rimborsi e cancellazioni\" style=\"opacity:0;transition:opacity 0.3s\" class=\"lvbg-post-link__image\"\/>Vacanze e crisi in Medio Oriente: guida a rimborsi e cancellazioniVai al contenuto <\/a><\/p>\n<p>07:05<\/p>\n<p>Attacchi aerei Israele nel sud del Libano<\/p>\n<p>I media israeliani hanno riferito che l&#8217;Idf sta<br \/>\nlanciando attacchi aerei e bombardando posizioni nel Libano meridionale,<br \/>\naggiungendo che si sono udite esplosioni in Galilea. Nel frattempo,<br \/>\nHezbollah ha annunciato di aver preso di mira un contingente israeliano<br \/>\nall&#8217;interno di un&#8217;abitazione nella citta&#8217; di Al-Taybeh, nel Libano<br \/>\nmeridionale.<\/p>\n<p>07:05<\/p>\n<p>Oggi ministri Esteri Ue discutono di sanzioni a coloni <\/p>\n<p>I ministri degli Esteri dell&#8217;Unione Europea si<br \/>\nriuniranno oggi a Bruxelles per discutere di possibili sanzioni a causa<br \/>\ndell&#8217;attivita&#8217; di insediamento israeliana nella Cisgiordania occupata. Si<br \/>\nprevede che i colloqui si concentreranno sul raggiungimento di un accordo<br \/>\ndi principio sulle misure punitive contro i coloni israeliani. Diversi<br \/>\npaesi dell&#8217;UE stanno inoltre esercitando pressioni sulla Commissione<br \/>\neuropea affinche&#8217; proponga dazi doganali sulle importazioni di merci<br \/>\nprodotte negli insediamenti israeliani nei territori palestinesi.<br \/>\nTuttavia, permangono divisioni all&#8217;interno dell&#8217;Unione, con alcuni<br \/>\ngoverni, tra cui la Germania, che si oppongono a tali restrizioni<br \/>\ncommerciali. La discussione si svolgera&#8217; in concomitanza con una piu&#8217;<br \/>\nampia riunione dei ministri degli Esteri, che dovrebbe concentrarsi su<br \/>\nnuove sanzioni per le deportazioni e le adozioni forzate di bambini<br \/>\nucraini da parte della Russia.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>07:05<\/p>\n<p>Droni Hezbollah uccidono soldato israeliano <\/p>\n<p>Un riservista delle Forze di Difesa Israeliane<br \/>\n(IDF) e&#8217; rimasto ucciso ieri in un attacco di droni di Hezbollah nel nord<br \/>\ndi Israele. Lo ha annunciato l&#8217;IDF. Il soldato ucciso e&#8217; stato<br \/>\nidentificato come il sergente maggiore Alexander Glovanyov, 47 anni,<br \/>\nautista del 6924* battaglione del Centro trasporti, originario di Petah<br \/>\nTikva. Durante l&#8217;attacco, diversi droni esplosivi lanciati da Hezbollah<br \/>\nhanno colpito il territorio israeliano, vicino al confine con il Libano.<br \/>\nSecondo un&#8217;indagine delle Forze di Difesa Israeliane (IDF), uno dei droni<br \/>\nha ucciso Glovanyov.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>07:04<\/p>\n<p>Iran: nipote Kennedy: &#8220;Usa hanno gi\u00e0 perso la guerra&#8221;<\/p>\n<p>Jack Schlossberg, nipote del Presidente John F.<br \/>\nKennedy e principale candidato alla successione del seggio del deputato<br \/>\nnewyorkese uscente Jerry Nadler, ha dichiarato di sostenere un embargo<br \/>\nsulle armi contro Israele e ha affermato che gli Stati Uniti &#8220;hanno gia&#8217;<br \/>\nperso la guerra contro l&#8217;Iran&#8221;. Durante un dibattito elettorale pubblico<br \/>\ntenutosi presso la Stephen Wise Free Synagogue di Manhattan, Schlossberg,<br \/>\nche e&#8217; ebreo da parte di padre, ha affermato che avrebbe votato a favore<br \/>\ndella proposta del senatore Bernie Sanders di bloccare il trasferimento a<br \/>\nIsraele di bombe e attrezzature militari per un valore di 440 milioni di<br \/>\ndollari. Schlossberg ha aggiunto che opporsi alla guerra con l&#8217;Iran<br \/>\nsignifica opporsi a qualsiasi finanziamento per essa, ma ha sottolineato<br \/>\ndi sostenere comunque il finanziamento del sistema Iron Dome e la<br \/>\ndefinizione di Israele come Stato ebraico.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>07:04<\/p>\n<p>Iran: richieste di Trump sono &#8220;eccessive&#8221;<\/p>\n<p>La rete televisiva statale iraniana PressTV ha<br \/>\nannunciato che l&#8217;iniziativa statunitense per porre fine alla guerra e&#8217;<br \/>\nstata respinta, in quanto &#8220;significherebbe la resa di Teheran alle<br \/>\nrichieste eccessive di Trump&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"L&#8217;Iran respinge il piano Usa. \\&#8221;Non mi piace la loro risposta, \u00e8 inappropriata\\&#8221;, commenta Trump. Gli Usa monitorano&hellip;\n","protected":false},"author":3,"featured_media":484645,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[14,164,165,206,77,764,72,166,7,15,11,167,12,168,410,161,162,163],"class_list":{"0":"post-484644","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-cronaca","9":"tag-dal-mondo","10":"tag-dalmondo","11":"tag-donald-trump","12":"tag-guerra","13":"tag-iran","14":"tag-israele","15":"tag-mondo","16":"tag-news","17":"tag-notizie","18":"tag-ultime-notizie","19":"tag-ultime-notizie-di-mondo","20":"tag-ultimenotizie","21":"tag-ultimenotiziedimondo","22":"tag-usa","23":"tag-world","24":"tag-world-news","25":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116554456668081348","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/484644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=484644"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/484644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/484645"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=484644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=484644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=484644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}