{"id":485170,"date":"2026-05-11T13:50:18","date_gmt":"2026-05-11T13:50:18","guid":{"rendered":"https:\/\/www.europesays.com\/it\/485170\/"},"modified":"2026-05-11T13:50:18","modified_gmt":"2026-05-11T13:50:18","slug":"lavvocato-dei-poggi-i-pm-si-sono-accaniti-per-sconfessare-la-condanna-di-stasi-i-legali-di-alberto-tante-nuove-prove-sulla-sua-innocenza-acceleriamo-sulla-revisione","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/485170\/","title":{"rendered":"L&#8217;avvocato dei Poggi: \u00abI pm si sono accaniti per sconfessare la condanna di Stasi\u00bb. I legali di Alberto: \u00abTante nuove prove sulla sua innocenza, acceleriamo sulla revisione\u00bb"},"content":{"rendered":"<p>    di<br \/>\n    Redazione Milano<\/p>\n<p class=\"summary-art is-line-h-12\">Garlasco, Tizzoni, legale dei genitori di Chiara: \u00abLa loro collaborazione \u00e8 sempre stata massima, oggi sono dispiaciuti e demoralizzati\u00bb. I difensori dell&#8217;ex fidanzato: \u00abLa sentenza di condanna \u00e8 stata disintegrata\u00bb<\/p>\n<p class=\"chapter-paragraph\"><b>\u00abLa Procura di Pavia si \u00e8 accanita<\/b> nel cercare di sconfessare quanto gi\u00e0 stabilito nelle aule di giustizia\u00bb con<a href=\"https:\/\/milano.corriere.it\/notizie\/cronaca\/26_maggio_11\/garlasco-alberto-stasi-chiara-sempio-marco-poggi-video-d319be06-e557-4432-a443-49124779fxlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\"> la condanna definitiva di Alberto Stasi,<\/a> accusato di aver ucciso l&#8217;allora fidanzata Chiara Poggi. \u00bb. Cos\u00ec <b>Gian Luigi Tizzoni<\/b>, il legale della famiglia Poggi, commenta gli atti depositati dai pm pavesi nell&#8217;ambito dell&#8217;indagine, chiusa da poco, <a href=\"https:\/\/milano.corriere.it\/notizie\/cronaca\/26_maggio_11\/garlasco-quei-45-mila-euro-in-contanti-che-la-famiglia-sempio-consegno-ai-tre-avvocati-prima-che-andrea-venisse-indagato-06080f9d-85c9-4d9e-97b6-230bac8bfxlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">a carico di Andrea Sempio<\/a>. E la Procura si sarebbe accanita, aggiunge l\u2019avvocato,\u00a0<b>\u00abanche in maniera abbastanza deludente<\/b> perch\u00e9 quello che leggo \u00e8 un lavoro che pu\u00f2 sembrare mastodontico ma che non va a colpire i punti centrali della vicenda. <b>Opposta la posizione degli avvocati di Stasi <\/b>che ora chiedono di\u00a0\u00abaccelerare i tempi della revisione della condanna di Alberto\u00bb<\/p>\n<p class=\"chapter-paragraph\">\u00abLa casa dei Poggi \u00e8 sempre stata messa a disposizione, la collaborazione \u00e8 sempre stata massima e doverosa \u2013 continua Tizzoni -. Diciamo che<b> oggi sono particolarmente dispiaciuti e demoralizzati <\/b>nell&#8217;aver visto come questa inchiesta \u00e8 stata unidirezionale, volta sostanzialmente a sconfessare <b>la responsabilit\u00e0 di Stasi che \u00e8 stata accertata <\/b>nel Palazzo di Giustizia di Milano, poi in Cassazione, confermata dalla Corte europea dei diritti dell&#8217;uomo\u00bb.    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\">Il legale respinge l&#8217;idea degli investigatori di presunte commistione con i Sempio. \u00ab<b>Se delle famiglie si conoscono, continuano a conoscersi <\/b>e continueranno a conoscersi. Qui tutte le volte ci si dimentica che sono persone che vivono in un piccolo paese, che avevano delle frequentazioni anche contingenti, non mi risulta che si siano frequentati durante quest&#8217;indagine\u00bb aggiunge.  \u00ab<b>Abbiamo sempre avuto interlocuzioni chiare e trasparenti <\/b>con tutte le autorit\u00e0 giudiziarie, inclusa la Procura di Pavia alla quale, quando c&#8217;\u00e8 stato detto di fornire della documentazione, abbiamo prontamente risposto\u00bb.<\/p>\n<p class=\"chapter-paragraph\"><b>\u00abNon vedo spazio per una revisione<\/b> &#8211; sostiene Tizzoni -, n\u00e9 dalla consulenza medico-legale della dottoressa Cattaneo, n\u00e9 dalla consulenza informatica di Dal Checco, n\u00e9 dalle consulenze del Ris per quanto riguarda la Bpa\u00bb, ovvero l&#8217;analisi delle tracce ematiche sulla scena del crimine per ricostruire la dinamica dell&#8217;omicidio di Chiara. <b>\u00abL&#8217;unico tema che rimane da esplorare, e a me dispiace, \u00e8 l&#8217;impronta 33\u00bb<\/b>, quella sul muro delle scale che portavano in cantina, in fondo alle quali \u00e8 stato trovato il corpo senza vita della ragazza. \u00abAvevo chiesto di sottoporla in incidente probatorio\u00bb, che si \u00e8 tenuto l&#8217;anno scorso, \u00abe di farla verificare da un perito terzo\u00bb, cosa che per\u00f2 non \u00e8 avvenuta. \u00abIl nostro dattiloscopista e, leggo negli atti, anche altri, hanno forti perplessit\u00e0 che l&#8217;impronta 33 abbia<b> il numero di minuzie<\/b> per essere attribuita non a Sempio ma a chicchessia\u00bb.<\/p>\n<p class=\"chapter-paragraph\">Opposta la lettura degli avvocati di Stasi,<b> Giada Bocellari e Antonio De Rensis<\/b>, secondo i quali la Procura di Pavia, \u00abmediante un&#8217;imponente ed articolata attivit\u00e0 investigativa, ha letteralmente disintegrato la sentenza di condanna di Alberto, evidenziando una serie lunghissima di nuovi elementi di prova che dimostrano l&#8217;assoluta innocenza\u00bb. Per loro quello che \u00e8 emerso \u00e8 <b>un \u00abquadro\u00bb, che \u00abcoinvolge numerosi soggetti\u00bb, \u00abspaventoso e gravissimo<\/b>, avendo fortemente inciso, tra l&#8217;altro, sul diritto di Stasi di dimostrare prima la propria innocenza\u00bb. Quadro che sar\u00f2 \u00aboggetto di separata valutazione\u00bb.<b> La difesa ora lavora \u00abper accelerare i tempi della revisione\u00bb.<\/b><\/p>\n<p class=\"is-mr-t-20 is-mr-b-20\"><b><br \/>\n                    <a href=\"https:\/\/milano.corriere.it\/?intcmp=Notizielocali_nd_010623_corriere_ss_milano\" target=\"_blank\" rel=\"nofollow noopener\">Vai a tutte le notizie di Milano<\/a><br \/>\n            <\/b><\/p>\n<p class=\"chapter-paragraph\"><b><a href=\"https:\/\/www.corriere.it\/newsletter\/?theme=41&amp;intcmp=IIIcolonna_NL_CorMilano\" target=\"_blank\" rel=\"nofollow noopener\">Iscriviti alla newsletter di Corriere Milano<\/a><\/b><\/p>\n<p class=\"is-last-update\" datetime=\"2026-05-11T14:39:15+02:00\">11 maggio 2026 ( modifica il 11 maggio 2026 | 14:39)<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Redazione Milano Garlasco, Tizzoni, legale dei genitori di Chiara: \u00abLa loro collaborazione \u00e8 sempre stata massima, oggi&hellip;\n","protected":false},"author":3,"featured_media":485171,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[122443,10920,168799,270038,1237,1493,7401,2550,183849,1239,40,2567,270039,805,91262,270040,11074,14,93,94,243465,85648,270041,485,3596,950,140852,1537,90,89,8428,15262,1219,1354,270042,7,15,8141,11065,282,38979,11602,270037,11066,11072,96632,11,84,91,12,85,92],"class_list":{"0":"post-485170","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-italia","8":"tag-accanita","9":"tag-accelerare","10":"tag-accelerare-tempi","11":"tag-accelerare-tempi-revisione","12":"tag-aggiunge","13":"tag-alberto","14":"tag-atti","15":"tag-avvocati","16":"tag-avvocati-stasi","17":"tag-avvocato","18":"tag-chiara","19":"tag-collaborazione","20":"tag-collaborazione-massima","21":"tag-condanna","22":"tag-condanna-alberto","23":"tag-conoscersi","24":"tag-consulenza","25":"tag-cronaca","26":"tag-cronaca-italiana","27":"tag-cronacaitaliana","28":"tag-demoralizzati","29":"tag-dispiaciuti","30":"tag-dispiaciuti-demoralizzati","31":"tag-giustizia","32":"tag-impronta","33":"tag-indagine","34":"tag-innocenza","35":"tag-it","36":"tag-italia","37":"tag-italy","38":"tag-legale","39":"tag-leggo","40":"tag-massima","41":"tag-ne","42":"tag-ne-consulenza","43":"tag-news","44":"tag-notizie","45":"tag-pavia","46":"tag-poggi","47":"tag-procura","48":"tag-procura-pavia","49":"tag-revisione","50":"tag-sconfessare","51":"tag-sempio","52":"tag-stasi","53":"tag-tizzoni","54":"tag-ultime-notizie","55":"tag-ultime-notizie-e-news-di-oggi","56":"tag-ultime-notizie-italia","57":"tag-ultimenotizie","58":"tag-ultimenotizieenewsdioggi","59":"tag-ultimenotizieitalia"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/485170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=485170"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/485170\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/485171"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=485170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=485170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=485170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}