{"id":487231,"date":"2026-05-12T19:26:16","date_gmt":"2026-05-12T19:26:16","guid":{"rendered":"https:\/\/www.europesays.com\/it\/487231\/"},"modified":"2026-05-12T19:26:16","modified_gmt":"2026-05-12T19:26:16","slug":"colpo-dante-maddox-chiuso-ora-scatta-la-corsa-al-prestito","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/487231\/","title":{"rendered":"colpo Dante Maddox chiuso. Ora scatta la corsa al prestito"},"content":{"rendered":"<p> 4<\/p>\n<p>L\u2019Olimpia Milano non guarda solo al presente, ma lavora incessantemente per mettere al sicuro i talenti del futuro: secondo quanto riportato da RealOlimpiaMilano, il club meneghino ha praticamente definito l\u2019accordo per l\u2019acquisto di <strong>Dante Maddox<\/strong>, esplosivo esterno classe 2002 originario di Chicago. <a href=\"https:\/\/www.nbapassion.com\/lega-basket-a\/olimpia-milano-occhi-su-washington-in-caso-di-partenza-di-brooks-319848\/\" id=\"https:\/\/www.nbapassion.com\/lega-basket-a\/olimpia-milano-occhi-su-washington-in-caso-di-partenza-di-brooks-319848\/\" rel=\"nofollow noopener\" target=\"_blank\">La dirigenza biancorossa<\/a> \u00e8 gi\u00e0 alle prese con lo scambio dei documenti: il giocatore sar\u00e0 di propriet\u00e0 dell\u2019EA7 a partire dalla prossima estate.<\/p>\n<p>Un dominatore in Belgio: i numeri dell\u2019operazione Maddox per l\u2019Olimpia Milano<\/p>\n<p>Il DS Daniele Baiesi ha deciso di muoversi con largo anticipo, bruciando la concorrenza per mettere le mani su uno degli handler pi\u00f9 intriganti dell\u2019intero panorama europeo. Maddox si \u00e8 messo in mostra quest\u2019anno nella BNXT League (il campionato belga-olandese) con la maglia dell\u2019<strong>Okapi Aalst<\/strong>, registrando numeri semplicemente irreali: <strong>24.9 punti, 5.8 rimbalzi e 2.6 assist<\/strong> di media a partita. \u00c8 vero che nelle ultimissime uscite stagionali il suo rendimento offensivo ha subito una lieve flessione (4 punti contro Limburg e 17 nel recente successo contro Leeuwarden), ma il quadro generale resta quello di una regular season da assoluto dominatore. Con il terzo posto blindato in classifica, dal 15 maggio <strong>Maddox<\/strong> sar\u00e0 impegnato nei playoff belgi contro il <strong>Kang Roes<\/strong>: l\u2019ultimo atto della sua avventura prima del grande salto nel basket che conta.<\/p>\n<p>Nonostante l\u2019investimento importante, il futuro immediato di <strong>Dante<\/strong> <strong>Maddox<\/strong> non sar\u00e0 sul parquet del Forum. La strategia <strong>dell\u2019Olimpia<\/strong> <strong>Milano<\/strong> \u00e8 definita: blindare il cartellino del talento di <strong>Chicago<\/strong> e girarlo immediatamente in prestito, per permettergli di confrontarsi con un livello superiore mantenendo un alto minutaggio e responsabilit\u00e0 importanti. La corsa per aggiudicarsi l\u2019americano \u00e8 gi\u00e0 nel vivo. In questo momento, la favorita indiscussa sembra essere il <strong>Derthona Basket<\/strong>: la dirigenza piemontese si \u00e8 mossa concretamente e ha gi\u00e0 incontrato il giocatore per illustrargli il progetto. La partita, per\u00f2, non \u00e8 ancora chiusa. In <strong>LBA<\/strong> resta alla finestra la <strong>Pallacanestro Reggiana<\/strong>, sempre molto attenta ai giovani talenti, mentre dall\u2019estero si registra il forte interesse dei francesi del <strong>JL Bourg<\/strong>, pronti a inserirsi per strappare il prestito <strong>all\u2019Olimpia<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"4 L\u2019Olimpia Milano non guarda solo al presente, ma lavora incessantemente per mettere al sicuro i talenti del&hellip;\n","protected":false},"author":3,"featured_media":487232,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1453],"tags":[1756,1757,1537,90,89,1868,5874,245,244],"class_list":{"0":"post-487231","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-basket","8":"tag-basket","9":"tag-basketball","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-lba","14":"tag-olimpia-milano","15":"tag-sport","16":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116563252712267699","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=487231"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487231\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/487232"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=487231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=487231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=487231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}