{"id":487263,"date":"2026-05-12T19:54:12","date_gmt":"2026-05-12T19:54:12","guid":{"rendered":"https:\/\/www.europesays.com\/it\/487263\/"},"modified":"2026-05-12T19:54:12","modified_gmt":"2026-05-12T19:54:12","slug":"reginaldo-intervista-la-mia-lite-con-conte","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/487263\/","title":{"rendered":"Reginaldo intervista: &#8220;La mia lite con Conte&#8221;"},"content":{"rendered":"<p>                                Il brasiliano, che a 43 anni ancora non ha appeso le scarpe al chiodo, e le accuse di &#8216;bella vita&#8217;: &#8220;A Siena pensavamo pi\u00f9 al marted\u00ec con Antonio che alle uscite in discoteca&#8221;<\/p>\n<p>\n                                                                    Alessandra Vaccaro\n                            <\/p>\n<p>                    12 maggio 2026 (modifica alle 21:05)  &#8211; NAPOLI<\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cSono cresciuto con le videocassette di Ronaldo\u201d, confessa commosso Reginaldo. Con gli occhi lucidi, la voce rotta e la nostalgia di quelle immagini che, da bambino, deve aver imparato a memoria come le tabelline. Del resto, per un ragazzino brasiliano che sogna di fare il calciatore \u00e8 un passaggio necessario. Reginaldo Ferreira da Silva li ha fatti tutti gli step per arrivare nell\u2019Olimpo dei grandi. Da piccolo andava a Rio de Janeiro solo per vedere gli allenamenti del Fenomeno. \u00c8 arrivato in Italia a 16 anni, prendendosi ben presto la scena, sia sui quotidiani sportivi, che sulle copertine dei settimanali. Dall\u2019interesse del Mourinho del Triplete, al fuori rosa con Conte al Siena. Regi, per gli amici, a 43 anni, non ha alcuna intenzione di attaccare le scarpette al chiodo: con l\u2019umilt\u00e0 e la professionalit\u00e0 di sempre continua a giocare nelle categorie inferiori.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Che cos\u2019\u00e8 per te Ronaldo?\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cViene subito dopo Ges\u00f9 Cristo. Da piccolo andavo a Rio de Janeiro per vedere i suoi allenamenti. \u00c8 uno dei giocatori pi\u00f9 forti della storia. Appena torner\u00f2 in Brasile andr\u00f2 a trovarlo\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Neanche tu eri cos\u00ec male, ti ha cercato Mourinho nell\u2019Inter del Triplete\u2026\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cEro al Siena e feci una partita straordinaria all\u2019andata contro l\u2019Inter a San Siro, feci due assist, davvero una partita bellissima. A fine gara venne Maicon a parlarmi e mi disse \u2018Mourinho ti sta seguendo da tre mesi, continuer\u00e0 a farlo, mi raccomando fai il bravo\u2019. Io ho vissuto il calcio sempre allo stesso modo, non dovevo cambiare perch\u00e9 mi stava seguendo l\u2019Inter, se dovevo essere un giocatore dell\u2019Inter dovevo restare Reginaldo. Ho continuato a fare le stesse cose. Certo, mi fece molto piacere sapere dell\u2019interessamento di una squadra blasonata come l\u2019Inter\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Hai avuto anche modo di conoscere mister Capello.\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cCapello \u00e8 un perfezionista, anche se ha quasi 80 anni. Recentemente siamo andati in Polonia a fare questa partita con la nazionale brasiliana, era lui il nostro allenatore. Ronaldinho non si \u00e8 presentato alla riunione e il mister \u00e8 andato in escandescenza, ha detto subito, \u2018Ronaldinho non deve giocare\u2019. Quando sono arrivate le telecamere per fare le riprese nello spogliatoio, Capello ha mandato via tutti, anche se era una partita per divertirci. La cosa che mi ha colpito di pi\u00f9 \u00e8 stato il momento della lavagnetta. Capello ha alzato il primo foglio e non c\u2019era la formazione, c\u2019era scritto solo \u2018Non mi piace perdere\u2019.&#8221;<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Stessa mentalit\u00e0 di Conte. \u00c8 vero che allenatori cos\u00ec ti allungano la carriera?\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cConte, se lo segui anche a livello atletico ti migliora tanto. Ti fa lavorare, arrivi a fare 90 minuti e non sentirli, sempre se riesci a non farti male. Io 43 anni ho ancora la mentalit\u00e0 di andare al campo ogni giorno, anche se si tratta di prima o seconda categoria, lo faccio sempre da professionista. \u00c8 una mentalit\u00e0 che il mister ci ha inculcato cos\u00ec come altri allenatori, ma Conte pi\u00f9 di tutti. Con il mister se dovevi fare un lavoro aerobico di 50 metri di campo in 10 secondi, lui stava l\u00ec a controllare se arrivavi preciso, non potevi arrivare n\u00e9 a 11 n\u00e9 a 9, \u00e8 fatto cos\u00ec. Questa \u00e8 la sua forza\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Conte, nei primi mesi al Napoli, sembrava non apprezzasse i giocatori di fantasia come Neres\u2026\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cA Conte piacciono i giocatori di qualit\u00e0 per\u00f2 devono dare ci\u00f2 che vuole lui, cio\u00e8 la fase difensiva. Io a Siena ho fatto l\u2019esterno ma anche la prima punta, all\u2019occorrenza. Con gli allenatori che ho avuto prima di Conte potevo fare anche una corsa in meno all\u2019indietro, invece con lui no. Mi diceva \u2018mi devi fare 65 minuti, devi fare avanti e indietro, e devi fare la differenza in fase offensiva\u2019. Lo sta facendo anche un po\u2019 Politano, anche se con lui ha cambiato modo di giocare. Io credo che Politano in un 4-3-3 pu\u00f2 fare la differenza in fase offensiva, per\u00f2 il mister lo sta utilizzando in un altro modo\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Conte non \u00e8 lo stesso di Siena\u2026\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cIl mister \u00e8 cambiato tanto nel corso del tempo. Dopo il Siena \u00e8 andato ad allenare la Juve e ha vinto, poi \u00e8 andato al Chelsea e si \u00e8 trovato di fronte giocatori come Hazard, Pedro. Ha dovuto cambiare pelle anche a seconda della situazione. Fare l\u2019allenatore non \u00e8 facile. Conte nel Napoli ha tanti giocatori forti. Deve fare delle scelte, tenere fuori De Bruyne e far giocare McTominay, o far giocare tutti e quattro insieme, ad esempio. L\u2019allenatore paga sempre perch\u00e9 non accontenta tutti. Quando ha avuto tutti disponibili li ha messi in campo contemporaneamente e l\u2019intuizione non ha avuto la fortuna che si aspettava. Conte nel suo piccolo ha provato ad accontentare tutti, ma non \u00e8 riuscito a fare il calcio che voleva, anche per gli infortuni\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Perch\u00e9 Conte ti mise fuori rosa al Siena?\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cQuell\u2019anno tornai dalle vacanze il giorno preciso che aveva deciso il mister, cosa che non avevo mai fatto nelle altre stagioni, proprio per affrontare al meglio il richiamo di preparazione a Messina. Feci 22 ore di volo, con vari scali da 6 ore, avevo il sediolino dell\u2019aereo ancora sulla schiena e il giorno dopo mi fece fare un allenamento aerobico. Ricordo, come se fosse ieri, che dovetti fare tre blocchi di lavoro da 7 minuti che erano qualcosa di impressionante e alla fine dissi \u201cMister basta non ce la faccio pi\u00f9\u201d e lui mi rispose che mancavano ancora tre blocchi. Io dissi \u201cMister mi sto stirando\u201d. Allora Conte mi disse di chiamare il mio procuratore per andar via da Siena perch\u00e9 non avevo voglia. A quella frase mi part\u00ec l\u2019embolo e gli risposi in maniera concitata \u201cCome fai a dire che non ho voglia?\u201d. Quando rispondi male a Conte, lui va fuori di testa. Pensavo che chiedendogli scusa sarebbe passato tutto. Invece io mi ritrovai ad allenarmi da solo, di pomeriggio. Non potevo andare neanche in pullman con gli altri, andavo in macchina col team manager. Se la leg\u00f2 proprio al dito. Mi fece fare una settimana fuori rosa a Messina, un\u2019altra a Siena e poi mi rimise dentro\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>I compagni di squadra ti diedero una mano?\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cCalai\u00f2, Del Grosso, Portanova, Vergassola mi diedero un grande aiuto quando Conte mi mise fuori. Sono arrivato in Italia a 16 anni da solo, a 13 anni sono andato a giocare a Rio, a 450 km da casa mia. Gli anni di Siena erano anni importanti per me, venivo da Parma, dove avevo vissuto anche una retrocessione\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Quella litigata ti \u00e8 servita?\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201c\u00c8 servita a tutto il gruppo. Vergassola, Portanova che andavano spesso a parlare col mister, approfittarono della mia situazione per fargli presente altri problemi. Gli dissero, ad esempio, che alcuni giocatori pi\u00f9 giovani come Immobile, avevano paura di allenarsi. Poi un gioved\u00ec mattina ebbi la possibilit\u00e0 di parlare personalmente con Conte: gli dissi che secondo me avremmo vinto il campionato, ma gli consigliai anche di stare sereno, perch\u00e9 c\u2019erano dei ragazzi pi\u00f9 giovani che avevano paura di sbagliare anche un semplice passaggio per il timore di essere rimproverati. Da quel giorno Conte cambi\u00f2 totalmente atteggiamento. Da gennaio in poi, ogni gioved\u00ec faceva il torello in campo con noi. Moll\u00f2 la presa e si leg\u00f2 moltissimo al gruppo\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Quindi \u00e8 meglio non far arrabbiare Conte\u2026\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cRicordo l\u2019intervallo di Sassuolo-Siena, il parziale era 3-0. Il mister era indemoniato nello spogliatoio, urlava, diede un cazzotto al tavolino e si tagli\u00f2 la mano, aveva la mano che gocciolava sangue. Dopo la sua sfuriata rientrammo in campo facendo un secondo tempo spettacolare. Riuscimmo a pareggiare 3-3, poi la perdemmo sul finale, ma Conte rimase soddisfatto della nostra reazione\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Non hai trovato un po\u2019 forti alcune esternazioni di Conte?\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cOgni discorso di Conte ha un fine. Io sono convinto che anche le dichiarazioni post Milan, quelle sulla Nazionale, (\u2018Se fossi il presidente della Federazione mi sceglierei\u2019), erano fatte di proposito. Perch\u00e9 vincendo col Milan, il Napoli sarebbe diventata la maggiore concorrente dell\u2019Inter. Se non avesse fatto un\u2019uscita del genere i giornali avrebbero parlato solo della corsa scudetto. Il mister attira l\u2019attenzione su di s\u00e9 per lasciare giocatori e societ\u00e0 tranquilli\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>\u201cOgnuno pensa al proprio orticello\u201d era contro i giocatori per\u00f2\u2026\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cIo con quelle dichiarazioni post Bologna, se fossi stato un giocatore del Napoli mi sarei sentito tirato in causa. Infatti, era proprio ci\u00f2 che voleva fare. Il mister dice ai giocatori le stesse cose che dice alle tv, che sia Kevin De Bruyne o chiunque altro, parla in faccia a tutti\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Ci ha pensato anche quest\u2019anno allo scudetto?\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cSono convinto che Conte, dentro di s\u00e9, abbia provato a fare lo sgambetto all\u2019Inter, di nuovo. Dopo la vittoria col Milan un pensiero concreto allo scudetto l\u2019ha fatto, sperando in un passo falso dell\u2019Inter. A un certo punto era a -7, quindi ha sperato di avvicinarsi a -4. Poi, a quel punto, se la sarebbe giocata fino alla fine\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Lukaku ha rischiato di andare fuori rosa, come successo a te. Credi che Conte lo abbia perdonato?\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cPerdonare s\u00ec, ma quest\u2019anno con lui non giocher\u00e0 pi\u00f9 un minuto. Un giocatore come Lukaku che il mister ha sempre voluto ovunque, che per avere al Napoli ha fatto i salti mortali, non pu\u00f2 comportarsi cos\u00ec. Io al posto di Lukaku, avrei chiamato il mister e avrei chiesto direttamente a lui di rimanere in Belgio. Sono certo che Conte glielo avrebbe concesso. Invece non ha riposto a Stellini, non ha risposto al club. Ha messo in difficolt\u00e0 il mister con questo atteggiamento\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Cosa manca a questo Napoli?\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cIn generale in Italia manca la qualit\u00e0. La serie A dei miei tempi era un\u2019altra storia. Quando giocavi contro l\u2019Inter ti trovavi di fronte Sneijder e Milito. Sono convinto che se il Napoli avesse avuto tutta la rosa al completo, avrebbe potuto far vedere un bel calcio, ma gli infortuni sono stati davvero troppi. Abbiamo visto i giocatori darsi il cambio ogni 3-4 partite per i guai fisici. Se non fosse stato per gli infortuni, alcuni non li avremmo neanche mai visti\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Il Napoli del prossimo anno, te lo immagini sempre con Conte in panchina?\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cIo ho la sensazione che Conte possa restare perch\u00e9 con la qualificazione in Champions ha la possibilit\u00e0 di sfatare il tab\u00f9 dell\u2019Europa. Il mister ha solo quella pecca. Non credo possa accettare la nazionale, \u00e8 davvero un momento troppo delicato\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Prima di arrivare al Siena sei stato molto chiacchierato anche fuori dal campo.\u00a0<\/b><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cAl Siena non c\u2019era tempo, pensavamo pi\u00f9 al marted\u00ec di allenamento di Conte che non a fare serata\u201d.\u00a0<\/p>\n<p class=\"paragraph\" spellcheck=\"true\"><b>Quando eri al Parma allora\u2026\u00a0<\/b><\/p>\n<p><a class=\"is-partner-link\" href=\"https:\/\/abbonamenti.gazzetta.it\/scudetto-inter-poster-de\/?pwcmp=cta&amp;forceBrowser=true\" rel=\"nofollow noopener\" target=\"_blank\">Inter Campione d\u2019Italia: abbonati alla Digital Edition + Poster Prima Pagina a 4,99\u20ac\/mese<\/a><\/p>\n<p class=\"paragraph\" spellcheck=\"true\">\u201cS\u00ec, sono stato pi\u00f9 di un anno con la Canalis. Ci siamo incontrati al compleanno di Bernardo Corradi. Lei mi voleva conoscere da tre mesi, per\u00f2 lui non mi dava il numero. Mi diceva che era un personaggio pubblico e non poteva uscire cos\u00ec allo scoperto. Il numero non me l\u2019ha dato, ma al compleanno di Bernardo ho trovato il posto libero proprio accanto ad Elisabetta, poi da l\u00ec ho fatto tutto io\u201d.<\/p>\n<p class=\"is-copyright\">\u00a9 RIPRODUZIONE RISERVATA<\/p>\n","protected":false},"excerpt":{"rendered":"Il brasiliano, che a 43 anni ancora non ha appeso le scarpe al chiodo, e le accuse di&hellip;\n","protected":false},"author":3,"featured_media":487264,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1452],"tags":[213417,6211,1548,1960,6095,270921,2537,32,2940,15425,28272,36,3077,59962,12899,36829,16961,4433,4701,721,2554,2295,921,30465,99850,483,5163,270922,12060,2790,270923,270924,26944,1276,122,1367,1278,277,4702,41122,270925,7882,14839,1102,270926,44182,3451,270927,270928,10407,41999,270929,16481,2097,133315,2154,313,72847,1740,435,1346,1889,564,3412,15364,1598,5302,12272,52,8455,350,270930,1537,90,89,41125,270931,270932,11216,1914,31345,4964,962,1427,6091,5990,553,3479,104466,24450,6048,248,1354,14344,1312,855,5775,6301,1290,2511,5238,154629,270933,7386,235878,30255,5569,6072,11909,1739,245,244,2959,13027],"class_list":{"0":"post-487263","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-calcio","8":"tag-aerobico","9":"tag-allenamenti","10":"tag-allenamento","11":"tag-allenatore","12":"tag-allenatori","13":"tag-allenatori-conte","14":"tag-altra","15":"tag-andare","16":"tag-andato","17":"tag-andavo","18":"tag-arrabbiare","19":"tag-arrivare","20":"tag-arrivato","21":"tag-arrivato-italia","22":"tag-atteggiamento","23":"tag-bernardo","24":"tag-blocchi","25":"tag-brasiliano","26":"tag-bruyne","27":"tag-calcio","28":"tag-cambiare","29":"tag-cambiato","30":"tag-campo","31":"tag-capello","32":"tag-chiodo","33":"tag-cio","34":"tag-compleanno","35":"tag-compleanno-bernardo","36":"tag-conoscere","37":"tag-conte","38":"tag-conte-mise","39":"tag-conte-siena","40":"tag-convinto","41":"tag-corsa","42":"tag-cose","43":"tag-credo","44":"tag-davvero","45":"tag-de","46":"tag-de-bruyne","47":"tag-de-janeiro","48":"tag-de-janeiro-vedere","49":"tag-devi","50":"tag-diceva","51":"tag-dichiarazioni","52":"tag-dichiarazioni-post","53":"tag-diedero","54":"tag-differenza","55":"tag-differenza-fase","56":"tag-differenza-fase-offensiva","57":"tag-disse","58":"tag-dissi","59":"tag-dissi-mister","60":"tag-dovevo","61":"tag-far","62":"tag-far-giocare","63":"tag-farlo","64":"tag-fase","65":"tag-fase-offensiva","66":"tag-football","67":"tag-forti","68":"tag-fronte","69":"tag-giocare","70":"tag-giocatore","71":"tag-giocatori","72":"tag-giocatori-forti","73":"tag-giovani","74":"tag-giovedi","75":"tag-immagini","76":"tag-indietro","77":"tag-infortuni","78":"tag-inter","79":"tag-inter-dovevo","80":"tag-it","81":"tag-italia","82":"tag-italy","83":"tag-janeiro","84":"tag-janeiro-vedere","85":"tag-janeiro-vedere-allenamenti","86":"tag-lego","87":"tag-li","88":"tag-lukaku","89":"tag-manca","90":"tag-mano","91":"tag-martedi","92":"tag-mentalita","93":"tag-messina","94":"tag-milan","95":"tag-minuti","96":"tag-mise","97":"tag-mister","98":"tag-mourinho","99":"tag-napoli","100":"tag-ne","101":"tag-neanche","102":"tag-numero","103":"tag-offensiva","104":"tag-parlare","105":"tag-parma","106":"tag-partita","107":"tag-passaggio","108":"tag-paura","109":"tag-pensavamo","110":"tag-pensavamo-martedi","111":"tag-piccolo","112":"tag-reginaldo","113":"tag-rio","114":"tag-rosa","115":"tag-scudetto","116":"tag-siena","117":"tag-soccer","118":"tag-sport","119":"tag-sports","120":"tag-vedere","121":"tag-voleva"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=487263"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487263\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/487264"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=487263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=487263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=487263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}