{"id":487357,"date":"2026-05-12T21:16:17","date_gmt":"2026-05-12T21:16:17","guid":{"rendered":"https:\/\/www.europesays.com\/it\/487357\/"},"modified":"2026-05-12T21:16:17","modified_gmt":"2026-05-12T21:16:17","slug":"julio-iglesias-82-parlano-le-figlie-victoria-e-cristina-disciplina-e-privilegi","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/487357\/","title":{"rendered":"Julio Iglesias (82) parlano le figlie Victoria e Cristina: disciplina e privilegi"},"content":{"rendered":"<p data-journey-content=\"true\" data-node-id=\"3\" class=\"css-6wxqfj emevuu60\">Nate nel 2001 a Miami, <strong data-node-id=\"3.1\">Victoria e Cristina Iglesias<\/strong>, figlie dell\u2019inconfondibile <strong data-node-id=\"3.3\"><a href=\"https:\/\/www.elle.com\/it\/showbiz\/celebrities\/a65073043\/julio-iglesias-figli-guillermo-iglesias-anni-instagram-foto-ultime-news\/\" target=\"_blank\" data-vars-ga-outbound-link=\"https:\/\/www.elle.com\/it\/showbiz\/celebrities\/a65073043\/julio-iglesias-figli-guillermo-iglesias-anni-instagram-foto-ultime-news\/\" data-vars-ga-ux-element=\"Hyperlink\" data-vars-ga-call-to-action=\"Julio Iglesias\" data-node-id=\"3.3.0\" class=\"body-link css-ohbdae emevuu60\" rel=\"nofollow noopener\">Julio Iglesias<\/a><\/strong> e dell\u2019ex modella <strong data-node-id=\"3.5\">Miranda Rijnsburger<\/strong>, sono cresciute lontano dal rumore mediatico che circonda una famiglia come la loro. Solo negli ultimi anni hanno iniziato a ritagliarsi uno spazio personale, con naturalezza, <strong data-node-id=\"3.7\">senza rinnegare le proprie origini ma nemmeno dipendere completamente da esse<\/strong>, mostrandosi sui social e partecipando ad alcuni eventi pubblici.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"10\" class=\"css-6wxqfj emevuu60\">A prima vista, distinguere le due sorelle \u00e8 tutt\u2019altro che semplice. Non solo per gli evidenti tratti fisici che condividono, ma anche per la forte complicit\u00e0 che emerge ogni volta che appaiono insieme, come accadde cinque anni fa quando aprirono le porte della loro tenuta in provincia di M\u00e1laga a Harper\u2019s Bazaar, firmando il loro primo servizio per una rivista internazionale di moda.<\/p>\n<p><img draggable=\"true\" alt=\"victoria y cristina iglesias\" title=\"Victoria y Cristina Iglesias\" loading=\"lazy\" width=\"1482\" height=\"1920\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/harpers-bazaar-hermanas-iglesias-f10-33698b-1600350440.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Javier Biosca<\/p>\n<p data-journey-content=\"true\" data-node-id=\"16\" class=\"css-6wxqfj emevuu60\">\u201cQuando eravamo piccole conoscevamo solo cosa significasse essere famose, soprattutto qui in Spagna: pensavamo fosse normale. Con l\u2019adolescenza abbiamo iniziato a capire davvero cosa comporta una vita pubblica\u201d, avevano raccontato in quell\u2019occasione. Le figlie di Julio Iglesias hanno sempre dimostrato grande lucidit\u00e0 rispetto alla loro posizione, sottolineando <strong data-node-id=\"16.1\">la consapevolezza di portare uno dei cognomi pi\u00f9 celebri al mondo<\/strong>.<br data-node-id=\"16.3\"\/>\u201c<strong data-node-id=\"16.5\">Nostro padre ci ha sempre trasmesso una grande disciplina. Siamo consapevoli dei privilegi che la vita ci ha dato<\/strong>\u201d, avevano aggiunto.<\/p>\n<p><img draggable=\"true\" alt=\"victoria y cristina iglesias\" title=\"Victoria y Cristina Iglesias\" loading=\"lazy\" width=\"1482\" height=\"1920\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto;\"   src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/harpers-bazaar-hermanas-iglesias-f3-32809b-1600350027.jpg\" class=\"css-0 e1g79fud0\"\/><\/p>\n<p>Javier Biosca<\/p>\n<p data-journey-content=\"true\" data-node-id=\"23\" class=\"css-6wxqfj emevuu60\">Proprio questa educazione rigorosa, ricevuta dall\u2019interprete di Sono un pirata, sono un signore, ha contribuito a plasmare un\u2019infanzia improntata a un\u2019educazione cosmopolita, fatta di lingue diverse e di un\u2019esposizione precoce a culture differenti. Non sorprende quindi che oggi si muovano con disinvoltura tra le grandi citt\u00e0 internazionali: <strong data-node-id=\"23.3\">Victoria vive a Londra<\/strong>, dove studia Produzione cinematografica e Recitazione, mentre <strong data-node-id=\"23.5\">Cristina si \u00e8 trasferita a New York<\/strong>, dove si dedica al design di moda.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"27\" class=\"css-6wxqfj emevuu60\">\u201cVogliamo sfruttare tutte le opportunit\u00e0 che abbiamo avuto fin dalla nascita\u201d, avevano spiegato, evidenziando come dal padre abbiano ereditato <strong data-node-id=\"27.1\">una forte etica del lavoro e la determinazione a non arrendersi mai<\/strong>. Dalla madre, invece, riconoscono di aver preso <strong data-node-id=\"27.3\">la discrezione, la gentilezza e la capacit\u00e0 di trovare sempre il lato positivo in ogni situazione<\/strong>.<\/p>\n<p data-journey-content=\"true\" data-node-id=\"31\" class=\"css-6wxqfj emevuu60\">Un equilibrio tra privilegio e impegno che oggi definisce il loro percorso: consapevoli del punto di partenza, ma determinate a costruire una strada tutta loro.<\/p>\n<p><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elle.com\/_assets\/design-tokens\/fre\/static\/icons\/arrow-right.7440adc.svg?primary=%2523D4D4D4\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" aria-label=\"Prev carousel button\" alt=\"Chevron Left Icon\" data-theme-key=\"icon-button-icon\" transform=\"scaleX(-1)\" class=\"css-14vtfey erhb41k0\"\/><img decoding=\"async\" data-dynamic-svg=\"true\" src=\"https:\/\/www.elle.com\/_assets\/design-tokens\/fre\/static\/icons\/arrow-right.7440adc.svg?primary=%25230f0f15\" loading=\"lazy\" data-testid=\"dynamic-svg-base\" height=\"auto\" width=\"auto\" aria-label=\"Next carousel button\" alt=\"Chevron Right Icon\" data-theme-key=\"icon-button-icon\" class=\"css-18znc9e erhb41k0\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"Nate nel 2001 a Miami, Victoria e Cristina Iglesias, figlie dell\u2019inconfondibile Julio Iglesias e dell\u2019ex modella Miranda Rijnsburger,&hellip;\n","protected":false},"author":3,"featured_media":487358,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1451],"tags":[1621,1620,5741,270971,620,203,204,259632,1537,90,89,619,270970,194017],"class_list":{"0":"post-487357","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-celebrita","8":"tag-celebrita","9":"tag-celebrities","10":"tag-content-type-default","11":"tag-contentid-99a65285-b6a1-4dbd-b092-c47b449e78cb","12":"tag-displaytype-standard-article","13":"tag-entertainment","14":"tag-intrattenimento","15":"tag-issyndicated-false","16":"tag-it","17":"tag-italia","18":"tag-italy","19":"tag-locale-it","20":"tag-shorttitle-le-riflessioni-delle-figlie-di-julio-iglesias","21":"tag-subsection-celebrities"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116563686009308710","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=487357"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/487358"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=487357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=487357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=487357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}