{"id":487453,"date":"2026-05-12T22:36:16","date_gmt":"2026-05-12T22:36:16","guid":{"rendered":"https:\/\/www.europesays.com\/it\/487453\/"},"modified":"2026-05-12T22:36:16","modified_gmt":"2026-05-12T22:36:16","slug":"marotta-teniamo-alla-coppa-italia-chivu-scelta-coraggiosa-il-merito","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/487453\/","title":{"rendered":"Marotta: &#8220;Teniamo alla Coppa Italia. Chivu scelta coraggiosa, il merito&#8230;&#8221;"},"content":{"rendered":"<p><strong>L&#8217;emozione dell&#8217;incontro con Mattarella?<\/strong><\/p>\n<p>&#8220;Non fa altro che dare sicuramente uno stimolo in pi\u00f9 in un contesto che sar\u00e0 bellissimo, in uno stadio sold out contro una squadra molto blasonata&#8221;.<\/p>\n<p><strong>Poter vincere la Coppa Italia che motivazioni d\u00e0 per mantenere l&#8217;Inter ad alti livelli?<\/strong><\/p>\n<p>&#8220;Credo che i valori pi\u00f9 importanti che hanno contraddistinto il nostro cammino siano due: l&#8217;umilt\u00e0 e il coraggio. L&#8217;umilt\u00e0 va di pari passo con la cultura del lavoro e il senso di appartenenza. Il coraggio \u00e8 quello di aver fatto una scelta che non aveva tanto consenso ma che era stata razionalmente valutata che \u00e8 quella di aver affidato la squadra ad un allenatore emergente come Chivu, che ha il merito di averla portata alla vittoria del campionato e alla finale di Coppa Italia&#8221;.<\/p>\n<p><strong>Cosa pensa del caos legato allo spostamento delle partite che valgono la Champions?<\/strong><\/p>\n<p>&#8220;Questo \u00e8 un fatto particolare, straordinario. Era da anni che non si arrivava a far s\u00ec che le ultime due giornate diventassero fondamentali. \u00c8 il bello del calcio e dello sport; \u00e8 altrettanto strano che si giochi un derby di Roma alla penultima giornata in concomitanza con gli Internazionali di tennis, che si giocano a poche centinaia di metri. \u00c8 un tema delicato di ordine pubblico, non sta a me entrare nel merito. Spero si risolva&#8221;.<\/p>\n<p><strong>Malag\u00f2 domani annuncer\u00e0 la sua candidatura alla presidenza FIGC: momento decisivo dove si pu\u00f2 parlare di cambiamento?<\/strong><\/p>\n<p>&#8220;Cominciamo a dire che i grandi problemi del calcio nazionale sono stati di carattere sportivo. Non c&#8217;\u00e8 stato default n\u00e9 economico n\u00e9 finanziario. Su questo aspetto bisogner\u00e0 concentrarsi nel futuro, perch\u00e9 bisogner\u00e0 affidare sicuramente queste responsabilit\u00e0 a persone che abbiamo competenza ed esperienza. Oltre che garantire delle strutture alla base perch\u00e9 i ragazzi possano giocare con strutture e maestri adeguati. Oggi ci sar\u00e0 un candidato come Malag\u00f2, ma questo discorso deve coinvolgere il movimento calcistico ed andare di pari passo con la politica. Mi rende triste la litigiosit\u00e0 che vedo, mettiamola da parte su tutti i fronti per stilare un programma che sia condiviso e che possa portare la nostra Italia il pi\u00f9 in alto possibile&#8221;.<\/p>\n<p class=\"is-copyright\">\u00a9 RIPRODUZIONE RISERVATA<\/p>\n","protected":false},"excerpt":{"rendered":"L&#8217;emozione dell&#8217;incontro con Mattarella? &#8220;Non fa altro che dare sicuramente uno stimolo in pi\u00f9 in un contesto che&hellip;\n","protected":false},"author":3,"featured_media":487454,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1452],"tags":[16569,721,2839,4297,5006,271005,15252,1102,1426,75233,75234,1740,350,1537,90,271006,89,5188,63425,5266,10329,1354,79520,271007,14711,219099,68,135,10333,1739,245,244],"class_list":{"0":"post-487453","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-calcio","8":"tag-bisognera","9":"tag-calcio","10":"tag-chivu","11":"tag-coppa","12":"tag-coppa-italia","13":"tag-coppa-italia-lazio","14":"tag-coraggio","15":"tag-dichiarazioni","16":"tag-finale","17":"tag-finale-coppa","18":"tag-finale-coppa-italia","19":"tag-football","20":"tag-inter","21":"tag-it","22":"tag-italia","23":"tag-italia-lazio","24":"tag-italy","25":"tag-lazio","26":"tag-malago","27":"tag-marotta","28":"tag-merito","29":"tag-ne","30":"tag-palmares","31":"tag-palmares-ricco","32":"tag-pari","33":"tag-pari-passo","34":"tag-passo","35":"tag-presidente","36":"tag-sicuramente","37":"tag-soccer","38":"tag-sport","39":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116564000030206625","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=487453"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487453\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/487454"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=487453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=487453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=487453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}