{"id":487637,"date":"2026-05-13T01:03:24","date_gmt":"2026-05-13T01:03:24","guid":{"rendered":"https:\/\/www.europesays.com\/it\/487637\/"},"modified":"2026-05-13T01:03:24","modified_gmt":"2026-05-13T01:03:24","slug":"hormuz-ecco-le-navi-che-passano-con-il-transponder-spento-evitando-il-blocco-iraniano-le-immagini-radar","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/487637\/","title":{"rendered":"Hormuz, ecco le navi che passano con il transponder spento (evitando il blocco iraniano): le immagini radar"},"content":{"rendered":"<p>Non si vedono sulle mappe satellitari, non appaiono agli &#8220;occhi&#8221; delle rilevazioni ottiche. Ma si muovono, in silenzio nel tentativo di eludere il blocco iraniano. <strong>Eccole le navi che attraversano lo Stretto di <a href=\"https:\/\/www.ilmessaggero.it\/t\/hormuz\" rel=\"nofollow noopener\" target=\"_blank\">Hormuz<\/a> con il transponder spento, cercando di sfuggire dall&#8217;imbuto del <a href=\"https:\/\/www.ilmessaggero.it\/t\/golfo-persico\" rel=\"nofollow noopener\" target=\"_blank\">Golfo Persico<\/a><\/strong>. Le immagini radar d&#8217;altronde non mentono.\u00a0<strong>\u00c8 accaduto nei giorni scorsi, si \u00e8 ripetuto ieri (11 maggio) ed \u00e8 proseguito oggi marted\u00ec 12 maggio il transito ombra di petroliere e cargo in fuga<\/strong>.\u00a0<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/hormuz_navi_1_12120301.jpg\"\/><\/p>\n<p>Le immagini radar a Hormuz <\/p>\n<p>Sono dei puntini bianchi che si confondono con gli scogli che affiorano nello Stretto. Ma la forma e la scia che si lasciano dietro, come mostrano le immagini di Copernicus,\u00a0permettono di identificarle come imbarcazioni, almeno dall&#8217;alto. Non \u00e8 tuttavia facile associarle a un nome, a un proprietario o a una nazionalit\u00e0 di bandiera. Probabilmente questo avverr\u00e0 quando la loro rotta sar\u00e0 uscita dal tiro del\u00a0Corpo delle guardie della rivoluzione islamica, in una zona sicura. <strong>Ad oggi sono delle imbarcazioni che navigano nell&#8217;ombra, sfidando i rischi che l&#8217;assenza di segnale satellitare provoca. L&#8217;obiettivo \u00e8 quello di uscire dalla bolla della Stretto nel tentativo di consegnare il carico di greggio trasportato a bordo<\/strong>.\u00a0<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/whatsapp_image_2026_05_12_at_11.14.27_12120315.jpg\"\/><\/p>\n<p>L&#8217;impatto economico <\/p>\n<p><strong>Ad oggi quasi 1.000 navi risultano ferme nel Golfo Persico, per un valore stimato di 23,7 miliardi di dollari di merci trasportate<\/strong>, con impatti sulle catene globali di approvvigionamento, in primis l&#8217;agroalimentare. A fare il punto sulla logistica in standby dopo la chiusura del traffico marittimo nello stretto di Hormuz \u00e8 il report \u00abPort Infographics\u00bb realizzato da Assoporti e Srm (Centro studi che fa capo al gruppo Intesa Sanpaolo). Lo Stretto di Hormuz movimenta il 37% del petrolio mondiale via mare e il 28% del Gpl globale e il 25% dei fertilizzanti: le tensioni nell&#8217;area hanno provocato un calo dell&#8217;89% dei transiti giornalieri in pochi mesi, rileva l&#8217;analisi di Assoporti e Srm nel sottolineare che le deviazioni delle rotte, ad esempio via Capo di Buona Speranza, comportano un aumento fino a 20 giorni di navigazione aggiuntivi e rincari significativi dei costi. Per l&#8217;Onu il persistente blocco di fertilizzanti nello Stretto di Hormuz rischia di causare entro \u00abqualche settimana\u00bb una \u00abgrave crisi umanitaria\u00bb.<\/p>\n<p> Lo stallo nelle trattative <\/p>\n<p>Nel frattempo\u00a0la risposta iraniana alla proposta Usa per chiudere la guerra e la conseguente reazione scomposta di Donald Trump rappresentano l&#8217;ennesima iniezione di incertezza e tensione sul conflitto in Medio Oriente: <strong>il cessate il fuoco \u00ab\u00e8 debolissimo, attaccato alle macchine per sopravvivere, dopo quella proposta spazzatura che ci hanno mandato\u00bb<\/strong> e \u00abha l&#8217;1% di chance di tenere\u00bb, ha sentenziato il tycoon. Ma se da una parte il presidente Usa boccia \u00abl&#8217;inaccettabile\u00bb replica di Teheran e valuta anche la ripresa dell&#8217;operazione Project Freedom a Hormuz, dall&#8217;altra ritiene una soluzione diplomatica ancora \u00abmolto possibile\u00bb, seppur bollando come \u00abindegna\u00bb la leadership della Repubblica islamica. Una soluzione che tuttavia sembra essere congelata, almeno fino all&#8217;attesissima visita di Trump a Pechino da Xi Jinping, considerata chiave anche per le sorti della guerra mediorientale.\u00a0<\/p>\n<p>&#13;<br \/>\n                                \u00a9 RIPRODUZIONE RISERVATA&#13;<\/p>\n<p>&#13;<\/p>\n<p>\n                            Il punto sui temi di attualit\u00e0, ogni luned\u00ec<br \/>\n                            <b>Iscriviti<\/b> e ricevi le notizie via email\n                        <\/p>\n","protected":false},"excerpt":{"rendered":"Non si vedono sulle mappe satellitari, non appaiono agli &#8220;occhi&#8221; delle rilevazioni ottiche. Ma si muovono, in silenzio&hellip;\n","protected":false},"author":3,"featured_media":487638,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[14,164,165,207034,194354,764,166,7,15,243,11,167,12,168,161,162,163],"class_list":{"0":"post-487637","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-cronaca","9":"tag-dal-mondo","10":"tag-dalmondo","11":"tag-guerra-usa-iran","12":"tag-hormuz","13":"tag-iran","14":"tag-mondo","15":"tag-news","16":"tag-notizie","17":"tag-ultima-ora","18":"tag-ultime-notizie","19":"tag-ultime-notizie-di-mondo","20":"tag-ultimenotizie","21":"tag-ultimenotiziedimondo","22":"tag-world","23":"tag-world-news","24":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116564577980318616","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=487637"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/487638"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=487637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=487637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=487637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}