{"id":487639,"date":"2026-05-13T01:04:18","date_gmt":"2026-05-13T01:04:18","guid":{"rendered":"https:\/\/www.europesays.com\/it\/487639\/"},"modified":"2026-05-13T01:04:18","modified_gmt":"2026-05-13T01:04:18","slug":"scomparse-quattro-ragazze-tra-leonessa-e-poggio-bustone-partite-le-ricerche","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/487639\/","title":{"rendered":"Scomparse quattro ragazze tra Leonessa e Poggio Bustone. Partite le ricerche"},"content":{"rendered":"<p><a class=\"gofollow\" data-track=\"MjQxLDE1LDEsNjA=\" href=\"https:\/\/www.confartigianatorieti.it\/\/\" target=\"_blank\" rel=\"nofollow noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-121693\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/Banner_trasporto_confartigianato.png\" alt=\"\" width=\"400\" height=\"333\"\/><\/a><\/p>\n<p>Quattro ragazze provenienti dallo snodo Poggio Bustone \u2013 Leonessa da ore non danno loro notizie. A lanciare l\u2019allarme un B&amp;B che non li ha visti arrivare. Sul posto aperto campo base con Protezione e Civile di Poggio Bustone, Carabinieri, Carabinieri Forestali, Vigili del Fuoco e Guardia di Finanza. Anche la cittadinanza si \u00e8 attivata per aiutare nelle ricerche.<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-375993\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/Polish_20260512_215400667.jpg\" alt=\"\" width=\"1200\" height=\"896\"  \/><\/p>\n<p><a class=\"gofollow\" data-track=\"MjQ4LDE2LDEsNjA=\" href=\"https:\/\/https:\/\/www.facebook.com\/coveraccessories\/\" target=\"_blank\" rel=\"nofollow\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-121693\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/03\/BANNER-Cover-via-roma-Riyad_.jpg\" alt=\"\" width=\"400\" height=\"333\"\/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Quattro ragazze provenienti dallo snodo Poggio Bustone \u2013 Leonessa da ore non danno loro notizie. A lanciare l\u2019allarme&hellip;\n","protected":false},"author":3,"featured_media":487640,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[79],"tags":[14,93,94,1537,90,89,7,15,11,84,91,12,85,92],"class_list":{"0":"post-487639","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-italia","8":"tag-cronaca","9":"tag-cronaca-italiana","10":"tag-cronacaitaliana","11":"tag-it","12":"tag-italia","13":"tag-italy","14":"tag-news","15":"tag-notizie","16":"tag-ultime-notizie","17":"tag-ultime-notizie-e-news-di-oggi","18":"tag-ultime-notizie-italia","19":"tag-ultimenotizie","20":"tag-ultimenotizieenewsdioggi","21":"tag-ultimenotizieitalia"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116564582099566145","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=487639"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487639\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/487640"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=487639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=487639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=487639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}