{"id":487736,"date":"2026-05-13T02:46:12","date_gmt":"2026-05-13T02:46:12","guid":{"rendered":"https:\/\/www.europesays.com\/it\/487736\/"},"modified":"2026-05-13T02:46:12","modified_gmt":"2026-05-13T02:46:12","slug":"figc-malago-scioglie-le-riserve-e-annuncia-mi-candido-alla-presidenza-e-sfida-aperta-con-abete-per-il-dopo-gravina","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/487736\/","title":{"rendered":"Figc, Malag\u00f2 scioglie le riserve e annuncia: mi candido alla presidenza. \u00c8 sfida aperta con Abete per il dopo-Gravina"},"content":{"rendered":"<p>    di<br \/>\n    Gennaro Scala<\/p>\n<p class=\"summary-art is-line-h-12\">Il numero uno del Coni: \u00abAvevo detto che avrei aspettato le componenti e sono stato di parola\u00bb. Ha il sostegno della Serie A e degli atleti. Il competitor, ex presidente federale, conta sul fortino dei Dilettanti<\/p>\n<p class=\"chapter-paragraph\">Alla fine, <b>Giovanni Malag\u00f2 ha scelto<\/b>. Il Presidente del Coni ha sciolto le ultime riserve dichiarando la sua intenzione di candidarsi ufficialmente alla guida della Federcalcio. \u00abAvevo detto che<a href=\"https:\/\/video.corriere.it\/sport\/malago-per-la-mia-candidatura-alla-figc-decidero-solo-dopo-l-incontro-con-tutte-componenti\/b13b4201-a969-40a6-8764-03cbcc6e3xlk\" rel=\"nofollow noopener\" target=\"_blank\"> avrei aspettato le componenti <\/a>e sono stato di parola\u00bb, ha dichiarato. Un\u2019attesa dettata dal galateo istituzionale \u2013\u2014 la visita romana di Kirsty Coventry per il Cio \u2013\u2014 ma anche dalla necessit\u00e0 di blindare i consensi prima dell\u2019affondo finale. Domattina, Malag\u00f2 varcher\u00e0 il portone di via Allegri per depositare la candidatura. Non lo far\u00e0 da solo, ma con un tesoretto di voti che, sulla carta, lo rende il grande favorito per l\u2019assemblea del 22 giugno.\u00a0<\/p>\n<p class=\"chapter-paragraph\">Dalla sua parte c\u2019\u00e8 <a href=\"https:\/\/www.corriere.it\/sport\/calcio\/26_aprile_30\/presidenza-figc-malago-calciatori-allenatori-aa92d77d-4ab2-4373-aa17-f54b3ddd7xlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">il \u00abblocco\u00bb della Lega Serie A<\/a> (18 club su 20 hanno gi\u00e0 garantito il via libera), a cui si \u00e8 aggiunto il peso specifico dell\u2019Associazione Calciatori (Aic) e degli Allenatori (Aiac). Un asse che sposta il 30% delle preferenze e che punta a un nuovo corso dopo<a href=\"https:\/\/www.corriere.it\/sport\/calcio\/mondiali\/26_aprile_12\/gravina-figc-intervista-nazionale-3e6a2958-f5dd-42e2-88a7-7922355edxlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\"> le dimissioni di Gabriele Gravina<\/a>.\u00a0    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\"><b><a href=\"https:\/\/www.corriere.it\/sport\/calcio\/26_aprile_14\/malago-abete-figc-duello-retroscena-afc5783e-3398-4d6a-bfef-b57b72f05xlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">Dall&#8217;altra parte c&#8217;\u00e8 Giancarlo Abete<\/a><\/b>. L\u2019uomo che ha gi\u00e0 guidato la Figc tra il 2007 e il 2014, \u00e8 pronto a dare battaglia dal suo fortino: la Lega Nazionale Dilettanti. Con il 34% dei voti in dote, Abete rappresenta la base territoriale, la pianta della piramide calcistica. La partita \u00e8 appena iniziata, ma con il deposito formale delle liste, le diplomazie lasceranno spazio ai numeri.\u00a0<\/p>\n<p class=\"is-last-update\" datetime=\"2026-05-12T21:31:50+02:00\">12 maggio 2026<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Gennaro Scala Il numero uno del Coni: \u00abAvevo detto che avrei aspettato le componenti e sono stato&hellip;\n","protected":false},"author":3,"featured_media":487737,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[176],"tags":[144348,34859,271142,271143,3857,271144,14565,25400,23067,128646,23099,1537,90,89,109,63425,7793,135,6325,1821,245,244],"class_list":{"0":"post-487736","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport","8":"tag-abete","9":"tag-aspettato","10":"tag-aspettato-componenti","11":"tag-aspettato-componenti-parola","12":"tag-componenti","13":"tag-componenti-parola","14":"tag-coni","15":"tag-dilettanti","16":"tag-figc","17":"tag-fortino","18":"tag-gravina","19":"tag-it","20":"tag-italia","21":"tag-italy","22":"tag-lega","23":"tag-malago","24":"tag-parola","25":"tag-presidente","26":"tag-riserve","27":"tag-serie","28":"tag-sport","29":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116564982857832355","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=487736"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/487737"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=487736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=487736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=487736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}