{"id":487857,"date":"2026-05-13T05:04:14","date_gmt":"2026-05-13T05:04:14","guid":{"rendered":"https:\/\/www.europesays.com\/it\/487857\/"},"modified":"2026-05-13T05:04:14","modified_gmt":"2026-05-13T05:04:14","slug":"android-17-strizza-locchio-ai-creator-con-il-supporto-nativo-a-instagram-arriva-anche-adobe-premiere","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/487857\/","title":{"rendered":"Android 17 strizza l\u2019occhio ai creator con il supporto nativo a Instagram. Arriva anche Adobe Premiere"},"content":{"rendered":"<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Negli ultimi anni Google si \u00e8 limitata a integrare all&#8217;interno del suo sistema operativo Android quelli che possiamo definire aggiornamenti &#8220;core&#8221;: stabilit\u00e0, framework, sicurezza. Il resto lo ha lasciato ai partner, con le feature delle loro interfacce IA. Android 17 cambia: \u00e8 la stessa Google a portare sulla prossima versione una serie di novit\u00e0 che andranno ad abbracciare tutti gli smartphone che verranno aggiornati, a partire dall&#8217;estensione dell&#8217;interoperabilit\u00e0 con il mondo Apple relativa allo scambio dei file. Il reverse engineering di AirDrop, che permette di cambiare file tra iPhone e Android e che ha gi\u00e0 debuttato sui Pixel e sui Samsung Galaxy, verr\u00e0 esteso quest&#8217;anno a tutti i Samsung, a OPPO, a OnePlus, a Vivo, a Xiaomi e a Honor. Google va oltre: per chi non avr\u00e0 un dispositivo compatibile, Quick Share generer\u00e0 un codice QR che permetter\u00e0 di condividere con iPhone file e foto via cloud. Quick Share arriver\u00e0 anche dentro le app di terze parti, a partire da WhatsApp. Google ha anche rivisto la procedura di passaggio da iPhone ad Android: totalmente riscritta da zero, la nuova soluzione &#8220;Passa ad Android&#8221; copia password, foto, messaggi, app preferite, contatti e persino il layout della home screen via wireless. La nuova procedura debutter\u00e0 quest&#8217;anno su Samsung Galaxy e Google Pixel e permetter\u00e0 di trasferire anche le eSIM.<\/p>\n<p>&#13;<br \/>\n<strong>Tante novit\u00e0 per i creator<\/strong>&#13;<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Android ha da sempre un problema: chi crea contenuti preferisce usare l&#8217;iPhone. Con Android 17 arriva il pi\u00f9 corposo aggiornamento di funzionalit\u00e0 che ci sia mai stato per il sistema operativo di Google in chiave video e audio. Android 17 introdurr\u00e0 Screen Reactions, che permetter\u00e0 di registrare contemporaneamente il proprio volto e lo schermo per creare reaction video senza green screen e senza saltare tra app diverse. Debutter\u00e0 in estate sui Pixel; non sappiamo se anche in Italia.<\/p>\n<p><video src=\"https:\/\/cdn.dday.it\/system\/uploads\/asset\/file\/302\/react.mp4\" autoplay=\"\" muted=\"\" playsinline=\"\" loop=\"\"\/>&#13;<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Decisamente pi\u00f9 interessante la partnership con Meta: sui dispositivi Android pi\u00f9 avanzati Instagram sfrutter\u00e0 nativamente la cattura e la riproduzione Ultra HDR, la stabilizzazione video integrata e l&#8217;integrazione con Night Sight per gli scatti in condizioni di scarsa luce. Google sostiene che i video catturati e caricati su Instagram dai telefoni Android di fascia alta raggiungeranno finalmente una qualit\u00e0 pari o superiore a quella del concorrente principale, ovviamente l&#8217;iPhone. Instagram \u00e8 inoltre stata ottimizzata per i tablet Android.<\/p>\n<p>&#13;<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Su Edits, l&#8217;app di editing di Instagram sempre pi\u00f9 utilizzata, arrivano poi in esclusiva per Android due funzioni AI on-device: Smart Enhance, per migliorare foto e video con un tocco, e Sound Separation, che isola e gestisce separatamente tracce audio come vento, rumore di fondo e musica.<\/p>\n<p><video src=\"https:\/\/cdn.dday.it\/system\/uploads\/asset\/file\/303\/smart.mp4\" autoplay=\"\" muted=\"\" playsinline=\"\" loop=\"\"\/>&#13;<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Per chi vuole qualcosa in pi\u00f9, in estate arriver\u00e0 Adobe Premiere per Android, con template ed effetti pensati per pubblicare direttamente su YouTube Shorts. Il formato APV (Advanced Professional Video) sar\u00e0 infine esteso a molti altri flagship con processore Snapdragon 8 Elite Gen5.<\/p>\n<p>&#13;<br \/>\n<strong>Una nuova collezione di emoji tridimensionali<\/strong>&#13;<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">Google ha annunciato anche Noto 3D, una nuova collezione di emoji tridimensionali destinata a sostituire progressivamente quelle piatte. Le emoji sono diventate ormai &#8220;il linguaggio universale del digitale&#8221; e secondo l&#8217;azienda la fisicit\u00e0 tridimensionale aiuta a dare maggiore personalit\u00e0. Debutteranno sui Pixel pi\u00f9 avanti nel corso dell&#8217;anno e successivamente verranno estese all&#8217;ecosistema Google.<\/p>\n<p>&#13;<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal leading-[1.7]\">C&#8217;\u00e8 spazio anche per Pause Point, una funzione che si attiva quando si apre un&#8217;app considerata &#8220;distraente&#8221;: invece di bloccare l&#8217;accesso o proporre un timer facilmente ignorabile, concede una pausa di 10 secondi durante la quale l&#8217;utente pu\u00f2 fare un esercizio di respirazione, impostare un limite, guardare foto preferite o passare a un&#8217;app alternativa come un audiolibro. Per disattivare la funzione sar\u00e0 necessario riavviare il telefono.<\/p>\n","protected":false},"excerpt":{"rendered":"Negli ultimi anni Google si \u00e8 limitata a integrare all&#8217;interno del suo sistema operativo Android quelli che possiamo&hellip;\n","protected":false},"author":3,"featured_media":487858,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[173],"tags":[1537,90,89,195,198,199,197,200,201,194,196],"class_list":{"0":"post-487857","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-scienza-e-tecnologia","8":"tag-it","9":"tag-italia","10":"tag-italy","11":"tag-science","12":"tag-science-and-technology","13":"tag-scienceandtechnology","14":"tag-scienza","15":"tag-scienza-e-tecnologia","16":"tag-scienzaetecnologia","17":"tag-technology","18":"tag-tecnologia"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116565525705199623","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=487857"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487857\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/487858"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=487857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=487857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=487857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}