{"id":487861,"date":"2026-05-13T05:06:16","date_gmt":"2026-05-13T05:06:16","guid":{"rendered":"https:\/\/www.europesays.com\/it\/487861\/"},"modified":"2026-05-13T05:06:16","modified_gmt":"2026-05-13T05:06:16","slug":"luranio-di-teheran-e-la-bomba-a-portata-razzi-e-sottomarini-lo-scudo-e-fragile","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/487861\/","title":{"rendered":"L&#8217;uranio di Teheran e la bomba a portata. Razzi e sottomarini: lo scudo \u00e8 &#8220;fragile&#8221;"},"content":{"rendered":"<p>La Bomba \u00e8 tornata. L&#8217;ordigno nucleare, il cui spettro si era allontanato da noi a partire dalla fine della Guerra fredda torna a minacciarci, a partire dal conflitto in Ucraina e da quello in Iran, ecco alcune cose da sapere per capire meglio l&#8217;entit\u00e0 del pericolo.<\/p>\n<p>1. Quanti tipi di bombe atomiche esistono?<\/p>\n<p>La prima grande differenza \u00e8 quella tra bombe a fissione e bombe a fusione o termonucleari. Le prime utilizzano soltanto uranio altamente arricchito (detto weapons grade) e plutonio 239 un isotopo sintetico e altamente radioattivo, prodotto tramite irraggiamento di uranio-238. Questo materiale fissile \u00e8 ampiamente pi\u00f9 instabile e &#8220;arricchito&#8221; rispetto a quello normalmente utilizzato nelle centrali nucleari. Esistono poi le bombe a fusione nucleare in cui l&#8217;esplosivo a fissione serve a innescare una molto pi\u00f9 potente esplosione causata dalla fusione di atomi di deuterio e trizio (isotopi dell&#8217;idrogeno). Questo tipo di bombe pu\u00f2 sviluppare potenze elevatissime. La pi\u00f9 potente mai costruita \u00e8 stata la &#8220;Bomba Zar&#8221; sovietica testata nel 1961. Svilupp\u00f2 una potenza di 50 megatoni, circa 3125 volte la bomba di Hiroshima.<\/p>\n<p>2. L&#8217;Iran pu\u00f2 produrre una bomba atomica?<\/p>\n<p>Teheran aveva raggiunto la capacit\u00e0 di arricchire l&#8217;uranio al 60%, soglia che la poneva molto vicina alla soglia del 90% necessario per scopi bellici. Con circa 400 chilogrammi di uranio arricchito a quel livello, il rischio di una possibile rapida escalation verso la &#8220;bomba&#8221; era reale, sebbene non siano mai state fornite prove definitive sulla fase finale di weaponization. Dopo i massicci attacchi subiti dagli Usa e da Israele, passare alla fase militare e alla costruzione di una bomba vera e propria di dimensioni sufficientemente ridotte da essere montata su un vettore balistico \u00e8 un&#8217;ipotesi che sembra essersi decisamente allontanata; e anche recuperare parte del materiale fissile dai siti bombardati potrebbe essere complesso. Difficile quantificare in termini di tempo il ritardo inflitto agli iraniani per\u00f2.<\/p>\n<p>3. Cos&#8217;\u00e8 una bomba sporca e quanto pu\u00f2 essere piccola un&#8217;atomica?<\/p>\n<p>Non esistono solo super bombe. Una delle frontiere della ricerca \u00e8 quella della costruzione di &#8220;mini-nuke&#8221;. Ovvero bombe facilmente trasportabili e occultabili. Si tratta di ordigni a implosione lineare che ovviamente sviluppano potenze molto pi\u00f9 basse delle grandi testate ma potrebbero diventare oggetti terroristici. Uno degli ordigni pi\u00f9 leggeri \u00e8 stato realizzato dagli Usa per essere lanciata dal razzo &#8220;Davy Crockett&#8221;. La testata tattica pesava poco pi\u00f9 di 23 chili. Esistono poi le bombe sporche. Usano esplosivo convenzionale ma nell&#8217;esplosione rilasciano isotopi radioattivi: per questo tipo di ordigni pu\u00f2 bastare uranio arricchito al 20%.<\/p>\n<p>4. Ci si pu\u00f2 difendere da attacchi nucleari con scudi missilistici come il Golden Dome Shield?<\/p>\n<p>La tecnologia di intercettazione delle testate atomiche sviluppata dalla Nato, e soprattutto dagli Usa, ha forti limiti rispetto alle testate ipersoniche come ad esempio il missile &#8220;Oreshnik&#8221; sviluppato dalla Russia. Si stanno sviluppando svariate contromisure in quest&#8217;ambito. Ma la minaccia meno facilmente intercettabile potrebbero essere i droni sottomarini. Ad esempio il &#8220;Poseidon&#8221;, un veicolo sottomarino autonomo di fabbricazione russa ed equipaggiato di una testata nucleare al cobalto-60. Ha una tecnologia stealth e pu\u00f2 percorrere pi\u00f9 di 11mila chilometri. Provoca un&#8217;esplosione nucleare a cui segue uno tsunami radiattivo. Non esistono contromisure.\n<\/p>\n<p> \u00c8 una tecnologia a cui lavora anche la Nord Corea.5. Quante testate nucleari ci sono nel mondo?<\/p>\n<p>Si parla di pi\u00f9 di 12300 testate di cui 9600 pronte all&#8217;uso. A detenerle sono Russia, Usa, Cina, Francia, Gran Bretagna, India, Pakistan, Israele (90 testate non confermate) e Corea del Nord (50 testate stimate).<\/p>\n","protected":false},"excerpt":{"rendered":"La Bomba \u00e8 tornata. L&#8217;ordigno nucleare, il cui spettro si era allontanato da noi a partire dalla fine&hellip;\n","protected":false},"author":3,"featured_media":487862,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[41060,14,164,165,767,166,7,15,11,167,12,168,132446,161,162,163],"class_list":{"0":"post-487861","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-bomba-atomica","9":"tag-cronaca","10":"tag-dal-mondo","11":"tag-dalmondo","12":"tag-difesa","13":"tag-mondo","14":"tag-news","15":"tag-notizie","16":"tag-ultime-notizie","17":"tag-ultime-notizie-di-mondo","18":"tag-ultimenotizie","19":"tag-ultimenotiziedimondo","20":"tag-uranio","21":"tag-world","22":"tag-world-news","23":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116565533552325782","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=487861"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/487861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/487862"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=487861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=487861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=487861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}