{"id":488032,"date":"2026-05-13T07:48:14","date_gmt":"2026-05-13T07:48:14","guid":{"rendered":"https:\/\/www.europesays.com\/it\/488032\/"},"modified":"2026-05-13T07:48:14","modified_gmt":"2026-05-13T07:48:14","slug":"guerra-ucraina-russia-le-ultime-news-di-oggi-13-maggio-diretta","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/488032\/","title":{"rendered":"Guerra Ucraina Russia, le ultime news di oggi 13 maggio. DIRETTA"},"content":{"rendered":"<p>Mosca sta ritardando lo scambio \\&#8221;1000 per 1000\\&#8221; di prigionieri, come prevede l&#8217;accordo annunciato dal presidente statunitense Donald Trump lo scorso 8 maggio. E&#8217; l&#8217;accusa che il difensore civico dell&#8217;Ucraina, Dmytro Lubinets, rivolge alla Russia &#8211; come riporta l&#8217;agenzia Unian &#8211; dopo che il team negoziale ucraino ha consegnato le liste di nomi per lo scambio.\\n<\/p>\n<p>Il Presidente degli Stati Uniti, Donald Trump, ritiene che la fine della guerra russo-ucraina sia \\&#8221;gi\u00e0 imminente\\&#8221;. Interrogato sulle prospettive della guerra russo-ucraina, Trump ha espresso l&#8217;opinione che la sua fine sia \\&#8221;molto vicina\\&#8221;. \\&#8221;La fine della guerra in Ucraina, credo, sia molto vicina\\&#8221;, ha affermato.\\&#8221;Che ci crediate o no, penso che accadr\u00e0. E raggiungeremo un accordo tra Russia e Ucraina\\&#8221;, ha detto Trump, ribadendo di aver \\&#8221;posto fine a otto guerre\\&#8221;.<\/p>\n<p>\\n\\n<\/p>\n<p><strong>Per approfondire:<\/strong><\/p>\n<p>\\n\\n<\/p>\n<p><strong>Per ricevere le notizie di Sky TG24:<\/strong><\/p>\n<p>\\n<\/p>\n<ul>\\n  <\/p>\n<li>Il canale Whatsapp di Sky TG24 (<a href=\"\\&quot;https:\/\/whatsapp.com\/channel\/0029VaDyGIp90x2wDXgUnV2j\\&quot;\" data-intcmp-qp=\"\\&quot;skytg24_liveblog_interlink_text\\&quot;\">clicca qui<\/a>)<\/li>\n<p>\\n  <\/p>\n<li>Le notizie audio con i titoli del tg (<a href=\"\\&quot;https:\/\/tg24.sky.it\/cronaca\/approfondimenti\/audio-news-sky-tg24.html\\&quot;\" data-intcmp=\"\\&quot;skytg24_liveblog_interlink_text\\&quot;\">clicca qui<\/a>)<\/li>\n<p>\\n<\/ul>\n<p>\\n&#8221;,&#8221;postId&#8221;:&#8221;1063b069-ea25-403f-934f-d7bc5b12bb79&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}}],&#8221;posts&#8221;:[{&#8220;timestamp&#8221;:&#8221;2026-05-13T07:40:43.931Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-13T09:40:43+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Il presidente ucraino Zelensky avverte di possibili attacchi di droni russi durante il giorno&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Il presidente ucraino Volodymyr Zelensky ha avvertito di possibili ondate di attacchi di droni russi nel corso della giornata di mercoled\u00ec, affermando che oltre cento droni si trovavano nello spazio aereo ucraino, poich\u00e9 Mosca ha modificato la sua tattica per colpire sempre pi\u00f9 spesso durante le ore diurne. \\&#8221;La Russia continua i suoi attacchi e lo fa sfacciatamente, prendendo di mira deliberatamente le nostre infrastrutture ferroviarie e i siti civili nelle nostre citt\u00e0\\&#8221;, ha dichiarato Zelensky in un post su X.<\/p>\n<p>\\n<\/p>\n<p>Dall&#8217;inizio della guerra, pi\u00f9 di quattro anni fa, la Russia ha condotto principalmente attacchi con droni e missili di notte. Nelle ultime settimane, tuttavia, ha ripetutamente inviato centinaia di droni e missili durante il giorno.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;0dcd6573-f02a-40b8-a3f8-b63665926269&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-13T07:15:26.046Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-13T09:15:26+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Quanto sono credibili le parole di Putin sulla fine della guerra?&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>\\&#8221;Penso che la questione stia giungendo al termine\\&#8221; ha detto il presidente russo, ma come interpretare queste dichiarazioni arrivate dal demiurgo del conflitto e l&#8217;idea dell&#8217;ex cancelliere tedesco Schr\u00f6der come mediatore? Occorre un po&#8217; di contesto per capirne gli obiettivi e la portata.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;36d21c89-9188-42f2-af70-425f14e471ab&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;Quanto sono credibili le parole di Putin sulla fine della guerra?&#8221;,&#8221;url&#8221;:&#8221;https:\/\/tg24.sky.it\/mondo\/2026\/05\/11\/fine-guerra-ucraina-putin&#8221;,&#8221;imageSrc&#8221;:&#8221;https:\/\/tg24.sky.it\/assets\/images\/5f291a32b4604f3b0750cbff2c8bca39aadde3d8\/skytg24\/it\/mondo\/2026\/05\/11\/fine-guerra-ucraina-putin\/GettyImages-2274879061.jpg?im=Resize,width=1218&#8243;}},{&#8220;timestamp&#8221;:&#8221;2026-05-13T06:34:00.893Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-13T08:34:00+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Attacchi russi contro Dnipropetrovsk, 8 morti e 11 feriti&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Nella regione di Dnipropetrovsk, otto persone sono state uccise e altre undici ferite a seguito di attacchi russi. Come riporta Ukrinform, il capo dell&#8217;amministrazione militare regionale Oleksandr Ganzha lo ha comunicato su Telegram. Secondo Ganzha i russi hanno attaccato tre distretti della regione quasi 30 volte. Nel distretto di Nikopol, i quartieri di Nikopol, Marhanetska, Myrivska, Pokrovska e Chervonogryhorivska sono stati oggetto di attacco. Sono stati danneggiati infrastrutture, abitazioni private e automobili. Tre persone sono rimaste ferite. Un ragazzo di 16 anni \u00e8 stato ricoverato in ospedale in condizioni non gravi. Un altro ragazzo di 16 anni e un altro ancora di 21 anni sono attualmente in cura ambulatoriale. Nel distretto di Sinelnyky, i russi hanno attaccato le comunit\u00e0 di Dubovykivska e Mykolaivska. Pi\u00f9 di 20 case sono state danneggiate. Due persone sono rimaste uccise. Nove altre case sono state danneggiate nell&#8217;attacco di ieri sera nella zona. Quattro persone sono morte e altre quattro sono rimaste ferite, tre delle quali ricoverate in ospedale. Un uomo di 50 anni \u00e8 in gravi condizioni. A Kryvyi Rih, un&#8217;azienda, delle infrastrutture e un gasdotto sono stati danneggiati. Due persone sono morte e altre quattro sono rimaste ferite. Come riportato da Ukrinform, ieri una donna di 65 anni e un uomo di 43 anni sono stati uccisi in un attacco russo a Kryvyi Rih. Quattro persone sono rimaste ferite. Una bambina di nove mesi ha subito l&#8217;amputazione di una gamba.\u00a0<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;37fa6c55-408c-4b00-be84-e6c84b472a49&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-13T06:29:00.039Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-13T08:29:00+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Lavrov: \\&#8221;Gli Usa vogliono comprare a poco prezzo parte del gasdotto Nord Stream\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Gli Stati Uniti vogliono acquistare a prezzo stracciato la porzione del gasdotto Nord Stream appartenente a societ\u00e0 europee. Lo ha annunciato il ministro degli Esteri russo Sergei Lavrov, secondo quanto riporta l&#8217;agenzia Ria Novosti. \\&#8221;Guardate come gli americani stanno pianificando di ripristinare il Nord Stream, due gasdotti distrutti. Eppure, sotto la presidenza di Joe Biden, gli stessi americani avevano dichiarato che questi gasdotti non avrebbero funzionato. Ora, invece, incolpano gli ucraini per averli distrutti, tre su quattro sono stati fatti saltare in aria, e gli americani vogliono acquistare la parte che apparteneva a societ\u00e0 europee\\&#8221;, ha affermato in un&#8217;intervista a Rt India. Il ministro ha sottolineato che Washington intende spendere circa dieci volte meno rispetto all&#8217;investimento iniziale dell&#8217;Europa. \\&#8221;Se lo faranno, costringeranno i tedeschi a riappropriarsi della propria dignit\u00e0 nazionale e a dire: &#8216;Va bene, useremo questo gasdotto&#8217;. Ma i prezzi non saranno pi\u00f9 il risultato di un accordo tra il fornitore, la Russia, e la Germania; saranno dettati dagli americani, che acquisteranno questo gasdotto dagli europei\\&#8221;, ha spiegato Lavrov. Gli Stati Uniti non fanno mistero del loro desiderio di controllare il transito del gas attraverso l&#8217;Ucraina, ha aggiunto il ministro degli Esteri.\u00a0<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;29a73c00-d71c-4724-92a4-2e92f2e7bd3e&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-13T06:23:20.034Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-13T08:23:20+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Droni contro due quartieri di Kharkiv, scoppia un incendio&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>I russi hanno lanciato due attacchi sui quartieri di Shevchenkivskyi e Kholodnohirskyi a Kharkiv, e un incendio \u00e8 scoppiato nel luogo della caduta. La notizia \u00e8 riportata da Ukrinform, che cita il sindaco della citt\u00e0 Igor Terekhov su Telegram. Come riportato dal sindaco, secondo il Centro informazioni di Kharkiv, nel distretto di Shevchenkivskyi i resti di un drone nemico sono caduti sulla strada, senza causare feriti finora. Sempre nel distretto di Kholodnohirsk, Mosca ha colpito un&#8217;infrastruttura: sul luogo dell&#8217;attacco \u00e8 scoppiato un incendio. Non si hanno notizie di vittime.\u00a0<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;790ac06f-68fb-43b9-892a-393ddfc09912&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-13T05:36:06.224Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-13T07:36:06+0200&#8243;,&#8221;video&#8221;:{&#8220;videoId&#8221;:&#8221;1097479&#8243;,&#8221;videoPageUrl&#8221;:&#8221;https:\/\/video.sky.it\/news\/mondo\/video\/oltre-20mila-bambini-ucraini-rapiti-da-mosca-lue-stanzia-50-milioni-di-euro-1097479&#8243;},&#8221;altBackground&#8221;:true,&#8221;title&#8221;:&#8221;Oltre 20mila bambini ucraini rapiti da Mosca: l&#8217;Ue stanzia 50 milioni di euro. VIDEO&#8221;,&#8221;postId&#8221;:&#8221;822dc1fd-f58c-4052-8492-06fc5e3dc32e&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-13T05:21:00.489Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-13T07:21:00+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;L&#8217;Ucraina lancia un attacco di droni contro Krasnodar &#8220;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Nella notte l&#8217;esercito ucraino ha lanciato un attacco con droni contro il territorio di Krasnodar, colpendo presumibilmente le infrastrutture portuali del villaggio di Volna, secondo quanto riportato da alcuni canali Telegram russi.Video pubblicati sui social media mostrano dense colonne di fumo che si alzano da un porto vicino, come riportato da diverse testate giornalistiche. In un altro messaggio su Telegram, il Comando Operativo del Territorio di Krasnodar ha segnalato un incendio che ha coinvolto attrezzature presso un&#8217;azienda non specificata, affermando inoltre che una persona \u00e8 rimasta ferita nell&#8217;attacco con droni ucraini.<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;38e1de37-69b9-426c-92ec-76d51b74f92a&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-13T05:16:00.317Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-13T07:16:00+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Kiev accusa Mosca: \\&#8221;Ritardato lo scambio dei prigionieri\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Mosca sta ritardando lo scambio \\&#8221;1000 per 1000\\&#8221; di prigionieri, come prevede l&#8217;accordo annunciato dal presidente statunitense Donald Trump lo scorso 8 maggio. E&#8217; l&#8217;accusa che il difensore civico dell&#8217;Ucraina, Dmytro Lubinets, rivolge alla Russia &#8211; come riporta l&#8217;agenzia Unian &#8211; dopo che il team negoziale ucraino ha consegnato le liste di nomi per lo scambio. \\&#8221;I contatti non si sono interrotti &#8211; ha detto &#8211; ma il processo ha subito un rallentamento. Anche se si raggiunge un accordo con i russi, non si pu\u00f2 mai essere sicuri al 100% che verr\u00e0 rispettato da loro. In realt\u00e0, il lavoro non si \u00e8 fermato. Ogni giorno si svolgono processi di negoziazione\\&#8221;.\u00a0<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;1569ffb2-a8d1-48c1-92a7-3bb513814ef9&#8243;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}},{&#8220;timestamp&#8221;:&#8221;2026-05-13T05:10:33.992Z&#8221;,&#8221;timestampUtcIt&#8221;:&#8221;2026-05-13T07:10:33+0200&#8243;,&#8221;altBackground&#8221;:false,&#8221;title&#8221;:&#8221;Ucrain, Trump: \\&#8221;La fine della guerra \u00e8 imminente\\&#8221;&#8221;,&#8221;content&#8221;:&#8221;<\/p>\n<p>Il Presidente degli Stati Uniti, Donald Trump, ritiene che la fine della guerra russo-ucraina sia \\&#8221;gi\u00e0 imminente\\&#8221;. Interrogato sulle prospettive della guerra russo-ucraina, Trump ha espresso l&#8217;opinione che la sua fine sia \\&#8221;molto vicina\\&#8221;. \\&#8221;La fine della guerra in Ucraina, credo, sia molto vicina\\&#8221;, ha affermato.\\&#8221;Che ci crediate o no, penso che accadra&#8217;. E raggiungeremo un accordo tra Russia e Ucraina\\&#8221;, ha detto Trump, ribadendo di aver \\&#8221;posto fine a otto guerre\\&#8221;. Gli \u00e8 stato anche chiesto se ci fosse un \\&#8221;accordo\\&#8221; tra lui e il leader russo secondo cui la Russia avrebbe dovuto ricevere l&#8217;intero Donbass nell&#8217;ambito di un accordo di pace. Trump ha risposto brevemente: \\&#8221;No\\&#8221;.\u00a0<\/p>\n<p>&#8220;,&#8221;postId&#8221;:&#8221;297e51b3-e695-4c3e-aaf5-43e012d36b2b&#8221;,&#8221;postLink&#8221;:{&#8220;title&#8221;:&#8221;&#8221;,&#8221;url&#8221;:&#8221;&#8221;,&#8221;imageSrc&#8221;:&#8221;&#8221;}}]}&#8221; query='{&#8220;configurationName&#8221;:&#8221;LIVEBLOG_CONTAINER_WIDGET&#8221;,&#8221;liveblogId&#8221;:&#8221;28f53349-a980-4942-bdf8-9ed4d5527c24&#8243;,&#8221;tenant&#8221;:&#8221;tg24&#8243;,&#8221;limit&#8221;:800}&#8217; config='{&#8220;live&#8221;:true,&#8221;isWebView&#8221;:false,&#8221;postsPerPageMobile&#8221;:10,&#8221;postsPerPageDesktop&#8221;:10}&#8217;&gt;<\/p>\n<p>Mosca sta ritardando lo scambio &#8220;1000 per 1000&#8221; di prigionieri, come prevede l&#8217;accordo annunciato dal presidente statunitense Donald Trump lo scorso 8 maggio. E&#8217; l&#8217;accusa che il difensore civico dell&#8217;Ucraina, Dmytro Lubinets, rivolge alla Russia &#8211; come riporta l&#8217;agenzia Unian &#8211; dopo che il team negoziale ucraino ha consegnato le liste di nomi per lo scambio.<\/p>\n<p>Il Presidente degli Stati Uniti, Donald Trump, ritiene che la fine della guerra russo-ucraina sia &#8220;gi\u00e0 imminente&#8221;. Interrogato sulle prospettive della guerra russo-ucraina, Trump ha espresso l&#8217;opinione che la sua fine sia &#8220;molto vicina&#8221;. &#8220;La fine della guerra in Ucraina, credo, sia molto vicina&#8221;, ha affermato.&#8221;Che ci crediate o no, penso che accadr\u00e0. E raggiungeremo un accordo tra Russia e Ucraina&#8221;, ha detto Trump, ribadendo di aver &#8220;posto fine a otto guerre&#8221;.<\/p>\n<p><strong>Per approfondire:<\/strong><\/p>\n<p><strong>Per ricevere le notizie di Sky TG24:<\/strong><\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>meno di un minuto fa<\/p>\n<p>Il presidente ucraino Zelensky avverte di possibili attacchi di droni russi durante il giorno<\/p>\n<p>Il presidente ucraino Volodymyr Zelensky ha avvertito di possibili ondate di attacchi di droni russi nel corso della giornata di mercoled\u00ec, affermando che oltre cento droni si trovavano nello spazio aereo ucraino, poich\u00e9 Mosca ha modificato la sua tattica per colpire sempre pi\u00f9 spesso durante le ore diurne. &#8220;La Russia continua i suoi attacchi e lo fa sfacciatamente, prendendo di mira deliberatamente le nostre infrastrutture ferroviarie e i siti civili nelle nostre citt\u00e0&#8221;, ha dichiarato Zelensky in un post su X.<\/p>\n<p>Dall&#8217;inizio della guerra, pi\u00f9 di quattro anni fa, la Russia ha condotto principalmente attacchi con droni e missili di notte. Nelle ultime settimane, tuttavia, ha ripetutamente inviato centinaia di droni e missili durante il giorno.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>25 minuti fa<\/p>\n<p>Quanto sono credibili le parole di Putin sulla fine della guerra?<\/p>\n<p>&#8220;Penso che la questione stia giungendo al termine&#8221; ha detto il presidente russo, ma come interpretare queste dichiarazioni arrivate dal demiurgo del conflitto e l&#8217;idea dell&#8217;ex cancelliere tedesco Schr\u00f6der come mediatore? Occorre un po&#8217; di contesto per capirne gli obiettivi e la portata.<\/p>\n<p><a href=\"https:\/\/tg24.sky.it\/mondo\/2026\/05\/11\/fine-guerra-ucraina-putin\" title=\"Quanto sono credibili le parole di Putin sulla fine della guerra?\" class=\"lvbg-post-link\" data-intcmp=\"skytg24_liveblog_liveblog-preview_null\" data-analytics-element=\"liveblog-preview\" rel=\"nofollow noopener\" target=\"_blank\"><img alt=\"Quanto sono credibili le parole di Putin sulla fine della guerra?\" style=\"opacity:0;transition:opacity 0.3s\" class=\"lvbg-post-link__image\"\/>Quanto sono credibili le parole di Putin sulla fine della guerra?Vai al contenuto <\/a><\/p>\n<p>08:34<\/p>\n<p>Attacchi russi contro Dnipropetrovsk, 8 morti e 11 feriti<\/p>\n<p>Nella regione di Dnipropetrovsk, otto persone sono state uccise e altre undici ferite a seguito di attacchi russi. Come riporta Ukrinform, il capo dell&#8217;amministrazione militare regionale Oleksandr Ganzha lo ha comunicato su Telegram. Secondo Ganzha i russi hanno attaccato tre distretti della regione quasi 30 volte. Nel distretto di Nikopol, i quartieri di Nikopol, Marhanetska, Myrivska, Pokrovska e Chervonogryhorivska sono stati oggetto di attacco. Sono stati danneggiati infrastrutture, abitazioni private e automobili. Tre persone sono rimaste ferite. Un ragazzo di 16 anni \u00e8 stato ricoverato in ospedale in condizioni non gravi. Un altro ragazzo di 16 anni e un altro ancora di 21 anni sono attualmente in cura ambulatoriale. Nel distretto di Sinelnyky, i russi hanno attaccato le comunit\u00e0 di Dubovykivska e Mykolaivska. Pi\u00f9 di 20 case sono state danneggiate. Due persone sono rimaste uccise. Nove altre case sono state danneggiate nell&#8217;attacco di ieri sera nella zona. Quattro persone sono morte e altre quattro sono rimaste ferite, tre delle quali ricoverate in ospedale. Un uomo di 50 anni \u00e8 in gravi condizioni. A Kryvyi Rih, un&#8217;azienda, delle infrastrutture e un gasdotto sono stati danneggiati. Due persone sono morte e altre quattro sono rimaste ferite. Come riportato da Ukrinform, ieri una donna di 65 anni e un uomo di 43 anni sono stati uccisi in un attacco russo a Kryvyi Rih. Quattro persone sono rimaste ferite. Una bambina di nove mesi ha subito l&#8217;amputazione di una gamba.\u00a0<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>08:29<\/p>\n<p>Lavrov: &#8220;Gli Usa vogliono comprare a poco prezzo parte del gasdotto Nord Stream&#8221;<\/p>\n<p>Gli Stati Uniti vogliono acquistare a prezzo stracciato la porzione del gasdotto Nord Stream appartenente a societ\u00e0 europee. Lo ha annunciato il ministro degli Esteri russo Sergei Lavrov, secondo quanto riporta l&#8217;agenzia Ria Novosti. &#8220;Guardate come gli americani stanno pianificando di ripristinare il Nord Stream, due gasdotti distrutti. Eppure, sotto la presidenza di Joe Biden, gli stessi americani avevano dichiarato che questi gasdotti non avrebbero funzionato. Ora, invece, incolpano gli ucraini per averli distrutti, tre su quattro sono stati fatti saltare in aria, e gli americani vogliono acquistare la parte che apparteneva a societ\u00e0 europee&#8221;, ha affermato in un&#8217;intervista a Rt India. Il ministro ha sottolineato che Washington intende spendere circa dieci volte meno rispetto all&#8217;investimento iniziale dell&#8217;Europa. &#8220;Se lo faranno, costringeranno i tedeschi a riappropriarsi della propria dignit\u00e0 nazionale e a dire: &#8216;Va bene, useremo questo gasdotto&#8217;. Ma i prezzi non saranno pi\u00f9 il risultato di un accordo tra il fornitore, la Russia, e la Germania; saranno dettati dagli americani, che acquisteranno questo gasdotto dagli europei&#8221;, ha spiegato Lavrov. Gli Stati Uniti non fanno mistero del loro desiderio di controllare il transito del gas attraverso l&#8217;Ucraina, ha aggiunto il ministro degli Esteri.\u00a0<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>08:23<\/p>\n<p>Droni contro due quartieri di Kharkiv, scoppia un incendio<\/p>\n<p>I russi hanno lanciato due attacchi sui quartieri di Shevchenkivskyi e Kholodnohirskyi a Kharkiv, e un incendio \u00e8 scoppiato nel luogo della caduta. La notizia \u00e8 riportata da Ukrinform, che cita il sindaco della citt\u00e0 Igor Terekhov su Telegram. Come riportato dal sindaco, secondo il Centro informazioni di Kharkiv, nel distretto di Shevchenkivskyi i resti di un drone nemico sono caduti sulla strada, senza causare feriti finora. Sempre nel distretto di Kholodnohirsk, Mosca ha colpito un&#8217;infrastruttura: sul luogo dell&#8217;attacco \u00e8 scoppiato un incendio. Non si hanno notizie di vittime.\u00a0<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>07:36<\/p>\n<p>Oltre 20mila bambini ucraini rapiti da Mosca: l&#8217;Ue stanzia 50 milioni di euro. VIDEO<\/p>\n<p>07:21<\/p>\n<p>L&#8217;Ucraina lancia un attacco di droni contro Krasnodar <\/p>\n<p>Nella notte l&#8217;esercito ucraino ha lanciato un attacco con droni contro il territorio di Krasnodar, colpendo presumibilmente le infrastrutture portuali del villaggio di Volna, secondo quanto riportato da alcuni canali Telegram russi.Video pubblicati sui social media mostrano dense colonne di fumo che si alzano da un porto vicino, come riportato da diverse testate giornalistiche. In un altro messaggio su Telegram, il Comando Operativo del Territorio di Krasnodar ha segnalato un incendio che ha coinvolto attrezzature presso un&#8217;azienda non specificata, affermando inoltre che una persona \u00e8 rimasta ferita nell&#8217;attacco con droni ucraini.<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>07:16<\/p>\n<p>Kiev accusa Mosca: &#8220;Ritardato lo scambio dei prigionieri&#8221;<\/p>\n<p>Mosca sta ritardando lo scambio &#8220;1000 per 1000&#8221; di prigionieri, come prevede l&#8217;accordo annunciato dal presidente statunitense Donald Trump lo scorso 8 maggio. E&#8217; l&#8217;accusa che il difensore civico dell&#8217;Ucraina, Dmytro Lubinets, rivolge alla Russia &#8211; come riporta l&#8217;agenzia Unian &#8211; dopo che il team negoziale ucraino ha consegnato le liste di nomi per lo scambio. &#8220;I contatti non si sono interrotti &#8211; ha detto &#8211; ma il processo ha subito un rallentamento. Anche se si raggiunge un accordo con i russi, non si pu\u00f2 mai essere sicuri al 100% che verr\u00e0 rispettato da loro. In realt\u00e0, il lavoro non si \u00e8 fermato. Ogni giorno si svolgono processi di negoziazione&#8221;.\u00a0<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n<p>07:10<\/p>\n<p>Ucrain, Trump: &#8220;La fine della guerra \u00e8 imminente&#8221;<\/p>\n<p>Il Presidente degli Stati Uniti, Donald Trump, ritiene che la fine della guerra russo-ucraina sia &#8220;gi\u00e0 imminente&#8221;. Interrogato sulle prospettive della guerra russo-ucraina, Trump ha espresso l&#8217;opinione che la sua fine sia &#8220;molto vicina&#8221;. &#8220;La fine della guerra in Ucraina, credo, sia molto vicina&#8221;, ha affermato.&#8221;Che ci crediate o no, penso che accadra&#8217;. E raggiungeremo un accordo tra Russia e Ucraina&#8221;, ha detto Trump, ribadendo di aver &#8220;posto fine a otto guerre&#8221;. Gli \u00e8 stato anche chiesto se ci fosse un &#8220;accordo&#8221; tra lui e il leader russo secondo cui la Russia avrebbe dovuto ricevere l&#8217;intero Donbass nell&#8217;ambito di un accordo di pace. Trump ha risposto brevemente: &#8220;No&#8221;.\u00a0<\/p>\n<p>Leggi di pi\u00f9 <\/p>\n","protected":false},"excerpt":{"rendered":"Mosca sta ritardando lo scambio \\&#8221;1000 per 1000\\&#8221; di prigionieri, come prevede l&#8217;accordo annunciato dal presidente statunitense Donald&hellip;\n","protected":false},"author":3,"featured_media":488033,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[14,164,165,206,77,56742,166,7,15,171,170,11,167,12,168,4526,4528,161,162,163],"class_list":{"0":"post-488032","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-cronaca","9":"tag-dal-mondo","10":"tag-dalmondo","11":"tag-donald-trump","12":"tag-guerra","13":"tag-liveblog","14":"tag-mondo","15":"tag-news","16":"tag-notizie","17":"tag-russia","18":"tag-ucraina","19":"tag-ultime-notizie","20":"tag-ultime-notizie-di-mondo","21":"tag-ultimenotizie","22":"tag-ultimenotiziedimondo","23":"tag-vladimir-putin","24":"tag-volodymyr-zelensky","25":"tag-world","26":"tag-world-news","27":"tag-worldnews"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116566171037368716","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/488032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=488032"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/488032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/488033"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=488032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=488032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=488032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}