{"id":488062,"date":"2026-05-13T08:11:13","date_gmt":"2026-05-13T08:11:13","guid":{"rendered":"https:\/\/www.europesays.com\/it\/488062\/"},"modified":"2026-05-13T08:11:13","modified_gmt":"2026-05-13T08:11:13","slug":"perche-lhantavirus-e-una-minaccia-diversa-dal-covid-e-cosa-ci-dovrebbe-preoccupare-davvero","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/488062\/","title":{"rendered":"Perch\u00e9 l&#8217;Hantavirus \u00e8 una minaccia diversa dal Covid (e cosa ci dovrebbe preoccupare davvero)"},"content":{"rendered":"<p>    di<br \/>\n    Paolo Giordano e Alessandro Vespignani<\/p>\n<p class=\"summary-art is-line-h-12\">La prima differenza \u00e8 sostanziale: l&#8217;Hantavirus Andes non \u00e8 un patogeno sconosciuto. Lo studiamo fin dai primi anni Novanta, epidemiologicamente e geneticamente, attraverso l\u2019analisi delle catene di trasmissione documentate<\/p>\n<p class=\"chapter-paragraph\">Vale la pena di capire perch\u00e9 le rassicurazioni dell\u2019Oms non sono di facciata, di percepirne la fondatezza. Anche perch\u00e9 \u00e8 plausibile, come si osserva gi\u00e0 nelle ultime ore, <b>che il focolaio debba ancora esprimersi appieno e che la febbre mediatica salga ancora un po\u2019 prima di placarsi<\/b>. In che cosa la minaccia dell\u2019Hantavirus si presenta diversa da quella iniziale del Covid?<\/p>\n<p class=\"chapter-paragraph\"><b>La prima differenza \u00e8 sostanziale:<a href=\"https:\/\/www.corriere.it\/cronache\/diretta-live\/26_maggio_12\/hantavirus-ultime-notizie-diretta.shtml\" rel=\"nofollow noopener\" target=\"_blank\"> l\u2019Hantavirus Andes<\/a> <\/b>non \u00e8 un patogeno sconosciuto. Lo studiamo fin dai primi anni Novanta, epidemiologicamente e geneticamente, attraverso l\u2019analisi delle catene di trasmissione documentate. <b>Le conoscenze pi\u00f9 recenti vengono da un outbreak,<\/b> avvenuto a Epuy\u00e9n, nella provincia di Chubut, Argentina, nel novembre 2018.    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\">A Epuy\u00e9n almeno 34 persone sono state contagiate con sintomi, di cui 11 sono morte.<\/p>\n<p class=\"chapter-paragraph\"><b>Due numeri che fanno saltare all\u2019occhio<\/b> un aspetto poco rassicurante dell\u2019Hantavirus: <a href=\"https:\/\/roma.corriere.it\/notizie\/cronaca\/26_maggio_12\/hantavirus-sintomatico-in-arrivo-allo-spallanzani-di-roma-e-federico-amaretti-il-marittimo-calabrese-sulla-ave-da-crociera-mv-fe7632d6-6b31-4f35-9d1f-4c02ebec7xlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">una letalit\u00e0 elevata<\/a>, tra il 21% e il 51%, elevatissima in effetti, dovuta anche alla mancanza di cure specifiche. Una letalit\u00e0 che fra l\u2019altro non sembra molto correlata, come nel caso del Covid, a fattori di fragilit\u00e0 pregressi. L\u2019Hantavirus, insomma, \u00e8 qualcosa con cui non vogliamo avere a che fare individualmente.<\/p>\n<p class=\"chapter-paragraph\"><b>Gi\u00e0 che abbiamo iniziato, tanto vale proseguire<\/b> con le cattive notizie. Il tempo di incubazione dell\u2019Andes \u00e8 lungo, pu\u00f2 variare<a href=\"https:\/\/roma.corriere.it\/notizie\/cronaca\/26_maggio_12\/hantavirus-finestre-aperte-e-almeno-2-metri-di-distanza-dai-familiari-cosa-prevede-la-quarantena-e-chi-la-stabilisce-da27ae1d-baea-4a6a-860c-c70f99b24xlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\"> fra i quattro e i 40 giorni<\/a> (contro i tre-sei del Covid). <b>Questo aumenta la zona cieca del contagio e prolungher\u00e0 la nostra ansia (il conto alla rovescia). <\/b>Ci vorr\u00e0 pazienza insomma prima di dichiarare conclusi il focolaio attuale e la crisi che lo accompagna. <b>Ma questo stesso intervallo lungo concede anche alle autorit\u00e0 sanitarie pi\u00f9 tempo per il tracciamento dei contatti, <\/b>per mettere in quarantena chi \u00e8 stato esposto, per agire prima che i casi si manifestino. Inoltre, le indicazioni attuali suggeriscono che nella fase asintomatica si \u00e8 poco o per nulla contagiosi.<b> Possiamo quindi ragionevolmente pensare che ci\u00f2 che si svela via via al nostro sguardo sia all\u2019incirca ci\u00f2 che davvero c\u2019\u00e8.<\/b> Con il Covid, al contrario, eravamo nei guai seri prima ancora di capire per che cosa.<\/p>\n<p>APPROFONDISCI CON IL PODCAST<\/p>\n<p class=\"chapter-paragraph\"><b>Ci sono poi, pur nella statistica limitata a disposizione,<\/b> casi documentati di \u00absuperdiffusione\u00bb dell\u2019Hantavirus, ovvero di singole persone in grado di contagiarne diverse altre, dando un\u2019accelerazione all\u2019epidemia.<br \/><b>Ma le cattive notizie finiscono pi\u00f9 o meno qui. <\/b>E la peggiore di tutte, la letalit\u00e0 elevata, il parametro pi\u00f9 importante per la singola persona che contrae la malattia, diviene assai meno rilevante allargando lo sguardo alla collettivit\u00e0.<\/p>\n<p class=\"chapter-paragraph\"><b>Per la collettivit\u00e0, come abbiamo imparato nella primavera del 2020<\/b>, conta infatti molto di pi\u00f9 un\u2019altra caratteristica: la facilit\u00e0 di trasmissione. Almeno sulla base dei dati disponibili, <b>la trasmissibilit\u00e0 del virus Andes \u00e8 sensibilmente inferiore a quella del Sars-Cov-2, anche nella sua forma originale<\/b>. Il contagio interumano richiede un contatto ravvicinato e prolungato. Nell\u2019outbreak di Epuy\u00e9n misure di isolamento standard sono state sufficienti a interrompere la catena.<\/p>\n<p class=\"chapter-paragraph\"><b>Ed \u00e8 proprio questo l\u2019altro vantaggio fondamentale <\/b>che abbiamo rispetto al passato recente: le misure. Anzi: le misure e noi. Salvo mutazioni imprevedibili, <b>se anche l\u2019Hantavirus dovesse dimostrarsi pi\u00f9 trasmissibile della stima attuale, impatterebbe su una popolazione mondiale molto diversa da quella \u00abingenua\u00bb<\/b> su cui si \u00e8 abbattuto il Covid. Una popolazione che era ingenua non solo dal punto di vista immunologico ma anche da quello comportamentale.\u00a0<\/p>\n<p class=\"chapter-paragraph\"><b>Tutti o quasi, oggi, sono pronti a rimettersi l<\/b>e mascherine all\u2019occorrenza, tutti o quasi sono allenati alle misure di distanziamento sociale. <b>Nostro malgrado, la pandemia ci ha addestrati.<\/b> L\u2019attenzione stessa con cui non solo le organizzazioni sanitarie, ma anche i media e il pubblico hanno seguito le peripezie della nave da crociera testimonia di un\u2019aumentata consapevolezza, raggiunta non \u00abgrazie al\u00bb ma al costo del Covid. Questo cambia tutto.<\/p>\n<p class=\"chapter-paragraph\"><b>Nel gennaio 2020, quando fu lanciato l\u2019allarme coronavirus,<\/b> ci siamo trovati di fronte a un quadro opaco. Non avevamo idea di quale patogeno stavamo per affrontare. Le prime stime ci dicevano che l\u2019epidemia aveva gi\u00e0 superato i centomila casi in Cina, con decine di catene di trasmissione attive nel resto del mondo, la maggior parte delle quali non identificate. L<b>a sorveglianza era in ritardo rispetto alla realt\u00e0<\/b>, i modelli epidemiologici dovevano operare in condizioni di grande incertezza.<\/p>\n<p class=\"chapter-paragraph\"><b>Oggi il numero di casi \u00e8 piccolo e, soprattutto,<\/b> coerente con quello che sappiamo sulla biologia del virus. <a href=\"https:\/\/www.corriere.it\/salute\/malattie_infettive\/26_maggio_11\/navi-crociera-possibili-epidemie-hantavirus-norovirus-7f716e28-788c-4574-bed9-be8309f47xlk.shtml\" rel=\"nofollow noopener\" target=\"_blank\">Una nave da crociera \u00e8 un ottimo incubatore di malattie ma \u00e8 anche un luogo chiuso<\/a>, limitato, che permette un tracciamento rigoroso.<b> Sappiamo chi c\u2019era a bordo, dove dormiva, chi \u00e8 sceso prima, dove e quando<\/b> (c\u2019era stata un\u2019altra nave, all\u2019inizio della pandemia di Covid, ormeggiata a Yokohama, e si era rivelata preziosissima per gli epidemiologi in quelle prime settimane di caos).<\/p>\n<p class=\"chapter-paragraph\"><b>Se tutto origina veramente dai due olandesi <\/b>che hanno fatto birdwatching nella discarica di Ushuaia, se non sono gi\u00e0 loro infetti secondari,<b> allora possiamo veramente ricostruire il contagio dall\u2019inizio<\/b>. E fra qualche mese potremo forse affermare di sapere tutto del focolaio di Hantavirus del maggio 2026 e di come \u00e8 stato debellato.<\/p>\n<p class=\"chapter-paragraph\"><b>Fino ad allora, tuttavia, qualche cautela resta d\u2019obbligo<\/b>. Cognitiva ed emotiva, le due aree che abbiamo scoperto cos\u00ec difficili da conciliare durante la pandemia. Almeno fino allo scadere dei 42 giorni dal 6 maggio conviene tenere in quarantena, insieme alle persone con contatti a rischio, tanto la nostra autosuggestione quanto le nostre certezze assolute.<\/p>\n<p class=\"is-last-update\" datetime=\"2026-05-13T09:20:40+02:00\">13 maggio 2026 ( modifica il 13 maggio 2026 | 09:20)<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Paolo Giordano e Alessandro Vespignani La prima differenza \u00e8 sostanziale: l&#8217;Hantavirus Andes non \u00e8 un patogeno sconosciuto.&hellip;\n","protected":false},"author":3,"featured_media":488063,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[839,2537,5143,271358,271359,265850,271360,271361,1963,6880,1045,47020,271356,271362,86089,225629,483,24713,372,4435,4124,16997,1278,3451,271363,271364,2729,17563,11482,4203,271365,271366,271367,271357,13168,70054,271368,271369,263789,271370,271371,239,180953,1302,7378,1537,90,89,191679,271372,707,10703,2505,13402,52378,15,271373,31822,90239,240,15839],"class_list":{"0":"post-488062","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-salute","8":"tag-almeno","9":"tag-altra","10":"tag-analisi","11":"tag-analisi-catene","12":"tag-analisi-catene-trasmissione","13":"tag-andes","14":"tag-andes-patogeno","15":"tag-andes-patogeno-sconosciuto","16":"tag-attuale","17":"tag-capire","18":"tag-casi","19":"tag-catene","20":"tag-catene-trasmissione","21":"tag-catene-trasmissione-documentate","22":"tag-cattive","23":"tag-cattive-notizie","24":"tag-cio","25":"tag-collettivita","26":"tag-contagio","27":"tag-contatti","28":"tag-covid","29":"tag-crociera","30":"tag-davvero","31":"tag-differenza","32":"tag-differenza-sostanziale","33":"tag-differenza-sostanziale-hantavirus","34":"tag-diversa","35":"tag-documentate","36":"tag-elevata","37":"tag-epidemia","38":"tag-epidemiologicamente","39":"tag-epidemiologicamente-geneticamente","40":"tag-epidemiologicamente-geneticamente-analisi","41":"tag-epuyen","42":"tag-focolaio","43":"tag-geneticamente","44":"tag-geneticamente-analisi","45":"tag-geneticamente-analisi-catene","46":"tag-hantavirus","47":"tag-hantavirus-andes","48":"tag-hantavirus-andes-patogeno","49":"tag-health","50":"tag-ingenua","51":"tag-inizio","52":"tag-insomma","53":"tag-it","54":"tag-italia","55":"tag-italy","56":"tag-letalita","57":"tag-letalita-elevata","58":"tag-maggio","59":"tag-minaccia","60":"tag-misure","61":"tag-nave","62":"tag-nave-crociera","63":"tag-notizie","64":"tag-outbreak","65":"tag-pandemia","66":"tag-patogeno","67":"tag-salute","68":"tag-trasmissione"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/488062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=488062"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/488062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/488063"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=488062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=488062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=488062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}