{"id":488145,"date":"2026-05-13T09:23:16","date_gmt":"2026-05-13T09:23:16","guid":{"rendered":"https:\/\/www.europesays.com\/it\/488145\/"},"modified":"2026-05-13T09:23:16","modified_gmt":"2026-05-13T09:23:16","slug":"finali-nazionali-under-15-kellogs-forli-bassano-pall-varese-e-bologna-ai-quarti","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/488145\/","title":{"rendered":"Finali Nazionali Under 15 Kellog\u2019s: Forl\u00ec, Bassano, Pall. Varese e Bologna ai quarti"},"content":{"rendered":"<p>            <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" class=\"entry-thumb\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/05\/ROB_5960-scaled-1.jpg\"   alt=\"\" title=\"ROB_5960-scaled\"\/><\/p>\n<p><strong>Terza giornata di gare a Udine per la Finale Nazionale Kellogg\u2019s Under 15 Eccellenza \u201cTrofeo Claudio Papini\u201d, le partite odierne hanno definito il quadro degli Spareggi in programma domani.<\/strong>\u00a0<strong>Sabato 16 maggio la manifestazione assegner\u00e0 il titolo di campione d\u2019Italia 2026, si gioca tra Palasport Benedetti e Palasport Vecchiatto mentre la fase finale si terr\u00e0 interamente al Carnera a partire dai Quarti di finale.<\/strong><\/p>\n<p><strong>Ai Quarti di Finale \u00e8 passata la Bcc Emilbanca Virtus Bologna, che oggi ha superato la Stella Azzurra Roma (79-86). Secondo posto per Desio, che ha piegato Chieti 75-51, eliminandola. Forl\u00ec ha chiuso il girone B a punteggio pieno superando College: per classifica avulsa seconda Siena, terza Borgomanero e quarta Anzio, eliminata.<\/strong><\/p>\n<p>Nel gruppo C Bassano ha chiuso in testa regolando Robur et Fides Varese. Secondo posto per Faenza, che si \u00e8 imposta all\u2019overtime su Latina, eliminando di fatto la squadra laziale dalla competizione.<\/p>\n<p>L\u2019equilibrio nel girone D, prima di oggi con tutte e 4 le squadre appaiate a 2 punti in classifica, \u00e8 stato rotto dai successi di Pallacanestro Varese su Stella EBK Roma e da quello di Reggio Emilia sulla Reyer Venezia. Lombardi comunque primi, orogranata eliminati.<\/p>\n<p><strong>Gli Spareggi (13 Maggio)<br \/>Ore 16.00 Rimadesio-College Borgomanero (Benedetti)<br \/>Ore 18.00 Stosa Virtus Siena-Stella Azzurra (Benedetti)<br \/>Ore 16.00 Raggisolaris Faenza-Stella EBK Academy (Vecchiatto)<br \/>Ore 18.00 Una Hotels Reggio Emilia-Robur et Fides Varese (Vecchiatto)<\/strong><\/p>\n<p><strong>Le partite di oggi<br \/>Girone A<\/strong><br \/><strong>Stella Azzurra-Bcc Emilbanca Virtus Bologna 79-86 (27-14, 11-27, 22-23, 19-22)<br \/><\/strong>Stella Azzurra: Falappi 18 (8\/15, 0\/3), Gunda 7 (2\/2, 1\/1), Calvaire, Luchenti 12 (5\/7), Szabo-Haktlins 13 (2\/8, 2\/9), Galigani 5 (2\/5, 0\/1), Fazio (0\/2), Canciello 18 (5\/11, 1\/2), Tulini, Bogunovich, Scarsella 6 (2\/2, 0\/1), Chukwudi. All. Coggiatti<br \/>Bologna: Compagni 10 (2\/2, 1\/3), Damiano 11 (4\/8, 1\/1), Righi 8 (4\/5), Goldoni 2 (1\/3, 0\/1), Govoni 12 (2\/6, 2\/4), Lipparini 6 (1\/3, 0\/2), Lodini 13 (2\/4, 2\/4), Piras 2 (1\/4), Rusticelli 4 (2\/4, 0\/2), Melvine Angelo Z., Baldaccini 7 (3\/8, 0\/2), Castagnetti 11 (4\/8). All. Pezzoli<br \/>Al primo strappo della Stella Azzurra, che approccia in modo magistrale la partita, risponde Bologna nel secondo periodo con un perentorio 27-11. La svolta nell\u2019ultimo quarto, col gioco da 4 punti di Govoni che vale il 68-64 e poi con la tripla di Lodini per il 78-69 che piega la resistenza di un\u2019ottima Stella Azzurra. Per le vunere 13 di Lodini e 12 di Govoni; per la squadra di Coggiatti 18 punti di Canciello. Virtus prima, Stella agli spareggi.<\/p>\n<p><strong>Chieti Basket-Rimadesio Aurora Desio 94 51-75 (15-18, 17-14, 10-20, 9-23)<br \/><\/strong>Chieti: Mancinelli, Cioffi (0\/1 Da 3), Lusi 6 (3\/5, 0\/4), Spinozzi (0\/2, 0\/1), Maragno 11 (3\/6, 1\/6), Casmiri Mojica (0\/2 Da 3), Scimia 6 (3\/6, 0\/2), Brandimarte 13 (5\/14, 0\/4), Pennacchia 6 (3\/6, 0\/1), De Luca (0\/1 Da 3), Di Meo 2, Mocci 7 (3\/5, 0\/2). All. Pica<br \/>Rimadesio Aurora Desio 94: Dell\u2019Aquila 2 (1\/2, 0\/3), Montrasio 11 (5\/6, 0\/3), Frizzi 10 (2\/4, 2\/3), Pirelli 1, Torri 11 (2\/3, 1\/3), Croci 4 (2\/5, 0\/2), Caldarelli 2 (1\/4), De Simeis 5 (2\/6), De Dominicis 14 (4\/8, 1\/4), Brogiolo 2 (1\/2, 0\/1), Bentivoglio 4 (2\/5, 0\/1), Santandrea 9 (2\/6, 1\/4). All. Castoldi<br \/>La partita prende la strada di Desio dopo l\u2019intervallo lungo, al quale le due squadre arrivano in parit\u00e0 a quota 32. Nel terzo quarto il primo allungo dei lombardi, che poi prendono il largo negli ultimi minuti. Per Chieti, eliminata, 13 punti da Brandimarte: per Desio 14 di De Dominicis e 11 di Montrasio.<\/p>\n<p><strong>Girone B<br \/>College Basketball-Unieuro Basket Forl\u00ec 81-94 (19-20, 16-19, 19-22, 27-33)<br \/><\/strong>College: Pileggi (0\/1 Da 3), Guidetti 4 (2\/4, 0\/1), Et Tini (0\/1 Da 3), Okadoh Ogbemudia 2 (0\/1, 0\/2), Ferraro 34 (9\/15, 4\/16), Mariannini 8 (1\/5, 2\/5), Campone 2 (1\/5), Moia 2 (1\/3), Migliaccio 10 (5\/10, 0\/1), Span\u00f2 8 (1\/2, 2\/4), Varone 5 (1\/1, 1\/2), Felice Munaf\u00f2 6 (3\/8, 0\/1). All. Rossi<br \/>Forl\u00ec: Focaccia 12 (4\/12), Crescenzio, Paolin 14 (5\/14, 0\/2), Montano 3 (1\/2), Vandi (0\/1), Diomand\u00e8 2 (1\/3, 0\/2), Girardi 17 (5\/13, 1\/3), Cerminara 26 (8\/12, 2\/5), Bianco 4 (2\/2), Altini 12 (6\/7, 0\/1), Del Gatto, Zaccarini 4 (1\/4). All. Pelliconi<br \/>Forl\u00ec la vince mantenendo il percorso netto e chiudendo al primo posto il girone B grazie a una prestazione offensiva di eccellente livello. College rimane a contatto per 40 minuti ma al termine della sfida si deve arrendere ai cinque giocatori romagnoli in doppia cifra (Focaccia 12, Paolin 14, Girardi 17, Cerminara 26, Altini 12). Per la squadra di Rossi, 34 i punti di un eccellente Ferraro.<\/p>\n<p><strong>Anzio Basket Club-Stosa Virtus Siena 69-68 (14-23, 29-8, 8-17, 18-20)<br \/><\/strong>Anzio: Tontini 5 (2\/8), Lovato 22 (7\/16, 2\/8), Masci 17 (3\/10, 3\/13), Terzi, Bisbocci, De Padova 13 (0\/5, 4\/11), Di Pietro, M. Rossi (0\/1 Da 3), D. Rossi 7 (2\/6, 0\/2), Geracitano, Pisoni 5 (1\/2, 1\/8), Papagna. All. Conte<br \/>Siena: Buti, Gostinelli 12 (2\/5, 2\/8), Torricelli 2 (1\/2), Panichi 6 (0\/2, 2\/3), Zappa, Nesi 18 (6\/7, 2\/6), Sgheri 8 (2\/3, 1\/4), Prestigi 20 (6\/9, 1\/5), Perinti, Pianigiani, Buffa 2 (1\/2), Sommella (0\/2). All. Spinello<br \/>E\u2019 amaro il successo di Anzio, che per lunghi tratti sogna di ottenere la qualificazione agli spareggi e poi chiude in testa la partita ma al quarto posto per la classifica avulsa che la vede appaiata a Siena e a College. Per la squadra laziale, che chiude il suo torneo a testa altissima, 22 di Lovato e 17 di Masci. Per Siena, che festeggia il secondo posto nonostante il ko, 20 di Prestigi e 18 di Nesi e 12 di Gostinelli.<\/p>\n<p><strong>Girone C<br \/>Robur et Fides Varese-Orange1 Basket Bassano 66-79 (18-27, 13-16, 9-17, 26-19)<br \/><\/strong>Varese: Spada 2 (1\/3), Bada 15 (3\/8, 3\/7), Orrigoni 9 (2\/4, 1\/2), Coulibaly 5 (2\/6, 0\/1), Ciocchetti 19 (6\/11, 1\/8), Spinaci 1, Mai 7 (3\/7, 0\/1), Stancea 8 (3\/5, 0\/1), Villa (0\/3 Da 3), Sara (0\/1). All. Longoni<br \/>Bassano: Gottardi 24 (11\/16, 0\/2), Velez 11 (3\/9, 0\/2), Concei\u00e7\u00e3o 10 (2\/8, 0\/2), Caldieraro 10 (3\/6, 1\/2), Cappa (0\/1 Da 3), Cappozzo 5 (1\/3, 0\/1), Duscio (0\/1), Carlana, Gasparri 4 (2\/2, 0\/2), Mayfield 15 (3\/8, 3\/6), Butnaru, Bonato. All. Bordignon<br \/>Bassano consolida il primato nel girone controllando la partita per 40 minuti. La Robur ha il grande merito di rimanere in partita almeno per 25 minuti ma la squadra veneta mantiene il comando amministrando il vantaggio e ampliando le rotazioni. Per Varese 19 di Ciocchetti, per l\u2019Orange 24 di Gottardi e 15 di Mayfield<\/p>\n<p><strong>Smg Basket School-Raggisolaris Academy Faenza 54-62 d1ts (16-10, 11-15, 13-16, 11-10, 3-11)<br \/><\/strong>Smg: Paradiso 6 (3\/8, 0\/5), Troiso 17 (7\/10), Ravieli 11 (5\/9, 0\/2), Tosolini (0\/2), Dvornic 6 (3\/7, 0\/3), Salvatori (0\/1), Bisconti (0\/1), Mastrobattista 4 (2\/4, 0\/1), Giambra 2, Mascetti 6 (3\/8, 0\/2), Panella (0\/3, 0\/2), Mastrodomenico 2 (1\/6, 0\/5). All. Gallo<br \/>Faenza: Cimatti 20 (4\/12, 2\/6), Trevisan 11 (2\/7, 2\/11), Servadei (0\/2, 0\/5), Sicilia, Collamati (0\/1, 0\/1), Stamati 19 (6\/9, 1\/8), Tacconelli 4 (2\/5, 0\/2), Badiali 2 (0\/4, 0\/2), Placci (0\/2, 0\/1), Cattani 3 (0\/1, 1\/2), Mazzoni 3 (1\/3, 0\/7). All. Borelli<br \/>Faenza ottiene il secondo posto del girone C e chiude alle spalle di Bassano al termine di una partita equilibrata e piena di colpi di scena. All\u2019overtime Latina perde lucidit\u00e0 e si deve arrendere alla compagine romagnola, che in Cimatti (20) e Stamati (19) i migliori marcatori. Per coach Gallo, 17 di Troiso e 11 di Ravieli.<\/p>\n<p><strong>Girone D<br \/>Una Hotels Reggio Emilia-Umana Reyer Venezia 77-64 (23-13, 20-28, 16-8, 18-15)<br \/><\/strong>Reggio Emilia: Mambriani 14 (7\/25, 0\/3), Bendinelli 2 (1\/1), Fornaciari, Terrero Hernandez 8 (4\/9, 0\/2), Verona, Morini (0\/2, 0\/1), Beltrami 3 (1\/1), Manzini 4 (2\/6, 0\/1), Giudici 17 (1\/10, 2\/5), Zangrandi 6 (3\/8, 0\/4), Bizzarri 6 (1\/1, 1\/2), Ogie 17 (6\/12, 0\/1). All. Menozzi<br \/>Venezia: Pizzato 4 (2\/2, 0\/1), Gaiardo 10 (3\/9, 0\/1), Destiny Osayande 10 (4\/12, 0\/1), Chinello 8 (4\/10, 0\/1), Pugiotto, Diop 2 (1\/2), Pivetta 4 (2\/2), Ruggiero (0\/2, 0\/2), Daniel Osayande 8 (4\/13, 0\/1), Fulfiment 8 (1\/3, 1\/2), Boem 10 (5\/10, 0\/2), Miozzo. All. Buffo<br \/>Reggio Emilia la vince due volte, prima con un avvio molto deciso e poi nel terzo quarto quando trova un altro strappo che vanifica il ritorno della Reyer. Nel quarto periodo il divario si amplia, Venezia deve salutare Udine anzitempo mentre l\u2019Una Hotels chiude il girone D al secondo posto. Ogie (17) e Mambriani (14) i migliori realizzatori per Reggio, tre a quota 10 per l\u2019Umana: Destiny Osayande, Boem e Gaiardo.<\/p>\n<p><strong>Stella Ebk Academy-Pallacanestro Varese 63-71 (17-15, 15-16, 15-21, 16-19)<br \/><\/strong>Stella Ebk: Morel Pohl 18 (5\/9, 1\/9), Sarr 8 (4\/7), Baiera, Zanazzo 7 (2\/7, 1\/1), Peruzzi 17 (7\/13, 1\/6), Soda 3 (1\/7, 0\/1), Betto 2 (1\/1), Travaini, Bordo, Palma (0\/1), Di Zio (0\/1), Iaiani 8 (4\/9, 0\/1). All. Spalvieri<br \/>Varese: Carannante 6 (3\/7, 0\/4), Mantovani 26 (1\/4, 5\/17), Chiarello, Balzarotti 15 (4\/7, 1\/3), Foglia (0\/1 Da 3), De Iuliis 6 (1\/1, 1\/1), Vorfi 9 (2\/7, 1\/1), Begnis (0\/2, 0\/1), Giammarino, Salvio 6 (1\/1, 1\/2), Frediani 3 (0\/1, 1\/3), Schirripa. All. Todisco<br \/>Partita equilibrata, tesa anche per l\u2019importanza della posta in palio. Alla fine a imporsi \u00e8 la Pallacanestro Varese, che cos\u00ec centra il primo posto e si qualifica per i Quarti. La Stella EBK ci prova fino alla fine ma centra il terzo posto nel girone grazie al successo di Reggio su Venezia: decisivi i 26 punti di Mantovani, importanti i 15 di Balzarotti. Alla Stella EBK non bastano i 17 di Peruzzi, stavolta impreciso dall\u2019arco, e i 18 di Morel Pohl. I due totalizzano 2\/15 da tre punti.<\/p>\n<p><strong>Tutte le gare delle Finali Nazionali Kellogg\u2019s saranno trasmesse live sul canale Twitch della FIP a\u00a0<a href=\"https:\/\/www.twitch.tv\/italbasketofficial\" rel=\"nofollow noopener\" target=\"_blank\">questo link<\/a>\u00a0o su\u00a0<a href=\"https:\/\/www.youtube.com\/@fipbasketv\" rel=\"nofollow noopener\" target=\"_blank\">Youtube Italbasket<\/a>.<\/strong><\/p>\n<p><strong>Ufficio Stampa Fip Fvg<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"Terza giornata di gare a Udine per la Finale Nazionale Kellogg\u2019s Under 15 Eccellenza \u201cTrofeo Claudio Papini\u201d, le&hellip;\n","protected":false},"author":3,"featured_media":488146,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1453],"tags":[1756,1757,1537,90,89,245,244],"class_list":{"0":"post-488145","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-basket","8":"tag-basket","9":"tag-basketball","10":"tag-it","11":"tag-italia","12":"tag-italy","13":"tag-sport","14":"tag-sports"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116566544555909279","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/488145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=488145"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/488145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/488146"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=488145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=488145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=488145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}