{"id":488391,"date":"2026-05-13T12:45:15","date_gmt":"2026-05-13T12:45:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/488391\/"},"modified":"2026-05-13T12:45:15","modified_gmt":"2026-05-13T12:45:15","slug":"enel-cedola-in-aumento-del-4-e-buyback-da-15-miliardi-approvato-la-strategia","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/488391\/","title":{"rendered":"Enel, cedola in aumento del 4% e buyback da 1,5 miliardi approvato: la strategia"},"content":{"rendered":"<p>Si \u00e8 tenuta ieri, 12 maggio, la riunione degli azionisti di <strong>Enel<\/strong>, tra le principali aziende energetiche italiane ed ex monopolista di Stato, tuttora partecipata al 23,6% dal Ministero dell\u2019Economia e delle Finanze. L\u2019assemblea ha deciso per una <strong>cedola<\/strong> di 0,49 euro per azione, in aumento del 4% rispetto allo scorso anno.<\/p>\n<p>L\u2019azienda ha anche deciso di avviare un\u2019operazione di <strong>buyback<\/strong>, quindi di acquisto di azioni proprie, programmando di spendere circa 1,5 miliardi di euro. L\u2019assemblea degli azionisti ha anche approvato la nomina del consiglio di amministrazione, mentre Flavio Cattaneo sar\u00e0 riconfermato nel ruolo di amministratore delegato.\n<\/p>\n<p>La cedola di Enel a 0,49 euro ad azione<\/p>\n<p>Enel distribuir\u00e0 ai propri azionisti <strong>0,49 euro per azione di dividendo<\/strong>. Si tratta di un aumento del 4% rispetto alla cedola staccata nel 2024, che era stata di 0,47 euro ad azione. Il pagamento della cedola avverr\u00e0 il 20 luglio del 2026, e sar\u00e0 di 26 centesimi di euro ad azione, visto che l\u2019azienda ha gi\u00e0 staccato un dividendo di 0,23 euro a gennaio 2026.<\/p>\n<p>La cedola \u00e8 arrivata dopo l\u2019approvazione del bilancio da parte dell\u2019assemblea degli azionisti. Enel ha chiuso il 2025 con un <a href=\"https:\/\/quifinanza.it\/glossario\/utile\/\" rel=\"nofollow noopener\" target=\"_blank\">utile netto civilistico<\/a> di<strong> 3,07 miliardi di euro<\/strong>, in aumento rispetto ai 2,6 miliardi di euro fatti registrare l\u2019anno precedente.<\/p>\n<p>Il buyback di Enel<\/p>\n<p>Enel ha anche annunciato un\u2019importante operazione di <a href=\"https:\/\/quifinanza.it\/glossario\/buy-back\/\" rel=\"nofollow noopener\" target=\"_blank\">buyback<\/a>, acquisto di azioni proprie. L\u2019azienda comprer\u00e0 sul mercato 200mila azioni, per una spesa totale prevista attorno <strong>a 1,5 miliardi di euro<\/strong>. A seguito dell\u2019acquisto, che dovrebbe durare per i prossimi 18 mesi, le azioni saranno annullate.<\/p>\n<p>Si tratta di un\u2019operazione che serve ad <strong>aumentare il valore delle azioni<\/strong> che rimangono sul mercato. \u00c8, di fatto, un modo ulteriore per remunerare gli azionisti, oltre al dividendo, come spiega anche il comunicato diffuso dall\u2019azienda a seguito dell\u2019assemblea degli azionisti:<\/p>\n<blockquote>\n<p>Il buyback \u00e8 finalizzato a <strong>riconoscere agli azionisti una remunerazione aggiuntiva<\/strong> rispetto alla distribuzione dei dividendi e a operare sul mercato in un\u2019ottica di investimento a medio e lungo termine. L\u2019acquisto di azioni proprie \u00e8 stato autorizzato per diciotto mesi a decorrere dall\u2019odierna delibera assembleare.<\/p>\n<\/blockquote>\n<p>Il nuovo consiglio di amministrazione<\/p>\n<p>L\u2019assemblea degli azionisti ha anche nominato il nuovo consiglio di amministrazione, che rimarr\u00e0 in carica fino al 2028. Il <strong>Ministero dell\u2019Economia e delle Finanze<\/strong> ha indicato sei membri, tra cui:<\/p>\n<ul>\n<li>Paolo Scaroni, il presidente del CdA;<\/li>\n<li>Johanna Arbib;<\/li>\n<li>Flavio Cattaneo;<\/li>\n<li>Tiziana De Luca;<\/li>\n<li>Alessandro Monteduro;<\/li>\n<li>Federica Seganti.<\/li>\n<\/ul>\n<p>Gli altri componenti del <strong>consiglio di amministrazione<\/strong>, che sono stati indicati dagli altri azionisti dell\u2019azienda, saranno:<\/p>\n<ul>\n<li>Dario Frigerio;<\/li>\n<li>Mario Corsi;<\/li>\n<li>Alessandra Stabilini.<\/li>\n<\/ul>\n<p>La composizione del consiglio di amministrazione \u00e8 il risultato del sostegno ottenuto dalla lista presentata dal Mef, che ha ottenuto il sostegno di azionisti che detengono il 53,3% delle quote della societ\u00e0. Questo dovrebbe assicurare la nomina di <a href=\"https:\/\/quifinanza.it\/personaggi\/flavio-cattaneo\/\" rel=\"nofollow noopener\" target=\"_blank\">Flavio Cattaneo<\/a> ad <strong>amministratore<\/strong> <strong>delegato<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"Si \u00e8 tenuta ieri, 12 maggio, la riunione degli azionisti di Enel, tra le principali aziende energetiche italiane&hellip;\n","protected":false},"author":3,"featured_media":488392,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[178,177,32918,22566,173262,5430,1537,90,89],"class_list":{"0":"post-488391","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-affari","8":"tag-affari","9":"tag-business","10":"tag-conti-pubblici","11":"tag-enel","12":"tag-flavio-cattaneo","13":"tag-investimenti","14":"tag-it","15":"tag-italia","16":"tag-italy"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/488391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=488391"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/488391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/488392"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=488391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=488391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=488391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}