{"id":499651,"date":"2026-05-20T14:32:19","date_gmt":"2026-05-20T14:32:19","guid":{"rendered":"https:\/\/www.europesays.com\/it\/499651\/"},"modified":"2026-05-20T14:32:19","modified_gmt":"2026-05-20T14:32:19","slug":"alpecin-premier-tech-mistero-mathieu-van-der-poel-annunciato-al-via-della-prova-di-mtb-di-novo-mesto-ma-la-squadra-smentisce","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/499651\/","title":{"rendered":"Alpecin-Premier Tech, mistero Mathieu Van der Poel: annunciato al via della prova di MTB di Novo Mesto, ma la squadra smentisce"},"content":{"rendered":"<p>\t\t<img width=\"1200\" height=\"800\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/04\/Mathieu-Van-Der-Poel-Podio-Giro-delle-Fiandre-2026.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" data-main-img=\"1\" decoding=\"async\" fetchpriority=\"high\"  \/><\/p>\n<p>\t\t\t\t\t\t\t \u00a9 Sirotti<\/p>\n<p>\t\t\t\t\t<a href=\"https:\/\/cyclingpro.net\/spaziociclismo\/altro\/scopri-lapp-ufficiale-di-spaziociclismo\/\" title=\"\" rel=\"nofollow noopener\" target=\"_blank\"><br \/>\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/09\/1758060682_662_Banner-App-SpazioCiclismo.png\" alt=\"\" width=\"728\" height=\"91\"\/><br \/>\n\t\t\t\t\t<\/a><\/p>\n<p><strong>Mathieu Van der Poel<\/strong> non parteciper\u00e0 alla prova delle <strong>UCI Mountain Bike Pro Series<\/strong> in programma il 24 maggio a <strong>Novo Mesto<\/strong>. Una conferma che arriva direttamente dalla sua squadra, la <strong>Alpecin \u2013 Premier Tech<\/strong>, dopo che nelle ultime ore si erano succedute numerose indiscrezioni. Ad aprire il fronte un post sulla pagina Instagram dell\u2019organizzazione che ha annunciato la presenza del fuoriclasse olandese, in un possibile duello con Tom Pidcock che, viceversa, dovrebbe essere della partita. Tuttavia secondo quanto appreso da <a href=\"https:\/\/www.cyclingnews.com\/pro-cycling\/teams-riders\/no-mathieu-van-der-poel-wont-be-racing-the-mtb-world-cup-this-weekend-despite-organisers-announcement\/\" rel=\"nofollow noopener\" target=\"_blank\">Cyclingnews<\/a>, non \u00e8 mai arrivato il via libera da parte della sua squadra e anche il corridore, che aveva lasciato una porta socchiusa circa una sua partecipazione, non aveva dato garanzie.<\/p>\n<p>Tra l\u2019altro lo scorso anno proprio nella prova di Novo Mesto, Mathieu Van der Poel cadde provocandosi la frattura dello scafoide. Infortunio che non gli imped\u00ec comunque di essere al via del Tour de France, dove fu protagonista con una vittoria nella seconda tappa e quattro giorni in maglia gialla.<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/DYhi4qeDNLB\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<p>\u00a0<\/p>\n<\/blockquote>\n<p>Seguici<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/news.google.com\/publications\/CAAqBwgKMNaVhQswhaiCAw?hl=it&amp;gl=IT&amp;ceid=IT%3Ait\" title=\"Google News\" target=\"_blank\" rel=\"nofollow noopener\" class=\"post-followus-btn google-new-btn\"><br \/>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/themes\/jannah\/assets\/images\/google-news.svg\" alt=\"Google News\" loading=\"lazy\" width=\"120\" height=\"22\"\/><br \/>\n\t\t\t\t\t<\/a><br \/>\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/flipboard.com\/@SpazioCiclismo\" title=\"Flipboard\" target=\"_blank\" rel=\"nofollow noopener\" class=\"post-followus-btn flipboard-btn\"><br \/>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/cyclingpro.net\/spaziociclismo\/wp-content\/themes\/jannah\/assets\/images\/flipboard.svg\" alt=\"Flipboard\" loading=\"lazy\" width=\"152\" height=\"30\"\/><br \/>\n\t\t\t\t\t<\/a><\/p>\n<p>\t<script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"\u00a9 Sirotti Mathieu Van der Poel non parteciper\u00e0 alla prova delle UCI Mountain Bike Pro Series in programma&hellip;\n","protected":false},"author":3,"featured_media":467816,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1456],"tags":[145622,1824,1825,1537,90,89,2359,35389,245,244],"class_list":["post-499651","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ciclismo","tag-alpecin-premier-tech-2026","tag-ciclismo","tag-cycling","tag-it","tag-italia","tag-italy","tag-mathieu-van-der-poel","tag-mtb","tag-sport","tag-sports"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/116607395854685306","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/499651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=499651"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/499651\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/467816"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=499651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=499651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=499651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}