{"id":569285,"date":"2026-07-04T12:18:15","date_gmt":"2026-07-04T12:18:15","guid":{"rendered":"https:\/\/www.europesays.com\/it\/569285\/"},"modified":"2026-07-04T12:18:15","modified_gmt":"2026-07-04T12:18:15","slug":"f1-gp-silverstone-2026-la-sprint-race-in-diretta-antonelli-vince-davanti-a-hamilton-e-norris-che-bello-lottare-con-lewis-leclerc-quinto","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/569285\/","title":{"rendered":"F1 Gp Silverstone 2026: la Sprint race in diretta. Antonelli vince davanti a Hamilton e Norris: \u00abChe bello lottare con Lewis\u00bb. Leclerc quinto"},"content":{"rendered":"<p>\t\t\tKimi trionfa nel duello bellissimo contro Hamilton, ma \u00e8 solo il primo atto. Rimpianti Leclerc, risorge Norris.<\/p>\n<p>(Daniele Sparisci, inviato a Silverstone) Taglia il traguardo a zig-zag, urlando \u00abLet\u2019s go\u00bb. Dalla radio irrompe Toto Wolff: \u00abKimi, ti sei divertito a fare il giro veloce alla fine?\u00bb. Risposta: \u00abS\u00ec, mi ha dato proprio gusto, ancora meglio\u00bb.<\/p>\n<p>Eccolo il vero Antonelli, al quale non basta vincere: deve lanciare messaggi. Non a Hamilton, gran secondo posto comunque su una Ferrari che aveva fatto la pole contro ogni pronostico. Kimi parla a Russell, quarto e di nuovo alle prese con difficolt\u00e0 che sembrava aver archiviato in Austria. Il leader del Mondiale ha guadagnatot tre punti sul compagno si porta a +43.\u00a0<\/p>\n<p>Il 19enne bolognese conquista la sua prima vittoria in una gara Sprint dopo un bellissimo e intenso duello con Hamilton.\u00a0\u00abAbbiamo fatto 17 giri a tavoletta, mi sono divertito veramente. Ho usato qualsiasi cosa avessi per passarlo. Non possiamo abbassare la guardia \u00a0Lewis e la Ferrari stanno facendo un lavoro incredibile, la Red Bull e la McLaren stanno recuperando terrenoe George \u00e8 velocissimo. Quindi dobbiamo continuare ad alzare<br \/>l&#8217;asticella e a migliorare\u00bb.\u00a0 Ci aveva provato subito al via, ma Lewis con una manovra aggressiva lo aveva respinto. Ha aspettato, sfruttando il passo superiore della Mercedes (i valori sono emersi nell\u2019arco dei 17 giri), e alla fine ha piazzato un colpo pulito in rettilineo senza concedere possibilit\u00e0 di replica al ferrarista, che comunque \u00e8 soddisfatto: \u00abAbbiamo fatto una bella lotta, la macchina andava veramente. Anche io mi sono divertito, ho spinto al massimo per tenere il vantaggio sopra il secondo ma non \u00e8 bastato\u00bb.\u00a0<\/p>\n<p>\u00c8 stata una fuga a due, gli altri hanno assistito da lontano e si sono limitati alle scaramucce per i posti dietro al podio. Si \u00e8 rivista la McLaren: Norris, protagonista di uno start eccezionale, ha infilato quasi tutti e sfruttato i soliti limiti in partenza della Red Bull. Di nuovo Verstappen si \u00e8 piantato. Anche a Leclerc \u00e8 andata male: \u00e8 scivolato da quarto a settimo, per poi recuperare due posizioni con una garetta di grinta e rimpianti.<\/p>\n","protected":false},"excerpt":{"rendered":"Kimi trionfa nel duello bellissimo contro Hamilton, ma \u00e8 solo il primo atto. Rimpianti Leclerc, risorge Norris. (Daniele&hellip;\n","protected":false},"author":3,"featured_media":569286,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[176],"tags":[23684,121907,3429,11152,225515,8911,26629,26630,3356,3993,123573,50932,313753,121901,263531,225520,184779,313754,2941,6717,26632,765,313755,313756,3359,2233,4990,25346,225523,3986,313747,3361,3342,6708,10871,5376,86879,2238,368,629,12726,4034,6236,3369,123581,313748,12729,56864,10862,3345,313170,12877,3336,6874,313749,3346,3337,226853,313746,1537,90,89,3994,4043,26625,381,7754,112191,2312,2244,4044,3443,5993,1772,10861,7255,3671,10859,98,25336,12715,3352,3007,559,10331,4005,40855,313750,2915,50964,245,244,6228,313751,313752,12717,3413,3481,10870,10860,13062,2224,4318,313178,313179],"class_list":["post-569285","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sport","tag-albon","tag-albon-williams","tag-alexander","tag-alexander-albon","tag-alexander-albon-williams","tag-alonso","tag-alonso-aston","tag-alonso-aston-martin","tag-alpine","tag-antonelli","tag-antonelli-giro","tag-antonelli-hamilton","tag-antonelli-hamilton-norris","tag-antonelli-mercedes","tag-antonelli-vince","tag-arvid","tag-arvid-lindblad","tag-arvid-lindblad-racing","tag-aston","tag-aston-martin","tag-aston-martin-lance","tag-attacco","tag-attacco-partenza","tag-attacco-russell","tag-audi","tag-battaglia","tag-bellissimo","tag-bortoleto","tag-bortoleto-audi","tag-bretagna","tag-bretagna-silverstone","tag-bull","tag-bulls","tag-cadillac","tag-charles","tag-difficolta","tag-divertito","tag-duello","tag-ferrari","tag-gara","tag-gara-sprint","tag-george","tag-giri","tag-giro","tag-giro-antonelli","tag-giro-kimi","tag-giro-leclerc","tag-giro-veloce","tag-gomme","tag-gp","tag-gp-gran","tag-gp-gran-bretagna","tag-gran","tag-gran-bretagna","tag-gran-bretagna-silverstone","tag-haas","tag-hamilton","tag-hamilton-antonelli","tag-hamilton-norris","tag-it","tag-italia","tag-italy","tag-kimi","tag-kimi-antonelli","tag-lawson","tag-leader","tag-leclerc","tag-leclerc-verstappen","tag-lewis","tag-lewis-hamilton","tag-macchina","tag-martin","tag-mclaren","tag-mercedes","tag-norris","tag-partenza","tag-passa","tag-piastri","tag-porta","tag-quinto","tag-race","tag-racing","tag-racing-bulls","tag-red","tag-red-bull","tag-russell","tag-russell-leclerc","tag-russell-leclerc-verstappen","tag-silverstone","tag-spingere","tag-sport","tag-sports","tag-sprint","tag-sprint-gp","tag-sprint-gp-gran","tag-sprint-race","tag-top","tag-vantaggio","tag-veloce","tag-verstappen","tag-vince","tag-vittoria","tag-williams","tag-williams-alexander","tag-williams-alexander-albon"],"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/569285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=569285"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/569285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/569286"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=569285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=569285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=569285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}