{"id":57413,"date":"2025-08-20T03:31:10","date_gmt":"2025-08-20T03:31:10","guid":{"rendered":"https:\/\/www.europesays.com\/it\/57413\/"},"modified":"2025-08-20T03:31:10","modified_gmt":"2025-08-20T03:31:10","slug":"incidente-a-san-casciano-paura-sullautopalio-tra-i-feriti-anche-dei-bambini","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/57413\/","title":{"rendered":"Incidente a San Casciano, paura sull\u2019Autopalio. Tra i feriti anche dei bambini"},"content":{"rendered":"<p>Firenze, 19 agosto 2025 \u2013<strong>\u00a0Brutto incidente<\/strong> sulla <strong>Firenze-Siena<\/strong> avvenuto nella tarda serata di oggi, 19 agosto. Secondo le prime informazioni sono due\u00a0i mezzi coinvolti nello scontro frontale che si \u00e8 verificato nei pressi dell\u2019uscita San Casciano intorno alle 22.<\/p>\n<p> <img alt=\"\" loading=\"lazy\" width=\"1600\" height=\"1200\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;max-width:100%;height:auto\"   src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/08\/1755660670_786_image.webp\"\/> <\/p>\n<p>L\u2019Autopalio \u00e8 stata chiusa in entrambe le direzioni fino a tarda notte. Dalle prime informazioni sarebbero coinvolte almeno 7 persone tra cui una famiglia di turisti con dei bambini. I feriti sono stati trasportati all\u2019ospedale di Torregalli con le ambulanze del 118. Non sarebbero in gravi condizioni.\u00a0Sul posto, oltre ai soccorritori, la polizia stradale di Siena e il personale Sicurverde. La strada \u00e8 stata chiusa per consentire le operazioni di soccorso. Lunghe code si sono formate in entrambe i sensi di marcia.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Firenze, 19 agosto 2025 \u2013\u00a0Brutto incidente sulla Firenze-Siena avvenuto nella tarda serata di oggi, 19 agosto. Secondo le&hellip;\n","protected":false},"author":3,"featured_media":57414,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[79],"tags":[46529,788,39814,14,93,94,826,298,1537,90,89,7,15,5238,532,11,84,91,12,85,92],"class_list":["post-57413","post","type-post","status-publish","format-standard","has-post-thumbnail","category-italia","tag-autopalio","tag-bambini","tag-casciano","tag-cronaca","tag-cronaca-italiana","tag-cronacaitaliana","tag-feriti","tag-incidente","tag-it","tag-italia","tag-italy","tag-news","tag-notizie","tag-paura","tag-san","tag-ultime-notizie","tag-ultime-notizie-e-news-di-oggi","tag-ultime-notizie-italia","tag-ultimenotizie","tag-ultimenotizieenewsdioggi","tag-ultimenotizieitalia"],"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/57413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=57413"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/57413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/57414"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=57413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=57413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=57413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}