{"id":57694,"date":"2025-08-20T07:07:11","date_gmt":"2025-08-20T07:07:11","guid":{"rendered":"https:\/\/www.europesays.com\/it\/57694\/"},"modified":"2025-08-20T07:07:11","modified_gmt":"2025-08-20T07:07:11","slug":"carambola-tra-moto-un-furgone-e-due-auto-morta-una-36enne","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/57694\/","title":{"rendered":"carambola tra moto, un furgone e due auto. Morta una 36enne"},"content":{"rendered":"<p>Gioia Fioravanti, una donna di 36 anni, \u00e8 morta in un incidente stradale sull&#8217;Aurelia, all&#8217;altezza del km 36,600 della consolare presso Palo Laziale. La vittima era in sella alla sua moto quando, per cause da accertare, si \u00e8 scontrata prima con un furgone e poi con una Fiat Panda e una Peugeot. Un impatto fatale avvenuto poco dopo le 18 di marted\u00ec 19 agosto.\u00a0<\/p>\n<p>Sul posto la polizia locale e i carabinieri che hanno identificato la vittima. Nel tratto dell&#8217;Aurelia sono giunti anche i vigili del fuoco e due ambulanze. Gioia Fioravanti, tuttavia, \u00e8 morta sul colpo. Gli altri conducenti sono stati portati al San Paolo di Civitavecchia e uno all\u2019Aurelia Hospital, tutti per lievi escoriazioni, in stato di choc.\u00a0<\/p>\n<p>La morte del fidanzato<\/p>\n<p>Un dramma che si somma al dramma. Gi\u00e0, perch\u00e9 Gioia (e i suoi conoscenti) alcuni giorni fa ha vissuto un grande lutto, quello del fidanzato Daniele, i cui funerali sono in programma gioved\u00ec 21 agosto nella parrocchia di San Martino Vescovo. A lui sono dedicati gli ultimi post pubblici di Gioia su Facebook. Ora su quella stessa bacheca ci sono i messaggi di cordoglio proprio per la morte della 36enne.\u00a0<\/p>\n<p><a href=\"https:\/\/www.romatoday.it\/cronaca\/incidente-stradale\/alessandro-loschiavo-morto-aurelia-capalbio-19-agosto-2025.html\" target=\"_blank\" rel=\"nofollow noopener\">Alessandro Loschiavo, il designer romano morto in un incidente stradale a Capalbio<\/a>Comunit\u00e0 in lutto\u00a0<\/p>\n<p>\u201cIl vostro amore era talmente forte che il destino, beffardo e crudele, \u00e8 andato contro ogni logica umana pur di farvi stare di nuovo insieme\u201d, ha scritto Rene\u00e9. \u201cUn&#8217;anima immensa, forte come poche ne conosco. \u00c8 stato un onore per me averti incontrata e percorso insieme le nostre strade. Ti porter\u00f2 sempre con me\u201d, il messaggio di Elisabetta. La salma di Gioia Fioravanti \u00e8 stata portata al cimitero del Verano per l&#8217;autopsia.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Gioia Fioravanti, una donna di 36 anni, \u00e8 morta in un incidente stradale sull&#8217;Aurelia, all&#8217;altezza del km 36,600&hellip;\n","protected":false},"author":3,"featured_media":57695,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[79],"tags":[14,93,94,1537,90,89,770,7,15,23260,11,84,91,12,85,92],"class_list":["post-57694","post","type-post","status-publish","format-standard","has-post-thumbnail","category-italia","tag-cronaca","tag-cronaca-italiana","tag-cronacaitaliana","tag-it","tag-italia","tag-italy","tag-morti","tag-news","tag-notizie","tag-stradali","tag-ultime-notizie","tag-ultime-notizie-e-news-di-oggi","tag-ultime-notizie-italia","tag-ultimenotizie","tag-ultimenotizieenewsdioggi","tag-ultimenotizieitalia"],"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/57694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=57694"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/57694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/57695"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=57694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=57694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=57694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}