{"id":62070,"date":"2025-08-22T10:36:09","date_gmt":"2025-08-22T10:36:09","guid":{"rendered":"https:\/\/www.europesays.com\/it\/62070\/"},"modified":"2025-08-22T10:36:09","modified_gmt":"2025-08-22T10:36:09","slug":"gli-affari-poco-chiari-del-genero-di-trump-tra-superyacht-e-miliardari-sauditi","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/62070\/","title":{"rendered":"Gli affari poco chiari del genero di Trump, tra superyacht e miliardari sauditi"},"content":{"rendered":"<p>    di<br \/>\n    Guido De Franceschi<\/p>\n<p class=\"summary-art is-line-h-12\">Michael Boulos \u00e8 il marito di Tiffany, la \u00abfiglia dimenticata\u00bb del presidente. E (con tutta la sua famiglia) avrebbe approfittato di questa parentela acquisita per arricchirsi<\/p>\n<p class=\"chapter-paragraph\"><b>Uno dei generi del presidente americano Donald Trump, Michael Boulos, avrebbe a pi\u00f9 riprese approfittato per il proprio tornaconto personale dell\u2019importante parentela acquisita<\/b>. Lo racconta un\u2019approfondita inchiesta del New York Times che ha scavato in varie operazioni finanziarie, apparentemente un po\u2019 opache, condotte negli ultimi quattro anni dal marito di Tiffany Trump. Nata nel 1993 da Trump e dalla sua seconda moglie, l\u2019attrice Marla Maples (lei e Donald si sposarono due mesi dopo la nascita della loro unica figlia per poi divorziare nel 1999), <a href=\"https:\/\/www.corriere.it\/foto-gallery\/moda\/21_gennaio_20\/chi-tiffany-trump-figlia-27-enne-donald-f54677da-5b06-11eb-92e1-bb138da514c2.shtml\" target=\"_blank\" rel=\"nofollow noopener\">Tiffany<\/a> \u00e8 cresciuta con la madre in California ed \u00e8 rimasta per molti anni lontana dai riflettori. Anche per questo \u00e8 stata spesso definita dai media americani <b>\u00abthe forgotten daughter\u00bb, ovvero \u00abla figlia dimenticata\u00bb di Trump<\/b>. E, quando nel 2019 il presidente, allora al suo primo mandato, <a href=\"https:\/\/www.corriere.it\/esteri\/19_agosto_30\/parla-presidente-coi-reporter-cacciata-l-assistente-personale-trump-47a15a04-cad5-11e9-9881-63e9a7b3e050.shtml\" target=\"_blank\" rel=\"nofollow noopener\">licenzi\u00f2<\/a> la sua segretaria personale Madeleine Westerhout per aver violato il suo obbligo alla privacy parlando con dei giornalisti, Politico scrisse che l\u2019assistente aveva rivelato che<b> il presidente non amava essere fotografato a fianco di Tiffany perch\u00e9 la riteneva in sovrappeso<\/b>.<\/p>\n<p class=\"chapter-paragraph\">Secondo il New York Times, fin dal giorno del suo fidanzamento con Tiffany, avvenuto nel gennaio del 2021, B<b>oulos avrebbe cercato di approfittare della sua posizione per tentare di fare qualche affare lucroso dai contorni un po\u2019\u00a0borderline.<\/b> Una delle sue prime \u00abvittime\u00bb sarebbe stato il suo futuro cognato<b> Jared Kushner,<\/b> sposato con un\u2019altra figlia di Trump, Ivanka &#8211; e a sua volta accusato di essere un esempio di nepotismo, dal momento che si sarebbe giovato della parentela con Trump per ottenere dei ruoli rilevanti all\u2019interno dell\u2019amministrazione.<b> Boulos e suo cugino Jimmy Frangi avrebbero coinvolto Kushner nell\u2019acquisto di un superyacht <\/b>la cui costruzione non era stata ancora completata, con l\u2019obiettivo di terminarlo e poi rivenderlo con un importante margine di guadagno. Secondo l\u2019inchiesta del New York Times, oltre a incassare una provvigione per l\u2019intermediazione, <b>i due cugini (o quantomeno Frangi),\u00a0a insaputa di Kushner, avrebbero gonfiato di un paio di milioni di dollari la cifra di acquisto dello yacht per trattenere la differenza con l\u2019inganno<\/b>. Boulos e Frangi hanno incassato rispettivamente 300 e 400 mila dollari per la loro attivit\u00e0 di brokeraggio, ma lo yacht, a distanza di tre anni, pur avendo ricevuto un nome (Solstice) langue ancora in Grecia, senza che i lavori siano stati terminati. Tutti gli interessati hanno negato alcuna malversazione.    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\">La seconda vicenda su cui si \u00e8 concentrata l\u2019attenzione del New York Times riguarda <b>il miliardario saudita Abdulelah Allam<\/b>, che vive negli Stati Uniti in un esilio auto-imposto. Anche in questo caso sarebbe coinvolto Frangi, il cugino di Boulos. Allam, con cui Frangi avrebbe accumulato un ingente debito, aveva l\u2019esigenza di recuperare il suo enorme patrimonio immobiliare in patria, che gli era stato sequestrato nel 2017 in seguito a un\u2019operazione anticorruzione sollecitata dal principe ereditario saudita Mohammad bin Salman. <b>Frangi e Boulos, in cambio dell\u2019estinzione del debito contratto dal primo con Allam, avrebbero maneggiato per invitare il miliardario saudita al matrimonio di Michael con Tiffany<\/b>, poi <a href=\"https:\/\/video.corriere.it\/spettacoli\/trump-accompagna-figlia-tiffany-all-altare-poi-balla-lei-immagini-matrimonio-mar-a-lago\/3a994030-6409-11ed-ae97-6a46826173e7\" target=\"_blank\" rel=\"nofollow noopener\">avvenuto nel 2022<\/a> nel golf club di Mar-a-Lago di propriet\u00e0 di Trump. L\u2019idea era di creare una photo opportunity per Allam: <b>comparendo in qualche immagine accanto a Trump, il saudita avrebbe potuto vantare una sua presunta vicinanza con l\u2019allora ex presidente americano<\/b> e, in grazia di questa amicizia, avrebbe forse potuto tornare in possesso dei suoi beni in patria. Anche in questo caso l\u2019operazione non \u00e8 riuscita: Allam non \u00e8 stato invitato al matrimonio e non ha recuperato le sue propriet\u00e0. Ma dai suoi conti sarebbero comunque arrivati a Boulos 100 mila dollari, che sono stati poi giustificati come il pagamento di un debito pregresso.<\/p>\n<p class=\"chapter-paragraph\">Anche il padre di Michael, Massad Boulos, si sarebbe avvantaggiato della parentela acquisita con Trump. Businessman appartenente a una vasta famiglia di origine libanese, <b>Massad Boulos, ceo di una azienda nigeriana controllata dal suocero che vende camion e macchinari di vario tipo nel Paese africano, veniva descritto dai giornali come un imprenditore molto ricco<\/b>. Ma poi, un\u2019altra inchiesta del New York Times, pubblicata l\u2019anno scorso, ha scoperto che le sue quote nell\u2019azienda del suocero ammontavano a meno di 2 dollari. In ogni caso, <b>durante la campagna di Trump per le elezioni presidenziali dell\u2019anno scorso, Boulos senior si \u00e8 speso molto per raccogliere voti per lui all\u2019interno delle comunit\u00e0 arabo-americane<\/b>. Boulos ha agito soprattutto in Michigan, uno Stato determinante in cui Trump ha poi vinto di stretta misura su Kamala Harris e in cui quattro anni prima aveva invece perso la sfida con Joe Biden.<\/p>\n<p class=\"chapter-paragraph\"><b>Dopo la vittoria di Trump, Massad Boulos \u00e8 stato nominato consigliere presidenziale per il Medio Oriente e poi senior adviser presso il Dipartimento di Stato per l\u2019Africa.<\/b> E, anche in questo caso, emerge un ruolo del figlio Michael. L\u2019ex premier della Guinea, Lansana Kouyat\u00e9, ha detto in alcune interviste che Boulos junior, dopo che il padre ha ricevuto l\u2019incarico di consigliere per l\u2019Africa, ha iniziato subito a darsi un certo daffare per \u00abmettere in contatto degli investitori statunitensi con alcuni governi africani\u00bb. Poi Kouyat\u00e9 ha smentito tutto. Nel frattempo, il 15 maggio di quest\u2019anno, <b>Michael Boulos e Tiffany, hanno dato a Trump un altro nipote: Alexander<\/b>.<\/p>\n<p class=\"is-last-update\" datetime=\"2025-08-22T11:32:13+02:00\">22 agosto 2025<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Guido De Franceschi Michael Boulos \u00e8 il marito di Tiffany, la \u00abfiglia dimenticata\u00bb del presidente. E (con&hellip;\n","protected":false},"author":3,"featured_media":62071,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[160],"tags":[49334,2842,3623,49332,2537,536,49341,4613,4072,49329,17518,41,14,11017,164,165,6008,13613,3761,1113,1909,3384,49342,49331,48,51,49335,49336,955,49343,17582,7242,49344,49337,49338,8866,1949,49339,38422,49345,166,11040,11041,16859,7,15,811,3608,49333,49340,20021,858,11045,135,3791,14154,18147,49330,6504,379,11,167,12,168,161,162,163,16860,16861],"class_list":{"0":"post-62070","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mondo","8":"tag-acquisita","9":"tag-acquisto","10":"tag-africa","11":"tag-allam","12":"tag-altra","13":"tag-americano","14":"tag-approfittato","15":"tag-avvenuto","16":"tag-azienda","17":"tag-boulos","18":"tag-coinvolto","19":"tag-consigliere","20":"tag-cronaca","21":"tag-cugino","22":"tag-dal-mondo","23":"tag-dalmondo","24":"tag-debito","25":"tag-dimenticata","26":"tag-dollari","27":"tag-donald","28":"tag-famiglia","29":"tag-figlia","30":"tag-figlia-dimenticata","31":"tag-frangi","32":"tag-importante","33":"tag-inchiesta","34":"tag-inchiesta-new","35":"tag-inchiesta-new-york","36":"tag-interno","37":"tag-kouyate","38":"tag-kushner","39":"tag-marito","40":"tag-marito-tiffany","41":"tag-massad","42":"tag-massad-boulos","43":"tag-matrimonio","44":"tag-michael","45":"tag-michael-boulos","46":"tag-miliardario","47":"tag-miliardario-saudita","48":"tag-mondo","49":"tag-new","50":"tag-new-york","51":"tag-new-york-times","52":"tag-news","53":"tag-notizie","54":"tag-operazione","55":"tag-padre","56":"tag-parentela","57":"tag-parentela-acquisita","58":"tag-patria","59":"tag-personale","60":"tag-potuto","61":"tag-presidente","62":"tag-presidente-americano","63":"tag-proprieta","64":"tag-saudita","65":"tag-tiffany","66":"tag-times","67":"tag-trump","68":"tag-ultime-notizie","69":"tag-ultime-notizie-di-mondo","70":"tag-ultimenotizie","71":"tag-ultimenotiziedimondo","72":"tag-world","73":"tag-world-news","74":"tag-worldnews","75":"tag-york","76":"tag-york-times"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/62070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=62070"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/62070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/62071"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=62070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=62070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=62070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}