{"id":659223,"date":"2026-09-01T06:28:22","date_gmt":"2026-09-01T06:28:22","guid":{"rendered":"https:\/\/www.europesays.com\/it\/659223\/"},"modified":"2026-09-01T06:28:22","modified_gmt":"2026-09-01T06:28:22","slug":"emergenza-influenza-aviaria-in-australia-scatta-il-piano-di-vaccinazione-per-5-000-pinguini-minori-blu","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/659223\/","title":{"rendered":"Emergenza influenza aviaria in Australia: scatta il piano di vaccinazione per 5.000 pinguini minori blu"},"content":{"rendered":"<p>    di<br \/>\n    Silvia Morosi<\/p>\n<p class=\"summary-art is--xlarge is-mr-b-25\">A Phillip Island, e nella localit\u00e0 balneare di St. Kilda, le autorit\u00e0 hanno iniziato le vaccinazioni per difendere gli esemplari dalla rapida avanzata del virus<\/p>\n<p class=\"chapter-paragraph\">L&#8217;Austrlia ha avviato una vera e propria corsa contro il tempo per proteggere una delle pi\u00f9 importanti colonie di <b>pinguino minore blu\u00a0<\/b>(Eudyptula minor)\u00a0dall&#8217;influenza aviaria, individuata per la prima volta a giugno. A Phillip Island, nello Stato di Victoria, circa 1.000 esemplari hanno gi\u00e0 ricevuto la prima dose del vaccino contro il virus H5N1, mentre il programma punta a raggiungere complessivamente 5mila animali tra Phillip Island e la spiaggia di St. Kilda.\u00a0<\/p>\n<p class=\"chapter-paragraph\">La specie \u00e8 gi\u00e0 colpita da violente tempeste, innalzamento del livello del mare e variazioni nella disponibilit\u00e0 di cibo causate dalla crisi climatica.    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\">Secondo i dati disponibili, si tratterebbe della pi\u00f9 grande campagna vaccinale mai avviata al mondo su degli uccelli selvatici.\u00a0L\u2019allarme \u00e8 scattato dopo che, il 15 agosto, era stato identificato <b>il primo pinguino malato. <\/b>In realt\u00e0, la grande epidemia di influenza aviaria \u00e8 in corso gi\u00e0 da circa sei anni, ma in Australia \u00e8 arrivata solo lo scorso giugno. Gli esemplari vengono intercettati la sera mentre risalgono dalla spiaggia, trattenuti\u00a0 per l\u2019iniezione e l\u2019identificazione con microchip, e poi rilasciati. La somministrazione prevede <b>un ciclo a due dosi <\/b>a distanza di tre o quattro settimane.\u00a0\u00ab\u00c8 la prima volta che qualcuno al mondo tenta un&#8217;impresa del genere su questa scala\u00bb, ha spiegato\u00a0Catherine Basterfield, amministratrice delegata di Phillip Island Nature Parks, al\u00a0Guardian.\u00a0\u00abI pinguini risalgono la spiaggia e cos\u00ec \u00e8 possibile <b>radunarli in un piccolo recinto <\/b>e poi trasferirli in recinti pi\u00f9 piccoli per procedere alla somministrazione del vaccino\u00bb.\u00a0<\/p>\n<p class=\"chapter-paragraph\"><b>Questi pinguini sono la specie di pi\u00f9 piccola al mondo<\/b> e sono alti circa 30 centimetri. Si trovano<b> sono nell&#8217;Australia meridionale e in Nuova Zelanda. Misurano circa\u00a0<\/b>40 centimetri di altezza e pesano tra gli 0,7 e i 2 chilogrammi: sono caratterizzati da un piumaggio\u00a0grigio tendente al bluastro sul dorso.<\/p>\n<p class=\"chapter-paragraph\">Intanto, il governo del Nuovo Galles del Sud ha avviato un programma mirato per specie di uccelli vulnerabili,  proprio per proteggerli dall&#8217;influenza aviaria H5.\u00a0Saranno vaccinate sia popolazioni in cattivit\u00e0, che selvatiche come i pinguini minori blu di Manly e dell&#8217;isola di Barunguba Montague.<\/p>\n<p class=\"chapter-paragraph\">E anche la Nuova Zelanda ha <b>avviato campagne di vaccinazione <\/b>per le sue specie pi\u00f9 rare e minacciate.<\/p>\n<p>        <img decoding=\"async\" class=\"is_full_image\" loading=\"lazy\" alt=\"Emergenza influenza aviaria in Australia: scatta il piano di vaccinazione per 5.000 pinguini minori blu\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/09\/6a95873de4e3f.jpeg\" data-full-src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/09\/6a95873de4e3f.jpeg\"\/><\/p>\n<p>        <img decoding=\"async\" class=\"is_full_image\" loading=\"lazy\" alt=\"Emergenza influenza aviaria in Australia: scatta il piano di vaccinazione per 5.000 pinguini minori blu\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/09\/6a959d877313c.png\" data-full-src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/09\/6a959d877313c.png\"\/><\/p>\n<p>        <img decoding=\"async\" class=\"is_full_image\" loading=\"lazy\" alt=\"Emergenza influenza aviaria in Australia: scatta il piano di vaccinazione per 5.000 pinguini minori blu\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/09\/6a959d96f29cb.png\" data-full-src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/09\/6a959d96f29cb.png\"\/><\/p>\n<p>        <img decoding=\"async\" class=\"is_full_image\" loading=\"lazy\" alt=\"Emergenza influenza aviaria in Australia: scatta il piano di vaccinazione per 5.000 pinguini minori blu\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/09\/6a959db39d1c9.png\" data-full-src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/09\/6a959db39d1c9.png\"\/><\/p>\n<p>        <img decoding=\"async\" class=\"is_full_image\" loading=\"lazy\" alt=\"Emergenza influenza aviaria in Australia: scatta il piano di vaccinazione per 5.000 pinguini minori blu\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/09\/6a959dd3e78da.png\" data-full-src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2026\/09\/6a959dd3e78da.png\"\/><\/p>\n<p>Per ricevere tutti gli aggiornamenti sul mondo degli animali<br \/>Iscrivetevi alla <a href=\"https:\/\/www.corriere.it\/newsletter\/?theme=70\" rel=\"nofollow noopener\" target=\"_blank\">newsletter Animali<\/a><\/p>\n<p class=\"is-last-update\" datetime=\"2026-08-31T17:29:44+02:00\">31 agosto 2026 ( modifica il 31 agosto 2026 | 17:29)<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Silvia Morosi A Phillip Island, e nella localit\u00e0 balneare di St. Kilda, le autorit\u00e0 hanno iniziato le&hellip;\n","protected":false},"author":3,"featured_media":659224,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[175],"tags":[3631,21670,4431,14807,22997,17781,1148,239,7944,21671,8203,1537,90,89,363625,13750,363626,273,20272,363624,94820,261618,363627,363628,9141,897,240,4739,13498],"class_list":["post-659223","post","type-post","status-publish","format-standard","has-post-thumbnail","category-salute","tag-australia","tag-aviaria","tag-avviato","tag-blu","tag-centimetri","tag-esemplari","tag-giugno","tag-health","tag-influenza","tag-influenza-aviaria","tag-island","tag-it","tag-italia","tag-italy","tag-kilda","tag-minori","tag-minori-blu","tag-nuova","tag-nuova-zelanda","tag-phillip","tag-phillip-island","tag-pinguini","tag-pinguini-minori","tag-pinguini-minori-blu","tag-pinguino","tag-programma","tag-salute","tag-specie","tag-spiaggia"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/117194373824342667","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/659223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=659223"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/659223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/659224"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=659223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=659223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=659223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}