{"id":659974,"date":"2026-09-01T16:18:17","date_gmt":"2026-09-01T16:18:17","guid":{"rendered":"https:\/\/www.europesays.com\/it\/659974\/"},"modified":"2026-09-01T16:18:17","modified_gmt":"2026-09-01T16:18:17","slug":"wiki-loves-puglia-2026-al-via-il-concorso-fotografico","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/659974\/","title":{"rendered":"Wiki Loves Puglia 2026: al via il concorso fotografico"},"content":{"rendered":"<p>Parte <strong>l&#8217;ottava edizione di Wiki Loves Puglia<\/strong>, edizione locale di <strong>Wiki Loves Monuments<\/strong>, il concorso fotografico organizzato ogni anno dai volontari di Wikimedia Italia. L&#8217;iniziativa coinvolge fotografi professionisti e amatoriali con l&#8217;obiettivo di documentare il patrimonio e la bellezza pugliese e italiana su Wikimedia Commons, Wikipedia e i progetti fratelli.<\/p>\n<p>L\u2019iniziativa \u00e8 stata presentata questa mattina a Palazzo della Citt\u00e0 dall\u2019assessora alle Culture Paola Romano, dal presidente di Wikimedia Italia Ferdinando Traversa, dal responsabile della comunicazione istituzionale di Pugliapromozione Gino Lorenzelli, dal coordinatore pugliese di Wikimedia Italia Francesco Moro e da Francesco Meledandri, ricercatore del Dipartimento di Ricerca e Innovazione Umanistica dell\u2019Universit\u00e0 degli Studi di Bari Aldo Moro.<\/p>\n<p>Grazie ai partecipanti al concorso e ai volontari dei progetti collaborativi, l&#8217;edizione pugliese ha raccolto, nelle sue passate edizioni, <strong>oltre 13.900 scatti, con la partecipazione di 1.015 fotografi<\/strong>.<\/p>\n<p>Quest\u2019anno, al centro degli scatti ci saranno <strong>ville e palazzi storici<\/strong>, edifici che rappresentano molto pi\u00f9 di un semplice patrimonio architettonico. Dalle dimore nobiliari ai palazzi civili, dalle residenze di rappresentanza agli edifici che hanno ospitato istituzioni, questi luoghi raccontano l&#8217;evoluzione politica, culturale e sociale della Puglia e dell&#8217;Italia. Tra le loro mura si conserva la memoria di epoche diverse, ma anche dei modi di vivere, dei gusti artistici e delle trasformazioni che hanno attraversato il territorio nel corso dei secoli. Documentarli significa contribuire a preservarne la memoria e renderla liberamente accessibile a milioni di persone. In totale sono 4.439 i monumenti fotografabili in totale.<\/p>\n<p>Organizzata in collaborazione con<strong> FIAF<\/strong> (Federazione Italiana Associazioni Fotografiche) e con il patrocinio di <strong>ANCI<\/strong> (Associazione Nazionale Comuni Italiani), l\u2019edizione pugliese si inserisce in un impegno nazionale che nel 2026 vedr\u00e0 attivi ben <strong>11 concorsi locali<\/strong> in tutta Italia. A livello regionale, il concorso \u00e8 co-organizzato con l\u2019associazione cine_fotografica Kaleidos Club e gode del patrocinio della Regione Puglia e dell\u2019ARET PugliaPromozione e si inserisce nell\u2019ambito della collaborazione avviata tra Wikimedia Italia e Universit\u00e0 degli Studi di Bari &#8211; Dipartimento di Ricerca e Innovazione Umanistica.<\/p>\n<p>\u201cWiki Loves Monuments, giunto alla sua ottava edizione, grazie all\u2019impegno di Ferdinando Traversa e della comunit\u00e0 di volontari, \u00e8 diventato negli anni un\u2019importante occasione di promozione e valorizzazione del patrimonio culturale della nostra citt\u00e0 e della nostra regione contribuendo a rendere la fotografia sempre pi\u00f9 conoscibile e democratica \u2013 ha dichiarato l\u2019assessora <strong>Paola Romano<\/strong> \u2013. \u00c8 bello che fotografi appassionati e professionisti possano raccontare liberamente il nostro patrimonio storico-artistico e partecipare a un concorso che coinvolge citt\u00e0 di tutta Europa e del mondo. Una competizione nella quale, in realt\u00e0, vinciamo tutti: vince soprattutto il territorio che attraverso le immagini diventa pi\u00f9 conosciuto e condiviso. Da quando, nove anni fa, abbiamo incontrato Ferdinando in una scuola di San Girolamo insieme all\u2019allora sindaco Antonio Decaro, abbiamo creduto nel valore di questo progetto. Per questo continuiamo a sostenere con convinzione lui e tutti i volontari che ogni anno contribuiscono alla sua crescita.\u201d<\/p>\n<p>\u201cAnche quest&#8217;anno invitiamo tutti i cittadini e gli appassionati di fotografia a riscoprire il patrimonio culturale pugliese e a contribuire alla sua valorizzazione \u2013 ha continuato <strong>Ferdinando Traversa<\/strong> \u2013 Le fotografie caricate, infatti, arricchiscono le voci e l&#8217;archivio fotografico di Wikipedia, consentendoci di far conoscere sempre di pi\u00f9 le bellezze della regione. Nell&#8217;ambito del concorso nazionale Wiki Loves Monuments la Puglia ci regala sempre grandi soddisfazioni, ottenendo risultati molto importanti sia in termini di partecipazione sia per la qualit\u00e0 delle immagini\u201d.<\/p>\n<p>\u201cWiki Loves Puglia \u00e8 un concorso che contribuisce a raccontare e promuovere la Puglia attraverso la forza evocativa della fotografia \u2013 ha continuato <strong>Gino Lorenzelli<\/strong> \u2013 Le immagini diventano ambasciatrici di un territorio ricco di paesaggi, patrimonio, borghi, cultura e identit\u00e0, offrendo nuovi motivi per scoprirlo e viverlo. Il concorso e la mostra valorizzano una Puglia autentica e plurale, capace di sorprendere anche attraverso luoghi e prospettive meno conosciuti. Come Pugliapromozione sosteniamo iniziative che trasformano la bellezza del territorio in racconto e in esperienza, rafforzandone l\u2019attrattivit\u00e0 sui mercati turistici. Wiki Loves Puglia rappresenta cos\u00ec un prezioso strumento di promozione della destinazione e, allo stesso tempo, un invito a scoprire la Puglia attraverso nuovi sguardi.\u201d<\/p>\n<p>\u201cL\u2019Universit\u00e0 di Bari \u00e8 lieta di partecipare all\u2019ottava edizione di \u201cWiki Loves Puglia\u201d, un\u2019iniziativa che valorizza il territorio, i suoi luoghi e le sue comunit\u00e0 \u2013 ha concluso <strong>Francesco Meledandri<\/strong> &#8211; Attraverso il dipartimento di ricerca e nnovazione Umanistica sosteniamo da anni Wikimedia e i principi della conoscenza aperta e condivisa. Crediamo che l\u2019universit\u00e0 abbia un ruolo fondamentale nel promuovere un uso consapevole, critico ed etico della rete e nel rendere la cultura sempre pi\u00f9 accessibile e partecipata. La collaborazione con Wikimedia ci consente di integrare questi principi anche nella didattica e nella ricerca. Con Wiki Loves Puglia rinnoviamo quindi il nostro impegno a favore della cultura libera, della valorizzazione della Puglia e di un rapporto sempre pi\u00f9 stretto tra universit\u00e0 e territorio.\u201d<\/p>\n<p>Il concorso si svolge interamente online, in contemporanea in tutto il mondo, <strong>dal 1\u00b0 al 30 settembre<\/strong>. La partecipazione \u00e8 <strong>gratuita e aperta a tutti<\/strong>: baster\u00e0 caricare le proprie foto tramite la <a href=\"https:\/\/communitygroup.sharepoint.com\/sites\/CloudMilano\/Documenti%20condivisi\/WIKIMEDIA\/01.%20Comunicati%20stampa\/2026\/10.%20Wiki%20Loves%20Monuments%202026%20-%20apertura\/Locali\/web-app\" target=\"_blank\" rel=\"nofollow noopener\"><strong>web-app<\/strong><\/a>. Aprendo il link si acceder\u00e0 a una <strong>mappa immersiva<\/strong> che consente di visualizzare tutti i monumenti protagonisti del concorso sul territorio ligure e nazionale, oltre al numero di foto gi\u00e0 presenti su Wikimedia Commons per ogni monumento. L\u2019app si basa sulle mappe libere di <strong>OpenStreetMap<\/strong> e rielabora dati di <strong>Wikidata<\/strong> e <strong>Wikimedia Commons<\/strong>.<\/p>\n<p>La giuria selezioner\u00e0 10 immagini vincitrici per il concorso regionale. Automaticamente tutte le immagini caricate dagli utenti parteciperanno anche al concorso nazionale e, se premiate, rappresenteranno l&#8217;Italia nella classifica internazionale del concorso. Il montepremi del solo concorso regionale ammonta a 350 euro. Le fotografie vincitrici verranno esposte nella mostra itinerante del concorso, che partir\u00e0 da Bari, dal 14 al 31 dicembre, e girer\u00e0 per tutta la regione. La premiazione si terr\u00e0 il 16 dicembre, alle ore 17, presso l\u2019aula Leogrande, presso il centro polifunzionale degli studenti, nell\u2019ex Palazzo delle Poste.<\/p>\n<p>Nell\u2019ambito del concorso sono previste anche delle passeggiate fotografiche, le wikigite, che porteranno i cittadini alla scoperta dei monumenti regionali in collaborazione con i comuni e le associazioni fotografiche, a partire da Cavallino (LE) il 5 settembre e poi in giro per la Puglia, Taranto, Mottola, Villa Castelli, Parco archeologico di Muro Tenente, Vieste, Manfredonia, Rutigliano, Molfetta e altre localit\u00e0 che verranno divulgate sui canali del concorso.<\/p>\n<p>Anche quest\u2019anno verr\u00e0 incentivata la partecipazione delle scuole, con la collaborazione degli istituti scolastici del territorio, nonch\u00e9 di studenti e docenti dell\u2019Universit\u00e0 degli Studi di Bari.<\/p>\n<p>Per restare aggiornati su tutte le novit\u00e0 e conoscere, \u00e8 possibile seguire le pagine ufficiali <a href=\"https:\/\/www.facebook.com\/share\/1LxKnLCB91\/\" target=\"_blank\" rel=\"nofollow noopener\"><strong>Facebook<\/strong><\/a><strong> e <\/strong><a href=\"https:\/\/www.instagram.com\/wikilovespuglia?igsi=MWRwMTl3anFuem5zOA==\" target=\"_blank\" rel=\"nofollow noopener\"><strong>Instagram<\/strong><\/a><strong> <\/strong>del concorso pugliese. Tutte le informazioni sulla partecipazione al concorso e alle wikigite sono disponibili sulla pagina <a href=\"https:\/\/wikimedia.it\/puglia\" target=\"_blank\" rel=\"nofollow noopener\">wikimedia.it\/puglia<\/a>.<\/p>\n<p>\u00a0<\/p>\n<p><strong>Che cos\u2019\u00e8 Wiki Loves Monuments<\/strong><\/p>\n<p>Promosso dalle comunit\u00e0 di volontari dei progetti Wikimedia, Wiki Loves Monuments rappresenta un\u2019opportunit\u00e0 fondamentale per la diffusione, la promozione e la tutela del patrimonio culturale globale. Dalla sua prima edizione, il concorso ha permesso di documentare milioni di monumenti grazie a oltre 3,6 milioni di immagini caricate da quasi 120.000 partecipanti in tutto il mondo. I numeri pi\u00f9 recenti confermano la straordinaria vitalit\u00e0 dell\u2019iniziativa: nel 2025 sono state inviate oltre 233.500 immagini da circa 4.000 fotografi nell\u2019ambito di 56 concorsi nazionali.<\/p>\n<p>Dal 2012 Wikimedia Italia organizza il capitolo italiano del concorso, consolidandolo come uno dei principali strumenti collaborativi per la documentazione digitale del patrimonio culturale del nostro Paese. In questi anni il progetto ha coinvolto oltre 11.000 partecipanti che hanno arricchito Wikimedia Commons con pi\u00f9 di 300.000 fotografie. Grazie a Wiki Loves Monuments \u00e8 oggi possibile consultare e scaricare le immagini di quasi 47.000 monumenti e beni culturali. Complessivamente, le fotografie italiane del concorso hanno superato un miliardo di visualizzazioni sulle pagine di Wikipedia in 81 lingue, contribuendo ogni giorno alla diffusione della conoscenza libera nel mondo.<\/p>\n<p>\u00a0<\/p>\n<p>      <script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"Parte l&#8217;ottava edizione di Wiki Loves Puglia, edizione locale di Wiki Loves Monuments, il concorso fotografico organizzato ogni&hellip;\n","protected":false},"author":3,"featured_media":659975,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1446],"tags":[1615,1613,1614,1611,1610,364044,364038,1612,203,364041,364043,204,1537,90,89,364040,364046,364042,364045,364039,364037,364036],"class_list":["post-659974","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arte-e-design","tag-arte","tag-arte-e-design","tag-arteedesign","tag-arts","tag-arts-and-design","tag-concorso-fotografia-puglia","tag-concorso-fotografico-puglia","tag-design","tag-entertainment","tag-fotografare-monumenti-puglia","tag-fotografia-puglia","tag-intrattenimento","tag-it","tag-italia","tag-italy","tag-monumenti-puglia","tag-palazzi-s","tag-patrimonio-culturale-puglia","tag-ville-storiche-puglia","tag-wiki-loves-monuments-2026","tag-wiki-loves-puglia","tag-wiki-loves-puglia-2026"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/117196692050303438","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/659974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=659974"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/659974\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/659975"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=659974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=659974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=659974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}