{"id":660158,"date":"2026-09-01T18:44:17","date_gmt":"2026-09-01T18:44:17","guid":{"rendered":"https:\/\/www.europesays.com\/it\/660158\/"},"modified":"2026-09-01T18:44:17","modified_gmt":"2026-09-01T18:44:17","slug":"rapina-choc-a-roma-entra-nel-supermercato-armato-di-pistola-lega-il-dipendente-e-scappa-con-9mila-euro","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/660158\/","title":{"rendered":"Rapina choc a Roma: entra nel supermercato armato di pistola, lega il dipendente e scappa con 9mila euro"},"content":{"rendered":"<p>Rapina choc a Roma dove un bandito armato di pistola ha fatto irruzione nel supermercato Tigre di viale XXI Aprile. Sono stati momenti di paura con un dipendente che \u00e8 stato legato mani e piedi dentro il magazzino. I fatti sono accaduti il 29 agosto intorno alle 21:30.<\/p>\n<p>Ad entrare in azione un malvivente con il volto coperto e con in pugno il &#8220;ferro&#8221;. Un colpo, il suo, che ha fruttato circa 9mila euro, con il contante che \u00e8 stato prelevato dalle casse e dalla cassaforte. Dopodich\u00e9 si \u00e8 dileguato. L&#8217;impiegato, secondo quanto appreso, ha rifiutato il trasporto in ospedale. Sulla vicenda indaga il commissariato Porta Pia e la squadra mobile.<\/p>\n<p>Una vicenda, questa, sulla quale \u00e8 giunto il commento del team &#8220;Tigre&#8221; di viale XXI Aprile: &#8220;Quando abbiamo deciso di aprire il supermercato ci aspettavamo una clientela variegata e affezionata: uno studente fuorisede che compra una scatoletta di tonno a mezzanotte per una spaghettata, una nonna che sceglie ovetti di cioccolato per il nipote o una famiglia che fa la spesa settimanale. Non ci aspettavamo una rapina a mano armata in piena Piazza Bologna, non ci aspettavamo il furto di un incasso di giorni che forse non rivedremo pi\u00f9. Non ci aspettavamo di trovare un nostro dipendente legato, mani e piedi, terrorizzato dentro il magazzino. Non eravamo e non siamo pronti a tutto questo&#8221;.<\/p>\n<p>Inoltre hanno aggiunto: &#8220;Noi non siamo un &#8220;colosso&#8221; della grande distribuzione. Dietro questo supermercato ci sono storie semplici, merci selezionate con criterio, dipendenti con figli da mantenere e clienti affezionati a cui ci dedichiamo con il nostro massimo impegno. Questa rapina \u00e8 una ferita violentissima per tutte le persone che lavorano con noi ma possiamo dire che lo \u00e8 anche per il quartiere e per il benessere che Piazza Bologna merita&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"Rapina choc a Roma dove un bandito armato di pistola ha fatto irruzione nel supermercato Tigre di viale&hellip;\n","protected":false},"author":3,"featured_media":660159,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[79],"tags":[14,93,94,1537,90,89,7,15,26283,11,84,91,12,85,92],"class_list":["post-660158","post","type-post","status-publish","format-standard","has-post-thumbnail","category-italia","tag-cronaca","tag-cronaca-italiana","tag-cronacaitaliana","tag-it","tag-italia","tag-italy","tag-news","tag-notizie","tag-rapine","tag-ultime-notizie","tag-ultime-notizie-e-news-di-oggi","tag-ultime-notizie-italia","tag-ultimenotizie","tag-ultimenotizieenewsdioggi","tag-ultimenotizieitalia"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@it\/117197266222420001","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/660158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=660158"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/660158\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/660159"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=660158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=660158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=660158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}