{"id":8113,"date":"2025-07-25T17:19:19","date_gmt":"2025-07-25T17:19:19","guid":{"rendered":"https:\/\/www.europesays.com\/it\/8113\/"},"modified":"2025-07-25T17:19:19","modified_gmt":"2025-07-25T17:19:19","slug":"restauro-per-tre-busti-illustri","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/8113\/","title":{"rendered":"Restauro per tre busti illustri"},"content":{"rendered":"<p><strong>Via libera al restauro di tre ritratti scultorei del museo dei Grandi fiumi<\/strong>.\u00a0La Regione Veneto ha infatti approvato il progetto presentato dal museo per il restauro di tre importanti ritratti scultorei.<\/p>\n<p>L\u2019intervento, finalizzato alla conservazione e valorizzazione del patrimonio artistico del museo, ricever\u00e0 un contributo di 5.131 euro.<\/p>\n<p>Il progetto denominato \u201cBusti illustri\u201d,<strong> riguarda due gessi e una terracotta<\/strong> che sono stati acquisiti negli anni \u201990 dall\u2019allora museo civico delle civilt\u00e0 in Polesine, oggi museo dei Grandi fiumi, provenienti dalla sede municipale.<\/p>\n<p><strong>Fanno parte di un nucleo legato al Risorgimento c<\/strong>ui appartiene anche un medaglione in bronzo che non necessita di interventi. Ciascuno ha una storia e un autore significativi.<\/p>\n<p>Nel dettaglio si tratta dei<strong> ritratti scultorei di Amos Bernini<\/strong> opera di Policronio Carletti, <strong>di re Vittorio Emanuele II<\/strong>, opera di Ambrogio Zuffi<strong> e di Giuseppe Garibaldi<\/strong> opera di Ettore Ximenes.<\/p>\n<p>Terminato il restauro le opere saranno esposte al pubblico.<\/p>\n","protected":false},"excerpt":{"rendered":"Via libera al restauro di tre ritratti scultorei del museo dei Grandi fiumi.\u00a0La Regione Veneto ha infatti approvato&hellip;\n","protected":false},"author":3,"featured_media":8114,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1446],"tags":[1615,1613,1614,1611,1610,1612,203,204,1537,90,89,8516],"class_list":{"0":"post-8113","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-arte-e-design","8":"tag-arte","9":"tag-arte-e-design","10":"tag-arteedesign","11":"tag-arts","12":"tag-arts-and-design","13":"tag-design","14":"tag-entertainment","15":"tag-intrattenimento","16":"tag-it","17":"tag-italia","18":"tag-italy","19":"tag-rovigo"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/8113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=8113"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/8113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/8114"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=8113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=8113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=8113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}