{"id":83636,"date":"2025-09-02T16:51:10","date_gmt":"2025-09-02T16:51:10","guid":{"rendered":"https:\/\/www.europesays.com\/it\/83636\/"},"modified":"2025-09-02T16:51:10","modified_gmt":"2025-09-02T16:51:10","slug":"francesco-gabbani-il-video-di-dalla-mia-parte-girato-a-bologna","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/83636\/","title":{"rendered":"Francesco Gabbani, il video di \u2018Dalla mia parte\u2019 girato a Bologna"},"content":{"rendered":"<p>Bologna, 2 settembre 2025 \u2013\u00a0E\u2019 online da oggi il nuovo video di <a rel=\"follow nofollow noopener\" href=\"https:\/\/www.ilrestodelcarlino.it\/rimini\/cronaca\/il-maltempo-ferma-gabbani-show-e6232c1d\" target=\"_blank\"><strong>Francesco Gabbani<\/strong><\/a> per l\u2019ultimo successo\u00a0inedito<strong> \u2018Dalla mia parte\u2019<\/strong>, girato interamente a <strong>Bologna<\/strong>. Il brano \u00e8 uscito\u00a0oggi sulle piattaforme digitali per BMG.<\/p>\n<p>Il videoclip si apre con un\u2019ampia veduta dei <strong>Giardini Margherita<\/strong>, protagonisti dell\u2019incipit della canzone. Panchine, bolognesi che corrono, bambini, qualche \u2018<strong>umarell\u2019<\/strong> qua e l\u00e0: il video di Gabbani sembra una radiografia completa del centro. Dai \u2018Gardenz\u2019 ci si sposta verso le Due Torri come in una passeggiata tipica al tramonto. Sullo sfondo di vedono i <strong>tanti cantieri<\/strong> e i lavori in strada, la recinzione attorno alla <strong>Garisenda<\/strong> e alla Torre degli Asinelli, i portici ovviamente. E ancora piazza Maggiore, piazzetta de\u2019 Celestini, via d\u2019Azeglio, il Crescentone, Palazzo Re Enzo. E un Gabbani in \u2018versione goliardo\u2019 che si attacca a <strong>un campanello per uno scherzo<\/strong> prima di scappare. Il brano continua e il video finisce cos\u00ec come era iniziato: nel cuore del verde dei Giardini Margherita.<\/p>\n<p>Approfondisci:<\/p>\n<p><a href=\"https:\/\/www.ilrestodelcarlino.it\/ravenna\/cultura\/conto-alla-rovescia-per-linaugurazione-del-museo-di-laura-pausini-a-solarolo-xquswmfj\" class=\"ArticleEmbed_article__embed__content__Jzqnz\" rel=\"nofollow noopener\" target=\"_blank\">L\u2019anteprima del museo di Laura Pausini a Solarolo tra abiti iconici, premi e cimeli: cosa ci sar\u00e0<img alt=\"L\u2019anteprima del museo di Laura Pausini a Solarolo tra abiti iconici, premi e cimeli: cosa ci sar\u00e0\" loading=\"lazy\" width=\"140\" height=\"78\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent\"  src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/09\/a-sinistra-laura-pausini-di-fronte-alla-casa-museo-a-solarolo-e-la-sua-casa-d-infanzia-che-e-anche-s.webp\"\/><\/a> <\/p>\n<p>Il videoclip di \u2018Dalla mia parte\u2019 \u00e8\u00a0diretto da <strong>Filiberto Signorello<\/strong> e racconta la vita attraverso immagini vere e quotidiane, tipiche di Bologna. Tra piccoli gesti che diventano poesia e momenti di apparente leggerezza, emergono anche sguardi che lasciano intravedere <strong>storie pi\u00f9 profonde<\/strong>. Cos\u00ec, la normalit\u00e0 si trasforma in un mosaico di emozioni, in cui bellezza fragilit\u00e0 e contrasti convivono.<\/p>\n<p>&#8220;Dalla mia parte\u00a0\u00e8 <strong>una dichiarazione d\u2019amore universale<\/strong> \u2013\u00a0si legge nella presentazione della clip appena uscita \u2013. In un rapporto di coppia, di amicizia, di condivisione, un amore vero, maturo, consapevole. Non perfetto, non idealizzato. Un amore che sa cosa significhi attraversare insieme le difficolt\u00e0, restare anche quando \u00e8 tutto in salita. \u00c8 la storia di un amore che salva, che d\u00e0 senso anche ai momenti pi\u00f9 bui. Di quella <strong>presenza silenziosa ma costante<\/strong> che diventa rifugio, forza, casa. \u2018Stare dalla mia parte\u2019\u00a0non significa solo condividere i sorrisi, ma esserci davvero, anche quando fa male. E questo, per Francesco, \u00e8 la forma pi\u00f9 profonda di ci\u00f2 che \u00e8 definibile come amore\u201d.<\/p>\n<p>Approfondisci:<\/p>\n<p><a href=\"https:\/\/www.ilrestodelcarlino.it\/ravenna\/cronaca\/cesare-cremonini-valentino-rossi-marina-romea-h3b52d5i\" class=\"ArticleEmbed_article__embed__content__Jzqnz\" rel=\"nofollow noopener\" target=\"_blank\">Cesare Cremonini e Valentino Rossi a Marina Romea: incursione alla festa e pioggia di selfie<img alt=\"Cesare Cremonini e Valentino Rossi a Marina Romea: incursione alla festa e pioggia di selfie\" loading=\"lazy\" width=\"140\" height=\"78\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent\"  src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/09\/valentino-rossi-e-cesare-cremonini-a-pranzo-a-marina-romea-ravenna-pioggia-di-selfie.webp\"\/><\/a> <\/p>\n<p>Il primo\u00a0ottobre, poi, Francesco Gabbani terr\u00e0 un concerto speciale all&#8217;<strong>Arena di Verona<\/strong> con cui celebrer\u00e0\u00a0i dieci anni dall\u2019uscita di <strong>\u2018Amen\u2019<\/strong>, il brano con cui vinse Sanremo nella categoria Nuove Proposte, che ha rappresentato il primo passo di un percorso artistico ricco di musica, parole e riconoscimenti.\u00a0\u00a0In attesa del concerto a Verona, inoltre, Gabbani si prepara a una nuova avventura televisiva: dall\u201911 settembre sar\u00e0 infatti uno dei quattro giudici della <strong>nuova stagione di X Factor<\/strong>, su Sky e in streaming su NOW.<\/p>\n<p>Poi, nel 2026, con il suo \u2018Dalla tua parte tour\u2019 toccher\u00e0 \u2013\u00a0ovviamente, a questo punto \u2013\u00a0anche Bologna: sar\u00e0 <strong>il 7 aprile\u00a02026 all\u2019Unipol Arena<\/strong> di Casalecchio di Reno.\u00a0Il tour \u00e8 prodotto da A1 Concerti, e i biglietti sono disponibili in prevendita su Ticketone.<\/p>\n","protected":false},"excerpt":{"rendered":"Bologna, 2 settembre 2025 \u2013\u00a0E\u2019 online da oggi il nuovo video di Francesco Gabbani per l\u2019ultimo successo\u00a0inedito \u2018Dalla&hellip;\n","protected":false},"author":3,"featured_media":83637,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1443],"tags":[586,58739,203,1250,13556,5379,204,1537,90,89,1538,1539,2392],"class_list":["post-83636","post","type-post","status-publish","format-standard","has-post-thumbnail","category-musica","tag-bologna","tag-dalla","tag-entertainment","tag-francesco","tag-gabbani","tag-girato","tag-intrattenimento","tag-it","tag-italia","tag-italy","tag-music","tag-musica","tag-video"],"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/83636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=83636"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/83636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/83637"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=83636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=83636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=83636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}