{"id":85754,"date":"2025-09-03T16:48:08","date_gmt":"2025-09-03T16:48:08","guid":{"rendered":"https:\/\/www.europesays.com\/it\/85754\/"},"modified":"2025-09-03T16:48:08","modified_gmt":"2025-09-03T16:48:08","slug":"sanita-regione-lombardia-perde-14-punti-in-livelli-assistenziali-rispetto-al-2023","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/85754\/","title":{"rendered":"Sanit\u00e0, Regione Lombardia perde 14 punti in livelli assistenziali rispetto al 2023"},"content":{"rendered":"<p>    di<br \/>\n    Thomas Bendinelli<\/p>\n<p class=\"summary-art is-line-h-12\">L&#8217;analisi della fondazione Gimbe. Botta e risposta fra PD e Lega: \u00abLa Regione mostra un profilo di adempienza superiore alla soglia in tutte le aree\u00bb<\/p>\n<p class=\"chapter-paragraph\"><b>Nel 2023 la Lombardia perde 14 punti rispetto all\u2019anno precedente nell\u2019adempimento dei livelli essenziali di assistenza (LEA)<\/b>, ovvero le prestazioni sanitarie che tutte le Regioni e Province Autonome devono garantire gratuitamente o previo il pagamento del ticket.<br \/>Lo osserva la Fondazione Gimbe rielaborando i dati diffusi dal Ministero della Salute.\u00a0<\/p>\n<p class=\"chapter-paragraph\">Per quanto riguarda i Lea, \u00e8 bene ricordare (come riportato anche nello studio Gimbe) che <b>la Lombardia \u00e8 \u00abadempiente\u00bb in tutte le tre macro aree di analisi: nella prevenzione<\/b>, dove ottiene 95 punti ed \u00e8 quarta a livello nazionale; <b>nell\u2019area dell\u2019assistenza distrettuale<\/b>, dove ottiene 76 punti ed \u00e8 solo undicesima; <b>nell\u2019area ospedaliera<\/b>, dove i punti sono 86 e mettono la regione in settima posizione. Nel 2022 i punti ottenuti dalla Lombardia nelle tre aree erano stati 90 nell\u2019area prevenzione (nel 2023, con 95 punti, c\u2019\u00e8 stato quindi un miglioramento), 95 in quella distrettuale (contro i 76 del 2023) e 86 in quella ospedaliera (uguale al 2023). In un\u2019ipotetica classifica che somma i valori delle tre macro aree la Lombardia perde appunto 14 punti rispetto al 2022 ed <b>\u00e8 sesta dietro Veneto, Toscana, Emilia Romagna, provincia autonoma di Trento e Piemonte.<\/b>\u00a0    &#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;\n<\/p>\n<p class=\"chapter-paragraph\">La sottolineatura sul calo complessivo di 14 punti \u00e8 stata oggetto ieri di diverse prese di posizione da parte dell\u2019opposizione in Regione, dal capogruppo Pd Majorino a Miriam Cominelli, consigliera regionale Pd e componente della commissione sanit\u00e0: <b>\u00abI dati elaborati da Gimbe sono terribili e certificano una realt\u00e0 che noi da tempo denunciamo &#8211; ha affermato Cominelli -. <\/b>Perdere 14 punti rispetto all\u2019anno precedente \u00e8 un dato che dovrebbe far dire a Fontana, a Bertolaso e a tutta la destra lombarda che bisogna cambiare profondamente, che bisogna ricostruire la sanit\u00e0 territoriale e bisogna reinvestire sulla sanit\u00e0 pubblica, riducendo i tempi di attesa che sono un insostenibile ricatto per i cittadini, costretti a farsi visitare e curare a pagamento. Tra poche settimane in consiglio regionale ci sar\u00e0 la proposta di legge di iniziativa popolare che ha raccolto oltre 100mila firme per riformare il servizio sanitario regionale: \u00e8 un\u2019occasione che la destra lombarda non pu\u00f2 permettersi di sprecare\u00bb.\u00a0<\/p>\n<p class=\"chapter-paragraph\">Secca la replica a Majorino, Gimbe e Cominelli del sottosegretario alla presidenza del consiglio regionale Mauro Piazza (Lega): \u00abLa Regione Lombardia mostra un profilo di adempienza ai Lea superiore alla soglia (60) in tutte e tre le aree di assistenza: altro che perdita di 14 punti. <b>Gimbe e Majorino farebbero bene a non distorcere o strumentalizzare i dati ufficiali del Ministero della Salute\u00bb.<\/b><\/p>\n<p class=\"is-mr-t-20 is-mr-b-20\"><b><br \/>\n                    <a href=\"https:\/\/brescia.corriere.it\/?intcmp=Notizielocali_nd_010623_corriere_ss_brescia\" target=\"_blank\" rel=\"nofollow noopener\">Vai a tutte le notizie di Brescia<\/a><br \/>\n            <\/b><\/p>\n<p class=\"chapter-paragraph\"><b><a href=\"https:\/\/www.corriere.it\/newsletter\/?theme=62&amp;intcmp=NL-artic_nd_050624_corriere_ss_brescia\" target=\"_blank\" rel=\"nofollow noopener\">Iscriviti alla newsletter di Corriere Brescia<\/a><\/b><\/p>\n<p class=\"is-last-update\" datetime=\"2025-09-03T18:25:48+02:00\">3 settembre 2025<\/p>\n<p class=\"is-copyright\">\n            \u00a9 RIPRODUZIONE RISERVATA\n        <\/p>\n","protected":false},"excerpt":{"rendered":"di Thomas Bendinelli L&#8217;analisi della fondazione Gimbe. Botta e risposta fra PD e Lega: \u00abLa Regione mostra un&hellip;\n","protected":false},"author":3,"featured_media":85755,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[62910,5143,841,1018,62911,62912,8152,3439,62907,728,3177,62913,40957,14920,62389,18901,239,1537,90,89,30569,109,62914,5762,62908,62909,490,22468,1292,13124,8150,111,1270,240,301],"class_list":{"0":"post-85754","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-salute","8":"tag-adempienza","9":"tag-analisi","10":"tag-area","11":"tag-aree","12":"tag-aree-lombardia","13":"tag-aree-lombardia-perde","14":"tag-assistenza","15":"tag-bisogna","16":"tag-cominelli","17":"tag-dati","18":"tag-destra","19":"tag-destra-lombarda","20":"tag-distrettuale","21":"tag-fondazione","22":"tag-fondazione-gimbe","23":"tag-gimbe","24":"tag-health","25":"tag-it","26":"tag-italia","27":"tag-italy","28":"tag-lea","29":"tag-lega","30":"tag-lega-regione","31":"tag-lombardia","32":"tag-lombardia-perde","33":"tag-majorino","34":"tag-pd","35":"tag-perde","36":"tag-punti","37":"tag-punti-rispetto","38":"tag-regionale","39":"tag-regione","40":"tag-rispetto","41":"tag-salute","42":"tag-sanita"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/85754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=85754"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/85754\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/85755"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=85754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=85754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=85754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}