{"id":86916,"date":"2025-09-04T06:30:09","date_gmt":"2025-09-04T06:30:09","guid":{"rendered":"https:\/\/www.europesays.com\/it\/86916\/"},"modified":"2025-09-04T06:30:09","modified_gmt":"2025-09-04T06:30:09","slug":"la-yuasa-battery-si-e-messa-di-nuovo-in-moto","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/86916\/","title":{"rendered":"La Yuasa Battery si \u00e8 messa di nuovo in moto"},"content":{"rendered":"<p><strong>GROTTAZZOLINA<\/strong>Settembre \u00e8 tempo di volley anche in casa <strong>Yuasa Battery Grottazzolina<\/strong>. In palestra per la squadra di coach Massimiliano Ortenzi che si allena duramente e sta gradualmente aumentando i carichi per andare a puntare sulla forza in questa prima fase di preparazione. Ma come settembre \u00e8 anche il mese del ritorno in palestra delle altre formazioni del panorama Yuasa. Lo hanno gi\u00e0 fatto molte squadre del mondo Yuasa come la Serie B guidata da Michele Delvecchio insieme ad Andrea Nicolini che ha rinnovato il proprio organico per essere pronta alla nuova stagione. Ma lo hanno anche fatto le formazioni giovanili maschili e femminili, un autentico esercito che sta tornando gradualmente ad allenarsi. Tutto questo non ferma ovviamente l\u2019attivit\u00e0 di promozione che il mondo <strong>M&amp;G Scuola Pallavolo<\/strong> sta portando avanti da tempo. Marted\u00ec il primo <strong>open day<\/strong> andato in scena a <strong>Porto San Giorgio<\/strong>, inizialmente programmato presso la Bambinopoli ma poi svoltosi al coperto. Oggi il secondo appuntamento e sempre a Porto San Giorgio presso la Pinetina Salvatori. In programma anche un terzo appuntamento quello del 7 settembre sul Lungomare Gramsci in occasione della Festa dello Sport organizzata dal Comune di Porto San Giorgio. L\u2019opportunit\u00e0 di giocare, divertirsi, provare la pallavolo e iniziare magari un percorso di sport ma anche di amicizia e sani valori che potrebbe accompagnare i ragazzi nel corso degli anni. Ma il mondo degli Open Day organizzati dalla Yuasa Battery Grottazzolina non si limiter\u00e0 e non si fermer\u00e0 solo a Porto San Giorgio perch\u00e9 questo \u00e8 un movimento di ampio respiro, capace di abbracciare e coinvolgere un intero territorio e moltissimi dei suoi comuni.<\/p>\n<p>Oltre al trittico di appuntamenti sangiorgese ecco che ci saranno altri quattro appuntamenti per andare a provare l\u2019emozione del volley. Il primo, sempre il 7 settembre e alle 15,30, a Piane di Falerone, il secondo invece il 10 di settembre a Servigliano dove gi\u00e0 si svolgere attivit\u00e0 di Mini Volley nel corso dell\u2019anno fin dalla scorsa stagione. Si torner\u00e0 poi sulla costa fermana e precisamente a Pedaso venerd\u00ec 12 agosto alle 21,15 mentre questa serie lunga di appuntamenti si chiuder\u00e0 &#8220;a casa&#8221; ovvero a Grottazzolina, il 14 settembre alle ore 6,30. Tante opportunit\u00e0 e tante occasioni epr conoscere il mondo del volley e soprattutto quello della M&amp;G Scuola Pallavolo che offre anche ai pi\u00f9 piccoli infinite possibilit\u00e0 di divertimento.<\/p>\n","protected":false},"excerpt":{"rendered":"GROTTAZZOLINASettembre \u00e8 tempo di volley anche in casa Yuasa Battery Grottazzolina. In palestra per la squadra di coach&hellip;\n","protected":false},"author":3,"featured_media":86917,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1474],"tags":[11936,1537,90,89,13181,1783,245,244,1869,11935],"class_list":{"0":"post-86916","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-volley","8":"tag-battery","9":"tag-it","10":"tag-italia","11":"tag-italy","12":"tag-messa","13":"tag-moto","14":"tag-sport","15":"tag-sports","16":"tag-volley","17":"tag-yuasa"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/86916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=86916"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/86916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/86917"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=86916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=86916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=86916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}