{"id":96791,"date":"2025-09-09T02:23:11","date_gmt":"2025-09-09T02:23:11","guid":{"rendered":"https:\/\/www.europesays.com\/it\/96791\/"},"modified":"2025-09-09T02:23:11","modified_gmt":"2025-09-09T02:23:11","slug":"vingegaard-contro-almeida-sfida-finale","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/it\/96791\/","title":{"rendered":"Vingegaard contro Almeida, sfida finale"},"content":{"rendered":"<p>La Vuelta entra nella sua terza e decisiva settimana. Senza certezze matematiche, ma con qualche indicazione pi\u00f9 netta. Salvo sorprese, la corsa per la vittoria riguarder\u00e0 solo <strong>Jonas Vingegaard<\/strong> e<strong> Joao Almeida<\/strong>. Quella per il terzo gradino del podio dovrebbe interessare Pidcock e Hindley, con pi\u00f9 in sottofondo Gall.<\/p>\n<p>Anche nell\u2019ultimo terzo della corsa spagnola non mancheranno salite, tappe con dislivello e insidie. Oltre alla crono, tutta piatta, di Valladolid (26km), che per\u00f2 non dovrebbe spostare troppi equilibri fra i primi due della classifica generale.<\/p>\n<p><strong>Il quadro tattico, finora, \u00e8 stato abbastanza chiaro<\/strong>. La Uae gioca d\u2019attacco sempre. La Visma difende e attende, senza soffrire troppo. I numeri degli emiratini sono strabilianti. 81 vittorie in stagione (il record di 85 dell\u2019HTC \u00e8 ormai dietro l\u2019angolo), di cui 7 in questa Vuelta, ottenute con 4 corridori diversi (Almeida, Ayuso, Vine e Soler). <strong>Ci fosse Poga\u010dar sarebbe un\u2019altra storia<\/strong>. Ma questa squadra \u00e8 camaleontica. In assenza del numero uno, si attenta al bersaglio grosso (la vittoria finale) cercando nel frattempo di vincere il pi\u00f9 possibile. Con buona pace del resto della truppa, che dubito sprizzi di gioia.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"1600\" src=\"https:\/\/www.europesays.com\/it\/wp-content\/uploads\/2025\/09\/Vuelta-2025-classifica-dopo-15-tappe.webp.webp\" alt=\"Vuelta 2025 classifica dopo 15 tappe: Vingegaard in testa segue a 48&quot; Almeida\" class=\"wp-image-240737\"  \/><\/p>\n<p>Fortuna che in questa Vuelta c\u2019\u00e8 Mads Pedersen, corridore buono per tutte le stagioni e garanzia di spettacolo. Il danese, dopo svariati tentativi andati a vuoto e diversi piazzamenti, \u00e8 riuscito a vincere una tappa, dimostrando una voglia e un\u2019abnegazione che lo rendono un corridore totale.<\/p>\n<p><strong>Capitolo italiani<\/strong>. Con Tiberi e Ciccone sottotono, la nostra perla \u00e8 <strong>Giulio Pellizzari<\/strong>. Il marchigiano, dopo il sesto posto al Giro d\u2019Italia, sta flirtando con la stessa posizione anche alla Vuelta, pur dimostrando alta fedelt\u00e0 al suo capitano e amico <strong>Jay Hindley<\/strong>. Il ragazzo ha stoffa, gamba, serenit\u00e0 e personalit\u00e0. Se guardiamo ai prossimi 3-4 anni possiamo essere ottimisti.<\/p>\n<p>In ottica <a href=\"https:\/\/www.bikeitalia.it\/2025\/09\/05\/mondiali-di-ciclismo-in-ruanda-tutto-quello-che-devi-sapere-e-dove-vederli-in-tv\/\" rel=\"nofollow noopener\" target=\"_blank\">Mondiale<\/a> stanno pedalando molto bene Frigo e Bagioli, mentre il nostro ct<strong> Marco Villa<\/strong> dovr\u00e0 rinunciare a <strong>Damiano Caruso<\/strong>, che sarebbe stato un prezioso regista in corsa.<\/p>\n<p>Domenica \u00e8 stato anche l\u2019ultimo giorno di corsa in carriera per <strong>Geraint Thomas<\/strong>, vincitore del Tour de France nel 2018. Il gallese voleva terminare al Tour of Britain e cos\u00ec ha fatto, fra il calore della sua gente e il sommo rispetto del resto del gruppo. Per la cronaca la corsa \u00e8 stata vinta dal talentino francese <strong>Romain Gregoire<\/strong>, al termine di un\u2019edizione in cui hanno ritrovato il gusto del successo sia <strong>Remco Evenepoel<\/strong> che <strong>Olav Kooj <\/strong>(3 tappe).<\/p>\n<p>Ultimo aggiornamento sulle <a href=\"https:\/\/www.bikeitalia.it\/2025\/09\/03\/la-israel-dovrebbe-lasciare-la-vuelta\/\" rel=\"nofollow noopener\" target=\"_blank\">manifestazioni pro-Pal alla Vuelta<\/a>. Negli ultimi giorni le proteste sono state pacifiche. Tante bandiere, tanti cartelli e striscioni contro Israele, ma nessuna forzatura e nessun fattaccio contro la Israel-Premier Tech, nonostante politici e autorit\u00e0 spagnole stiano caldeggiando l\u2019uscita di scena del team. Che, perlomeno, ha avuto il buon cuore di togliere il nome Israel dalle maglie, come segno di minimo rispetto verso quello che \u00e8 il sentimento di un intero paese. <strong>La strada fino a Madrid \u00e8 ancora lunga, ma per il momento la questione sembra sotto controllo<\/strong>.<\/p>\n<p>Le pagelle del Greg<\/p>\n<p><strong>VINGEGAARD 9<\/strong>: va al secondo giorno di riposo in testa alla classifica, con 48 secondi su Almeida e 2 tappe vinte. Praticamente il massimo col minimo sforzo. Gestisce e tampona, difende e scruta. In attesa, forse, di piazzare il colpo del ko. <strong>LEADER<\/strong><\/p>\n<p><strong>UAE 10<\/strong>: 7 vittorie di tappa su 15. Hanno gestito al meglio il caso interno del ribelle Ayuso (voto 8 grazie alle due tappe vinte), con Vine lanciato verso la conquista della classifica degli scalatori e Almeida che sta facendo una Vuelta pazzesca. Ah, ovviamente sono al comando della classifica a squadre. <strong>CANNIBALI<\/strong><\/p>\n<p><strong>PELLIZZARI 8,5<\/strong>: in salita \u00e8 senza discussioni il migliore degli italiani. Pedala con convinzione e leggerezza, mischiate a coraggio e maturit\u00e0. Vuole portare Hindley (voto 7,5) sul podio e nel contempo godersi una classifica di prestigio. <strong>LEGGIADRO<\/strong><\/p>\n<p><strong>PEDERSEN 9,5<\/strong>: per favore clonatelo! Sempre all\u2019attacco, sempre sul pezzo. Cuore e gambe, testa e potenza. Maglia verde quasi blindata. Siamo a 14 vittorie stagionali e 60 in carriera. Fa tutto e tutti esalta. <strong>UNIVERSALE<\/strong><\/p>\n<p><strong>CICCONE 5<\/strong>: ha la scusa di svariati problemi fisici e di salute, ma l\u2019ennesimo tentativo di fare classifica in un grande giro \u00e8 svanito per la 15esima volta in carriera. Non \u00e8 destino, evidentemente. Speriamo non continui a incaponirsi su un obiettivo che, probabilmente, non \u00e8 nelle sue corde. <strong>TESTONE<\/strong><\/p>\n<p><strong>BERNAL 4<\/strong>: dispiace essere cos\u00ec severi, ma sono mesi che ci dice che \u00e8 pronto per tornare al livello dei migliori. La bocca va pi\u00f9 veloce delle gambe e allora in questi casi non c\u2019\u00e8 perdono e piet\u00e0. <strong>EVANESCENTE<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"La Vuelta entra nella sua terza e decisiva settimana. Senza certezze matematiche, ma con qualche indicazione pi\u00f9 netta.&hellip;\n","protected":false},"author":3,"featured_media":96792,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1456],"tags":[1824,55309,1825,1537,90,89,245,244],"class_list":{"0":"post-96791","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ciclismo","8":"tag-ciclismo","9":"tag-ciclismo-sportivo","10":"tag-cycling","11":"tag-it","12":"tag-italia","13":"tag-italy","14":"tag-sport","15":"tag-sports"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/96791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/comments?post=96791"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/posts\/96791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media\/96792"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/media?parent=96791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/categories?post=96791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/it\/wp-json\/wp\/v2\/tags?post=96791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}