{"id":14763,"count":1,"description":"","link":"https:\/\/www.europesays.com\/nl\/tag\/genderneutraal\/","name":"Genderneutraal","slug":"genderneutraal","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/nl\/wp-json\/wp\/v2\/tags\/14763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/nl\/wp-json\/wp\/v2\/posts?tags=14763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}