{"id":5430,"count":21,"description":"","link":"https:\/\/www.europesays.com\/nl\/tag\/europees-parlement\/","name":"Europees Parlement","slug":"europees-parlement","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/nl\/wp-json\/wp\/v2\/tags\/5430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/nl\/wp-json\/wp\/v2\/posts?tags=5430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}