{"id":17068,"count":1,"description":"","link":"https:\/\/www.europesays.com\/no\/tag\/dee-snyder\/","name":"dee snyder","slug":"dee-snyder","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.europesays.com\/no\/wp-json\/wp\/v2\/tags\/17068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/no\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.europesays.com\/no\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.europesays.com\/no\/wp-json\/wp\/v2\/posts?tags=17068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}